{"id":894,"date":"2021-07-29T09:59:59","date_gmt":"2021-07-29T07:59:59","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=894"},"modified":"2021-07-29T09:59:59","modified_gmt":"2021-07-29T07:59:59","slug":"donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/","title":{"rendered":"Donne protagoniste del loro tempo &#8211; Siore Rine una imprenditrice all&#8217;avanguardia"},"content":{"rendered":"<p>Nella Fagagna di fine anni \u201940, basata sull\u2019agricoltura e caratterizzata da una grande semplicit\u00e0 di vita, Anna Erinna Piccoli (moglie del sior Aldo Cecconi e chiamata affettuosamente siore Rine) d\u00e0 il via a un\u2019 attivit\u00e0 imprenditoriale pioneristica che dura un ventennio dal 1949 al 1969.<br \/>\nSiore Rine \u00e8 senza dubbio una figura all\u2019avanguardia, una donna \u201cprotagonista del suo tempo\u201d, imprenditrice e datrice di lavoro ma allo stesso tempo trascinante, rassicurante e capace di trasmettere importanti valori umani e professionali. Non ha semplicemente fondato un piccolo laboratorio di paese bens\u00ec un\u2019attivit\u00e0 di grande modernit\u00e0 per l\u2019epoca in cui si sviluppa e per il significato che riveste.<\/p>\n<p>Da qui la volont\u00e0 dell\u2019Ecomuseo della gente di collina \u201cIl Caval\u00eer\u201d e del Museo \u201cCjase Cocel\u201d di intraprendere una ricerca a riguardo. Dalla ricerca sono scaturiti un volume e una mostra, strumenti utili per riportare alla luce e far conoscere questa esperienza imprenditoriale di cos\u00ec grande valore per la gente di Fagagna. Entrambi non solo raccontano l\u2019attivit\u00e0 di questa donna imprenditrice, ma offrono anche un interessante approfondimento sugli anni \u201950 \u2013 \u201970, contesto in cui l\u2019attivit\u00e0 di Siore Rine si \u00e8 sviluppata e momento storico di grandi cambiamenti economici e sociali non solo a livello locale ma anche nazionale.<\/p>\n<p>Sabato 31 luglio alle ore 18 sar\u00e0 inaugurata la mostra a lei dedicata c\/o la sala espositiva del Palazzo Municipale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella Fagagna di fine anni \u201940, basata sull\u2019agricoltura e caratterizzata da una grande semplicit\u00e0 di vita, Anna Erinna Piccoli (moglie del sior Aldo Cecconi e chiamata affettuosamente siore Rine) d\u00e0 [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donne protagoniste del loro tempo - Siore Rine una imprenditrice all&#039;avanguardia - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donne protagoniste del loro tempo - Siore Rine una imprenditrice all&#039;avanguardia - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Nella Fagagna di fine anni \u201940, basata sull\u2019agricoltura e caratterizzata da una grande semplicit\u00e0 di vita, Anna Erinna Piccoli (moglie del sior Aldo Cecconi e chiamata affettuosamente siore Rine) d\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-29T07:59:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/218665611_802473313770797_817870094143793234_n-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Donne protagoniste del loro tempo &#8211; Siore Rine una imprenditrice all&#8217;avanguardia\",\"datePublished\":\"2021-07-29T07:59:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/\"},\"wordCount\":234,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/07\\\/218665611_802473313770797_817870094143793234_n-scaled.jpeg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/\",\"name\":\"Donne protagoniste del loro tempo - Siore Rine una imprenditrice all'avanguardia - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/07\\\/218665611_802473313770797_817870094143793234_n-scaled.jpeg\",\"datePublished\":\"2021-07-29T07:59:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/07\\\/218665611_802473313770797_817870094143793234_n-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/07\\\/218665611_802473313770797_817870094143793234_n-scaled.jpeg\",\"width\":2560,\"height\":950},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donne protagoniste del loro tempo &#8211; Siore Rine una imprenditrice all&#8217;avanguardia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donne protagoniste del loro tempo - Siore Rine una imprenditrice all'avanguardia - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/","og_locale":"it_IT","og_type":"article","og_title":"Donne protagoniste del loro tempo - Siore Rine una imprenditrice all'avanguardia - Fagagna","og_description":"Nella Fagagna di fine anni \u201940, basata sull\u2019agricoltura e caratterizzata da una grande semplicit\u00e0 di vita, Anna Erinna Piccoli (moglie del sior Aldo Cecconi e chiamata affettuosamente siore Rine) d\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-07-29T07:59:59+00:00","og_image":[{"width":2560,"height":950,"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/218665611_802473313770797_817870094143793234_n-scaled.jpeg","type":"image\/jpeg"}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Donne protagoniste del loro tempo &#8211; Siore Rine una imprenditrice all&#8217;avanguardia","datePublished":"2021-07-29T07:59:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/"},"wordCount":234,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/218665611_802473313770797_817870094143793234_n-scaled.jpeg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/","url":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/","name":"Donne protagoniste del loro tempo - Siore Rine una imprenditrice all'avanguardia - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/218665611_802473313770797_817870094143793234_n-scaled.jpeg","datePublished":"2021-07-29T07:59:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/218665611_802473313770797_817870094143793234_n-scaled.jpeg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/218665611_802473313770797_817870094143793234_n-scaled.jpeg","width":2560,"height":950},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/donne-protagoniste-del-loro-tempo-siore-rine-una-imprenditrice-allavanguardia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Donne protagoniste del loro tempo &#8211; Siore Rine una imprenditrice all&#8217;avanguardia"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=894"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/894\/revisions"}],"predecessor-version":[{"id":896,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/894\/revisions\/896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media\/895"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}