{"id":902,"date":"2021-08-19T10:31:40","date_gmt":"2021-08-19T08:31:40","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=902"},"modified":"2021-08-19T10:31:40","modified_gmt":"2021-08-19T08:31:40","slug":"aurore-secret-concert-tra-le-colline-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/","title":{"rendered":"Aurore: secret concert tra le colline"},"content":{"rendered":"<p style=\"font-weight: 400\">Ricordiamo che l&#8217;evento <em>Aurore<\/em> \u00e8 stato rinviato a <strong>domenica 22 agosto alle ore 18<\/strong> (e non alle 19).<\/p>\n<p style=\"font-weight: 400\">La musica l\u00e0 dove meno te lo aspetti, una location segreta lungo il nuovo cammino dei 10.000 passi che si snoda tra le colline tra Moruzzo, Martignacco e Fagagna. Questa l\u2019idea che le tre amministrazioni comunali hanno condiviso e realizzato grazie alla preziosa collaborazione con la famiglia Rubilant, l\u2019azienda agricola Il Poggio e l\u2019Associazione Progetto Musica.<\/p>\n<p style=\"font-weight: 400\">Una novit\u00e0 sul territorio che nasce dalla passione per questi luoghi e dalla considerazione che ritrovarsi tra arte e natura \u00e8 la risposta pi\u00f9 efficace alle nuove esigenze di fruizione della musica del vivo che le nuove regole ci impongono. L\u2019obiettivo \u00e8 quello di coinvolgere un pubblico molto eterogeneo, voglioso di rimettersi in movimento, di emozionarsi e di immaginare un tempo nuovo attraverso la cultura, con appuntamenti che conciliano musica e benessere psicofisico.<\/p>\n<p style=\"font-weight: 400\">Passeggiate lungo il cammino\u00a0<strong>\u201c10.000 passi di salute\u201d<\/strong>\u00a0che partendo da tre punti differenti (comuni di Moruzzo, Fagagna e Martignacco) conducono alla location segreta in cui si collocano interventi musicali in natura, pensati per armonizzarsi con la\u00a0<strong>cornice sonora dell\u2019open air<\/strong>.<\/p>\n<p style=\"font-weight: 400\">L\u2019appuntamento \u00e8 quindi per le ore 18.00 a Moruzzo &#8211; Piazzale del Municipio, oppure a Martignacco &#8211; Piazzale Cimitero, o a Fagagna presso il Castello di Villalta. I camminatori e le camminatrici saranno accompagnati da una guida fino al luogo segreto del concerto della pianista Agnese Toniutti. L\u2019inizio del concerto \u00e8 previsto per le ore 18.30.<\/p>\n<p><span style=\"font-family: arial, sans-serif\">Si consiglia di portarsi una coperta per sedersi sul prato, mentre a\u00a0<\/span>conclusione del concerto \u00e8 prevista una piccola colazione sull\u2019erba grazie alla collaborazione delle proloco locali.<\/p>\n<p style=\"font-weight: 400\">L\u2019iniziativa \u00e8 possibile grazie allo sforzo congiunto dei comuni di Moruzzo, Fagagna e Martignacco, al contributo della Fondazione Friuli e alla collaborazione con le proloco locali.<\/p>\n<p style=\"font-weight: 400\">Evento a ingresso libero.<\/p>\n<p style=\"font-weight: 400\">Per info e prenotazione: Associazione Progetto Musica<\/p>\n<p style=\"font-weight: 400\">Mail:\u00a0<a href=\"mailto:info@associazioneprogettomusica.org\">info@associazioneprogettomusica.org<\/a>\u00a0oppure\u00a0<a href=\"mailto:concerto.aurore@gmail.com\">concerto.aurore@gmail.com<\/a><\/p>\n<p style=\"font-weight: 400\">Tel. 0432 532330 (Dal luned\u00ec al venerd\u00ec dalle 10.00 alle 15.00)<\/p>\n<p>In allegato la locandina degli eventi.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_886\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/Flayer-1920X1080verticale.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/Flayer-1920X1080verticale.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Flayer 1920X1080verticale<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ricordiamo che l&#8217;evento Aurore \u00e8 stato rinviato a domenica 22 agosto alle ore 18 (e non alle 19). La musica l\u00e0 dove meno te lo aspetti, una location segreta lungo [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-902","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aurore: secret concert tra le colline - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aurore: secret concert tra le colline - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Ricordiamo che l&#8217;evento Aurore \u00e8 stato rinviato a domenica 22 agosto alle ore 18 (e non alle 19). La musica l\u00e0 dove meno te lo aspetti, una location segreta lungo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-19T08:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/08\\\/19\\\/aurore-secret-concert-tra-le-colline-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/08\\\/19\\\/aurore-secret-concert-tra-le-colline-2\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Aurore: secret concert tra le colline\",\"datePublished\":\"2021-08-19T08:31:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/08\\\/19\\\/aurore-secret-concert-tra-le-colline-2\\\/\"},\"wordCount\":331,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/08\\\/19\\\/aurore-secret-concert-tra-le-colline-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/08\\\/19\\\/aurore-secret-concert-tra-le-colline-2\\\/\",\"name\":\"Aurore: secret concert tra le colline - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"datePublished\":\"2021-08-19T08:31:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/08\\\/19\\\/aurore-secret-concert-tra-le-colline-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/08\\\/19\\\/aurore-secret-concert-tra-le-colline-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/08\\\/19\\\/aurore-secret-concert-tra-le-colline-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aurore: secret concert tra le colline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aurore: secret concert tra le colline - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/","og_locale":"it_IT","og_type":"article","og_title":"Aurore: secret concert tra le colline - Fagagna","og_description":"Ricordiamo che l&#8217;evento Aurore \u00e8 stato rinviato a domenica 22 agosto alle ore 18 (e non alle 19). La musica l\u00e0 dove meno te lo aspetti, una location segreta lungo [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-08-19T08:31:40+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png","height":600,"width":1200,"type":""}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Aurore: secret concert tra le colline","datePublished":"2021-08-19T08:31:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/"},"wordCount":331,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/","url":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/","name":"Aurore: secret concert tra le colline - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"datePublished":"2021-08-19T08:31:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/08\/19\/aurore-secret-concert-tra-le-colline-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Aurore: secret concert tra le colline"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=902"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/902\/revisions"}],"predecessor-version":[{"id":903,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/902\/revisions\/903"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}