{"id":991,"date":"2021-11-25T11:45:12","date_gmt":"2021-11-25T10:45:12","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=991"},"modified":"2021-11-25T11:45:12","modified_gmt":"2021-11-25T10:45:12","slug":"25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/","title":{"rendered":"25 novembre &#8211; giornata per l&#8217;eliminazione della violenza sulle donne"},"content":{"rendered":"<p>Cittadini e amministrazione uniti per dire Basta alla violenza di ogni grado contro le donne oggi 25 novembre come tutti gli altri giorni dell&#8217;anno.<\/p>\n<p>Anche in tempo di pandemia il messaggio deve essere forte e chiaro e raggiungere tutta la cittadinanza, ancor di pi\u00f9 ora, dove l\u2019isolamento, la convivenza forzata e l\u2019instabilit\u00e0 socioeconomica di questo periodo di prolungata emergenza sanitaria, hanno comportato per le donne il rischio di una ancor maggior esposizione alla violenza domestica.<\/p>\n<p>Il Comune di Fagagna, in sinergia con i servizi sociali del territorio, continua a garantire la migliore assistenza possibile per tutte le donne in difficolt\u00e0. Il Centro Risorsa Donna, con cui il comune \u00e8 convenzionato, continua la sua attivit\u00e0 di ascolto e supporto psicologico anche telefonicamente.<\/p>\n<p>SPORTELLO DI CONSULENZA PSICOLOGICA<\/p>\n<p>CENTRO RISORSA DONNA<\/p>\n<p>Via Mazzini,\u00a05 \u2013 San Daniele del Friuli UD<\/p>\n<p>tel. 0432 940115<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cittadini e amministrazione uniti per dire Basta alla violenza di ogni grado contro le donne oggi 25 novembre come tutti gli altri giorni dell&#8217;anno. Anche in tempo di pandemia il [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>25 novembre - giornata per l&#039;eliminazione della violenza sulle donne - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25 novembre - giornata per l&#039;eliminazione della violenza sulle donne - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Cittadini e amministrazione uniti per dire Basta alla violenza di ogni grado contro le donne oggi 25 novembre come tutti gli altri giorni dell&#8217;anno. Anche in tempo di pandemia il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-25T10:45:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/11\/Basta-violenza-sulle-donne_.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"25 novembre &#8211; giornata per l&#8217;eliminazione della violenza sulle donne\",\"datePublished\":\"2021-11-25T10:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/\"},\"wordCount\":145,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/11\\\/Basta-violenza-sulle-donne_.jpeg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/\",\"name\":\"25 novembre - giornata per l'eliminazione della violenza sulle donne - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/11\\\/Basta-violenza-sulle-donne_.jpeg\",\"datePublished\":\"2021-11-25T10:45:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/11\\\/Basta-violenza-sulle-donne_.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/11\\\/Basta-violenza-sulle-donne_.jpeg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/11\\\/25\\\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"25 novembre &#8211; giornata per l&#8217;eliminazione della violenza sulle donne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"25 novembre - giornata per l'eliminazione della violenza sulle donne - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/","og_locale":"it_IT","og_type":"article","og_title":"25 novembre - giornata per l'eliminazione della violenza sulle donne - Fagagna","og_description":"Cittadini e amministrazione uniti per dire Basta alla violenza di ogni grado contro le donne oggi 25 novembre come tutti gli altri giorni dell&#8217;anno. Anche in tempo di pandemia il [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-11-25T10:45:12+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/11\/Basta-violenza-sulle-donne_.jpeg","type":"image\/jpeg"}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"25 novembre &#8211; giornata per l&#8217;eliminazione della violenza sulle donne","datePublished":"2021-11-25T10:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/"},"wordCount":145,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/11\/Basta-violenza-sulle-donne_.jpeg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/","url":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/","name":"25 novembre - giornata per l'eliminazione della violenza sulle donne - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/11\/Basta-violenza-sulle-donne_.jpeg","datePublished":"2021-11-25T10:45:12+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/11\/Basta-violenza-sulle-donne_.jpeg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/11\/Basta-violenza-sulle-donne_.jpeg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/11\/25\/25-novembre-giornata-per-leliminazione-della-violenza-sulle-donne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"25 novembre &#8211; giornata per l&#8217;eliminazione della violenza sulle donne"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=991"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/991\/revisions"}],"predecessor-version":[{"id":993,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/991\/revisions\/993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media\/992"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}