{"id":1045,"date":"2017-09-19T09:56:22","date_gmt":"2017-09-19T07:56:22","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1045"},"modified":"2017-09-19T09:56:22","modified_gmt":"2017-09-19T07:56:22","slug":"delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/","title":{"rendered":"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino"},"content":{"rendered":"<p>Guidata dal professor<strong> Paolo Maddalena<\/strong>, \u00e8 giunta, luned\u00ec 18 settembre, a Ferentino, <strong>una delegazione giapponese della citt\u00e0 di Kochi<\/strong>, una citt\u00e0 di oltre 300mila abitanti, situata nell\u2019isola di Shikoku, una delle quattro isole principali del paese del Sol Levante. Paolo Maddalena, originario di Ferentino, laurea in Scienze e Tecnologie della Comunicazione, certificazione Ditals dell\u2019Universit\u00e0 per Stranieri di Siena, ha scelto di vivere a Kochi, dove si \u00e8 trasferito, seguendo la propria passione per il Giappone, e dove ha aperto una scuola di lingue.<\/p>\n<p>La delegazione, accolta dal sindaco, Antonio Pompeo e dall\u2019assessore alla Pubblica Istruzione, Francesca Collalti, dal segretario generale, Franco Loi, ha anticipato l\u2019obiettivo di <strong>una reciproca conoscenza territoriale e culturale<\/strong> per dar corso a uno scambio d\u2019interessi comuni, storici, turistici, formativi, ambientali, enogastronomici. Finalit\u00e0 della <strong>visita in Ciociaria<\/strong> \u00e8 scoprire le peculiarit\u00e0 tipiche delle coltivazioni di frutta e verdura, la tradizione contadina con il contatto diretto con gli ingredienti, ricerca e scelta nel sapere dove sono nati e cresciuti, i<strong> segreti della cucina \u201ccasalinga e tradizionale,\u201d la ristorazione a Km0, le produzioni rigorosamente bio e di territorio.<\/strong><\/p>\n<p>La fortuna di Kochi &#8211; ha dichiarato Paolo Maddalena &#8211; \u00e8 di avere <strong>tradizioni e natura impeccabili,<\/strong> oltre ad essere una cittadina molto dinamica, che punta molto su ambiente e turismo.\u00a0 E\u2019 anche famosa per il suo<strong> festival, il Yasakoi-matsuri,<\/strong> tra il 9 e 12 agosto oltre 20.000 ballerini in yukata dai colori vivaci riempiono la citt\u00e0 di danze tradizionali. A Kochi si pu\u00f2 fare sport estremo in montagna, gustare un ricchissimo street food, praticare pesca estrema, andare a fare escursioni con la Vespa, assaggiare pesci, frutta e piatti che si possono trovare solo qui. <strong>L\u2019obiettivo di far diventare Kochi la capitale del bio in Giappone \u00e8 quasi raggiunto<\/strong>.<\/p>\n<p>Il sindaco Antonio Pompeo, facendo gli onori di casa, ha contraccambiato i saluti e condiviso le finalit\u00e0 della collaborazione: cultura, turismo, arte, storia, tradizioni, auspicando una forte cooperazione in ambito commerciale per lo sviluppo di progetti comuni, scambi di prodotti locali di qualit\u00e0, valenza culturale dell\u2019enogastronomia regionale insieme al suo importante ruolo nell\u2019offerta turistica nazionale, attivit\u00e0 di promozione e informazioni agli operatori locali interessati, informazioni sui produttori italiani, valorizzando i rispettivi territori.<\/p>\n<p>Accompagnati da una guida e dallo stesso professor, Paolo Maddalena, la delegazione di Kochi ha poi avuto la possibilit\u00e0 di ammirare i monumenti e le chiese pi\u00f9 importanti della Citt\u00e0 di Ferentino. Questi i membri della delegazione, iscritti all\u2019Associazione \u201cAmici d\u2019Italia di Kochi\u201d: Toshihiko Morioka, Kanae Kitamura, Reiko Tanaka, Etsuko Kubouchi, Kumiko Manabe, Junko Minezumi; studiosi di lingue e in grado di esprimersi in modo chiaro e corrente nella nostra lingua.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1047\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0047-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0047-300x225.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0047-768x576.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0047-1024x768.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0047-680x510.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0047.jpg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1048\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0050-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0050-300x225.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0050-768x576.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0050-1024x768.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0050-680x510.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0050.jpg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1049\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0048-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0048-300x225.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0048-768x576.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0048-1024x768.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0048-680x510.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0048.jpg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1050\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0040-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0040-300x225.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0040-768x576.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0040-1024x768.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0040-680x510.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/IMG-20170918-WA0040.jpg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1051\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/1-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/1-300x169.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/1-768x433.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/1-680x383.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/1-800x451.jpg 800w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/1.jpg 852w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1052\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/182684_w-684_h-242_q-70_m-crop-300x106.jpg\" alt=\"\" width=\"481\" height=\"170\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/182684_w-684_h-242_q-70_m-crop-300x106.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/182684_w-684_h-242_q-70_m-crop-680x241.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/182684_w-684_h-242_q-70_m-crop.jpg 684w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guidata dal professor Paolo Maddalena, \u00e8 giunta, luned\u00ec 18 settembre, a Ferentino, una delegazione giapponese della citt\u00e0 di Kochi, una citt\u00e0 di oltre 300mila abitanti, situata nell\u2019isola di Shikoku, una [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Guidata dal professor Paolo Maddalena, \u00e8 giunta, luned\u00ec 18 settembre, a Ferentino, una delegazione giapponese della citt\u00e0 di Kochi, una citt\u00e0 di oltre 300mila abitanti, situata nell\u2019isola di Shikoku, una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-19T07:56:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino\",\"datePublished\":\"2017-09-19T07:56:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/\"},\"wordCount\":445,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/\",\"name\":\"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg\",\"datePublished\":\"2017-09-19T07:56:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg\",\"width\":680,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/19\\\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/","og_locale":"it_IT","og_type":"article","og_title":"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino - Ferentino","og_description":"Guidata dal professor Paolo Maddalena, \u00e8 giunta, luned\u00ec 18 settembre, a Ferentino, una delegazione giapponese della citt\u00e0 di Kochi, una citt\u00e0 di oltre 300mila abitanti, situata nell\u2019isola di Shikoku, una [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-09-19T07:56:22+00:00","og_image":[{"width":680,"height":472,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino","datePublished":"2017-09-19T07:56:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/"},"wordCount":445,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/","name":"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg","datePublished":"2017-09-19T07:56:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/SUZUKI_Swift_LONGArticles_2013_JUN_kochi_05.jpg","width":680,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/19\/delegati-della-citta-di-kochi-giappone-in-visita-a-ferentino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Delegati della citt\u00e0 di Kochi (Giappone) in visita a Ferentino"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1045"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1045\/revisions"}],"predecessor-version":[{"id":1053,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1045\/revisions\/1053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1046"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}