{"id":1054,"date":"2017-09-23T12:48:02","date_gmt":"2017-09-23T10:48:02","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1054"},"modified":"2017-09-23T12:48:02","modified_gmt":"2017-09-23T10:48:02","slug":"ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/","title":{"rendered":"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE"},"content":{"rendered":"<p>Funziona molto bene il progetto dell\u2019assegno per il servizio civico promosso dal Comune di Ferentino. Una iniziativa pilota per il territorio, che sta rappresentando una risposta reale alla domanda di assistenza per quei cittadini e le relative famiglie che vivono situazioni di disagio e di rischio emarginazione, sia legate alla mancanza di lavoro che a specifiche situazioni personali.<\/p>\n<p>Un\u2019altra scelta che si \u00e8 dimostrata vincente da parte dell\u2019Amministrazione comunale guidata dal sindaco Antonio Pompeo. Anche perch\u00e9, attraverso le attivit\u00e0 che il progetto riesce e a garantire, costituisce anche un valore aggiunto in termini di servizi e manutenzione per il territorio. Dunque, un beneficio per la citt\u00e0 e per coloro che possono usufruire di questo strumento di contrasto al disagio economico.<\/p>\n<p>In questi giorni, i lavoratori attualmente impiegati nel progetto, coordinati dal funzionario del Comune Oreste Datti, stanno pulendo e bonificando da sterpaglie e immondizia una delle strade di accesso alla citt\u00e0 pi\u00f9 trafficate, la consortile nella zona industriale.<\/p>\n<p>L\u2019obiettivo \u00e8 quello che l\u2019Amministrazione comunale persegue in ogni intervento che porta avanti: offrire maggiore decoro, pi\u00f9 fruibilit\u00e0 e sicurezza, in particolare quando si tratta di viabilit\u00e0, nello specifico rispetto ad uno degli accessi principali alla citt\u00e0.<\/p>\n<p>\u201cL\u2019assegno per il\u00a0servizio\u00a0civico\u00a0\u2013 ha spiegato il sindaco Antonio Pompeo \u2013 \u00e8 stata una scelta vincente per il Comune di Ferentino. Un progetto innovativo che ha anticipato il dibattito e i provvedimenti simili in termini di lavori di pubblica utilit\u00e0 a livello nazionale e regionale.<\/p>\n<p>Lo scorso anno, alla sperimentazione del provvedimento, abbiamo riscontrato la validit\u00e0 della misura, capace di garantire dignit\u00e0 e reddito e lo abbiamo riproposto\u201d.<\/p>\n<p>\u201cNon la risoluzione del problema, ma un aiuto concreto. Non un semplice contributo assistenziale, ma un progetto di inserimento sociale attivo, in cui attraverso un lavoro di pubblica utilit\u00e0 si possa essere destinatari di un sussidio \u2013 ha aggiunto l\u2019assessore ai servizi sociali Luigi Vittori &#8211; Un progetto che mette al centro le persone e il lavoro, valorizza il ruolo di ciascuno e la possibilit\u00e0 di dare un contributo per migliorare la nostra citt\u00e0. Una iniziativa che sicuramente continueremo a riproporre anche nel prossimo periodo perch\u00e9 funziona\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Funziona molto bene il progetto dell\u2019assegno per il servizio civico promosso dal Comune di Ferentino. Una iniziativa pilota per il territorio, che sta rappresentando una risposta reale alla domanda di [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Funziona molto bene il progetto dell\u2019assegno per il servizio civico promosso dal Comune di Ferentino. Una iniziativa pilota per il territorio, che sta rappresentando una risposta reale alla domanda di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-23T10:48:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/servizio-civico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE\",\"datePublished\":\"2017-09-23T10:48:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/\"},\"wordCount\":364,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/servizio-civico.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/\",\"name\":\"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/servizio-civico.jpg\",\"datePublished\":\"2017-09-23T10:48:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/servizio-civico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/servizio-civico.jpg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/09\\\/23\\\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE - Ferentino","og_description":"Funziona molto bene il progetto dell\u2019assegno per il servizio civico promosso dal Comune di Ferentino. Una iniziativa pilota per il territorio, che sta rappresentando una risposta reale alla domanda di [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-09-23T10:48:02+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/servizio-civico.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE","datePublished":"2017-09-23T10:48:02+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/"},"wordCount":364,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/servizio-civico.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/","name":"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/servizio-civico.jpg","datePublished":"2017-09-23T10:48:02+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/servizio-civico.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/servizio-civico.jpg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/09\/23\/ferentino-funziona-lassegno-per-il-servizio-civico-ripulita-la-consortile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO, FUNZIONA L\u2019ASSEGNO PER IL SERVIZIO CIVICO. RIPULITA LA CONSORTILE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1054"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1054\/revisions"}],"predecessor-version":[{"id":1056,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1054\/revisions\/1056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1055"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}