{"id":113,"date":"2017-02-02T13:03:10","date_gmt":"2017-02-02T12:03:10","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=113"},"modified":"2017-02-02T13:03:10","modified_gmt":"2017-02-02T12:03:10","slug":"commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/","title":{"rendered":"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017"},"content":{"rendered":"<p>\u201cSono diverse le opportunit\u00e0 e gli incentivi per stimolare le attivit\u00e0 commerciali, contenute nel documento di bilancio 2017, che l\u2019Amministrazione comunale ha approvato in questi giorni. Ci\u00f2 dimostra la nostra volont\u00e0 di sostenere questo fondamentale comparto produttivo della citt\u00e0 di Ferentino\u201d.<\/p>\n<p>E\u2019 quanto afferma l\u2019assessore al commercio, Massimo Gargani. \u201cIl provvedimento pi\u00f9 importante riguarda la diminuzione della Tosap, la tassa per l\u2019occupazione del suolo pubblico che scender\u00e0, rispetto al 2016, del 10%. Sar\u00e0 pi\u00f9 conveniente esporre merce per i negozi, per i bar posizionare tavoli e sedie all\u2019aria aperta, per gli ambulanti frequentare con i propri banchi il mercato cittadino. Non solo, ne beneficeranno anche le attivit\u00e0 legate all\u2019edilizia per esempio, per le quali diminuir\u00e0 l\u2019imposta per i ponteggi esterni. Per il quarto anno consecutivo, questa Amministrazione interviene abbassando costantemente la tariffa della Tosap, proprio per venire incontro alle esigenze dei commercianti: sia delle attivit\u00e0 fisse che di quelle ambulanti. Provvedimenti che si inseriscono in un percorso di dialogo e di confronto costante. La prossima settimana, per esempio, si svolger\u00e0 un incontro in Comune proprio con gli ambulanti\u201d.<\/p>\n<p>\u201cInfine \u2013 ha concluso Gargani \u2013 restano in vigore anche i provvedimenti per incentivare gli investimenti nel centro storico: mille euro l\u2019anno di sconto sulle imposte comunali per i cittadini che vogliono avviare un\u2019attivit\u00e0 commerciale. Si tratta di un provvedimento di rilievo, che abbatte del 50% le imposte comunali della Tosap, della tassa sui rifiuti, della Tasi e dell\u2019Imu per un importo massimo di mille euro l\u2019anno per i primi tre anni di attivit\u00e0. Potranno accedervi coloro che sono interessati ad avviare una qualsivoglia tipologia di attivit\u00e0, rivolgendo specifica richiesta agli uffici comunali\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSono diverse le opportunit\u00e0 e gli incentivi per stimolare le attivit\u00e0 commerciali, contenute nel documento di bilancio 2017, che l\u2019Amministrazione comunale ha approvato in questi giorni. Ci\u00f2 dimostra la nostra [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attivita-produttive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017 - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017 - Ferentino\" \/>\n<meta property=\"og:description\" content=\"\u201cSono diverse le opportunit\u00e0 e gli incentivi per stimolare le attivit\u00e0 commerciali, contenute nel documento di bilancio 2017, che l\u2019Amministrazione comunale ha approvato in questi giorni. Ci\u00f2 dimostra la nostra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-02T12:03:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/Ferentino-mercato-repertorio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1974\" \/>\n\t<meta property=\"og:image:height\" content=\"1430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017\",\"datePublished\":\"2017-02-02T12:03:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/\"},\"wordCount\":285,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/Ferentino-mercato-repertorio.jpg\",\"articleSection\":[\"Attivit\u00e0 Produttive\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/\",\"name\":\"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017 - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/Ferentino-mercato-repertorio.jpg\",\"datePublished\":\"2017-02-02T12:03:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/Ferentino-mercato-repertorio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/Ferentino-mercato-repertorio.jpg\",\"width\":1974,\"height\":1430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/02\\\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017 - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/","og_locale":"it_IT","og_type":"article","og_title":"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017 - Ferentino","og_description":"\u201cSono diverse le opportunit\u00e0 e gli incentivi per stimolare le attivit\u00e0 commerciali, contenute nel documento di bilancio 2017, che l\u2019Amministrazione comunale ha approvato in questi giorni. Ci\u00f2 dimostra la nostra [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-02-02T12:03:10+00:00","og_image":[{"width":1974,"height":1430,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/Ferentino-mercato-repertorio.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017","datePublished":"2017-02-02T12:03:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/"},"wordCount":285,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/Ferentino-mercato-repertorio.jpg","articleSection":["Attivit\u00e0 Produttive"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/","name":"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017 - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/Ferentino-mercato-repertorio.jpg","datePublished":"2017-02-02T12:03:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/Ferentino-mercato-repertorio.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/Ferentino-mercato-repertorio.jpg","width":1974,"height":1430},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/02\/commercio-lassessore-gargani-illustra-le-opportunita-contenute-nel-bilancio-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"COMMERCIO, L\u2019ASSESSORE GARGANI ILLUSTRA LE OPPORTUNITA\u2019 CONTENUTE NEL BILANCIO 2017"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=113"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/113\/revisions"}],"predecessor-version":[{"id":115,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/113\/revisions\/115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/114"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}