{"id":1170,"date":"2017-11-15T13:51:37","date_gmt":"2017-11-15T12:51:37","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1170"},"modified":"2017-11-16T11:24:55","modified_gmt":"2017-11-16T10:24:55","slug":"ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/","title":{"rendered":"ORDINANZA N. 28  del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018"},"content":{"rendered":"<p>&#8230; omissis &#8230; Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018<\/p>\n<ol>\n<li><strong>LIMITAZIONI AL TRAFFICO VEICOLARE<\/strong><\/li>\n<\/ol>\n<p>a) divieto di circolazione 0-24, dal luned\u00ec al venerd\u00ec, per gli autoveicoli alimentati a benzina con caratteristiche emissive EURO 0, EURO 1 ad esclusione dei veicoli muniti di impianto a GPL o metano;<\/p>\n<p>b) Il divieto di circolazione 0-24, dal luned\u00ec al venerd\u00ec, per gli autoveicoli diesel con caratteristiche emissive EURO 0, EURO 1, EURO 2;<\/p>\n<p>c) Il divieto di circolazione 0-24 per ciclomotori e motoveicoli con motore a quattro tempi e caratteristiche emissive EURO 0;<\/p>\n<p>d) Il divieto di circolazione 0-24 per ciclomotori e motoveicoli con motore a due tempi e caratteristiche emissive EURO 0, EURO 1;<\/p>\n<p>e) Il divieto di circolazione, dal luned\u00ec al venerd\u00ec, dalle ore 10:00 alle ore 14:00 e dalle ore 16:00 alle ore 20:00 per i veicoli adibiti a trasporto merci con massa complessiva non superiore a 3,5 tonnellate, con eccezione dei veicoli a basso impatto ambientale (alimentati a GPL., metano, elettrici o ibridi, Euro 6), e dei veicoli degli operatori commerciali partecipanti al mercato rionale del marted\u00ec.<\/p>\n<p>In deroga a quanto disposto al punto e), al solo fine di consentire lo scarico merci, \u00e8 autorizzato il transito dalle ore 10:00 alle ore 14:00<\/p>\n<p>Le limitazioni alla circolazione veicolare di cui sopra non riguardano i veicoli adibiti a servizi di polizia, a servizi pubblici, a compiti di sicurezza, a servizi di protezione civile, a servizi sanitari.<\/p>\n<ol start=\"2\">\n<li><strong>ISTITUZIONE DI N. 04 DOMENICHE ECOLOGICH<\/strong>E<\/li>\n<\/ol>\n<p>per i giorni: <strong>26\/11\/2017 &#8211; 07\/01\/2018 &#8211; 28\/01\/2018 &#8211; 11\/02\/2018<\/strong><\/p>\n<p>Con <strong>Blocco totale della circolazione veicolare dalle ore 08:00 alle ore 18:00<\/strong><\/p>\n<p>Nelle suindicate giornate \u00e8 istituito il divieto di circolazione dinamica nell\u2019area urbana sopra indicata, per tutti i veicoli ad uso privato<\/p>\n<p>Le limitazioni alla circolazione veicolare di cui sopra non riguardano i veicoli adibiti a servizi di polizia, a servizi pubblici, a compiti di sicurezza, a servizi di protezione civile, a servizi sanitari ed a servizio di persone con limitata o impedita capacit\u00e0 motoria.<\/p>\n<ol start=\"3\">\n<li><strong>CIRCOLAZIONE A TARGHE ALTERNE &#8211; Dal 01\/12\/2017 al 31\/03\/2018<\/strong><\/li>\n<\/ol>\n<p>Limitazione della circolazione a targhe alterne per tutti i veicoli a combustione interna ad uso privato nei giorni di <strong>LUNEDI\u2019 e VENERDI\u2019<\/strong> dalle ore <strong>08:30 alle ore 13:00<\/strong> e dalle ore <strong>14:00 alle ore 21:30<\/strong>, consentendo la circolazione nei giorni di luned\u00ec ai soli veicoli con targa dispari e nei giorni di venerd\u00ec ai soli veicoli con targa pari.<\/p>\n<p>Le limitazioni alla circolazione veicolare di cui sopra non riguardano, altres\u00ec, i veicoli adibiti a servizi di polizia, a servizi pubblici, a compiti di sicurezza, a servizi di protezione civile, a servizi sanitari ed a servizio di persone con limitata o impedita capacit\u00e0 motoria.<\/p>\n<p>In deroga a tale disposto sulle targhe alterne, a prescindere dalla targa pari o dispari, <strong>potranno circolare le seguenti categorie di veicoli: veicoli a trazione elettrica ed ibridi, veicoli alimentati a metano e g.p.l, veicoli EURO 6<\/strong><\/p>\n<p>&#8230; omissis &#8230;<\/p>\n<p>Clendario domeniche ecologiche<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1176\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/11\/Domeniche-ecologiche-2017-2018-213x300.jpg\" alt=\"\" width=\"296\" height=\"417\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/11\/Domeniche-ecologiche-2017-2018-213x300.jpg 213w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/11\/Domeniche-ecologiche-2017-2018.jpg 498w\" sizes=\"auto, (max-width: 296px) 100vw, 296px\" \/><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1171\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/11\/DELIMITAZIONE-ZTL-CENTRO-URBANO.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/11\/DELIMITAZIONE-ZTL-CENTRO-URBANO.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>DELIMITAZIONE ZTL CENTRO URBANO<\/a><\/li>\n<li><a id=\"wpba_attachment_list_1172\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/11\/ORDINANZA-TRAFFICO-AMBIENTE-2017-2018.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/11\/ORDINANZA-TRAFFICO-AMBIENTE-2017-2018.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ORDINANZA TRAFFICO AMBIENTE 2017-2018<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; omissis &#8230; Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 LIMITAZIONI AL TRAFFICO VEICOLARE a) divieto di circolazione 0-24, dal luned\u00ec al [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 - Ferentino\" \/>\n<meta property=\"og:description\" content=\"&#8230; omissis &#8230; Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 LIMITAZIONI AL TRAFFICO VEICOLARE a) divieto di circolazione 0-24, dal luned\u00ec al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-15T12:51:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-16T10:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/Ordinanze.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"270\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018\",\"datePublished\":\"2017-11-15T12:51:37+00:00\",\"dateModified\":\"2017-11-16T10:24:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/\"},\"wordCount\":478,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/Ordinanze.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/\",\"name\":\"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/Ordinanze.jpg\",\"datePublished\":\"2017-11-15T12:51:37+00:00\",\"dateModified\":\"2017-11-16T10:24:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/Ordinanze.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/09\\\/Ordinanze.jpg\",\"width\":270,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/11\\\/15\\\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/","og_locale":"it_IT","og_type":"article","og_title":"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 - Ferentino","og_description":"&#8230; omissis &#8230; Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 LIMITAZIONI AL TRAFFICO VEICOLARE a) divieto di circolazione 0-24, dal luned\u00ec al [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-11-15T12:51:37+00:00","article_modified_time":"2017-11-16T10:24:55+00:00","og_image":[{"width":270,"height":300,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/Ordinanze.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018","datePublished":"2017-11-15T12:51:37+00:00","dateModified":"2017-11-16T10:24:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/"},"wordCount":478,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/Ordinanze.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/","name":"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018 - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/Ordinanze.jpg","datePublished":"2017-11-15T12:51:37+00:00","dateModified":"2017-11-16T10:24:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/Ordinanze.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/09\/Ordinanze.jpg","width":270,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/11\/15\/ordinanza-n-28-del-14-11-2017-provvedimenti-per-il-risanamento-della-qualita-dellaria-interventi-programmatici-di-limitazione-del-traffico-anno-2017-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"ORDINANZA N. 28 del 14.11.2017 Provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria. Interventi programmatici di limitazione del traffico anno 2017-2018"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1170"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1170\/revisions"}],"predecessor-version":[{"id":1179,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1170\/revisions\/1179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/989"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}