{"id":1259,"date":"2017-12-02T14:30:17","date_gmt":"2017-12-02T13:30:17","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1259"},"modified":"2017-12-02T14:54:12","modified_gmt":"2017-12-02T13:54:12","slug":"ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/","title":{"rendered":"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra"},"content":{"rendered":"<p><em>Il sindaco Pompeo: \u201cImpegno mantenuto. Per la nostra citt\u00e0 un\u2019ulteriore opportunit\u00e0\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Ferentino si conferma citt\u00e0 in controtendenza. In un momento di difficolt\u00e0, di tagli e di accorpamenti, il centro gigliato invece si segnala per l\u2019esatto opposto. E dopo le recenti inaugurazioni di diverse opere pubbliche, il taglio del nastro di nuovi servizi socio sanitari, ecco concretizzarsi un\u2019altra opportunit\u00e0.<\/p>\n<p>Si \u00e8 svolta oggi, infatti, la conferenza stampa di presentazione dei nuovi corsi che l\u2019Accademia di Belle Arti di Frosinone ha deciso di tenere proprio a Ferentino. Si tratta di due importantissimi e prestigiosi insegnamenti: Arte Sacra contemporanea e Comunicazione e valorizzazione del Patrimonio Artistico. I corsi prenderanno il via luned\u00ec prossimo, 4 dicembre.<\/p>\n<p>Per Ferentino, e soprattutto per l\u2019Amministrazione del sindaco Antonio Pompeo, un ulteriore traguardo raggiunto, attraverso quel solido e consolidato modello operativo che si sta rivelando vincente: dialogo con le istituzioni, lavoro di squadra silenzioso ma fruttuoso per arrivare all\u2019obiettivo prefissato.<\/p>\n<p>Questo ulteriore risultato accresce il prestigio della citt\u00e0, centro di formazione d\u2019eccellenza, ma sicuramente avr\u00e0 i suoi effetti benefici anche sull\u2019economia e sul commercio locale.<\/p>\n<p>Alla presentazione dei corsi nella sede di via Acropoli hanno partecipato il Prefetto di Frosinone Emilia Zarrilli, il Vescovo della Diocesi mons. Ambrogio Spreafico, il presidente dell\u2019Accademia di Belle Arti Ennio De Vellis e il sindaco di Ferentino Antonio Pompeo. Le relazioni tecniche, che hanno dettagliatamente illustrato la portata e la qualit\u00e0 dei corsi che si terranno in citt\u00e0, sono state affidate al professor Luigi Fiorletta, direttore dell\u2019Accademia; alla professoressa Loredana Rea, docente di Storia dell&#8217;Arte e mons. Pasquale Iacobone, Segretario Pontificia Commissione di Archeologia Sacra.<\/p>\n<p>\u201cAvevamo preso un impegno e lo abbiamo mantenuto \u2013 ha spiegato, con soddisfazione, il sindaco Antonio Pompeo \u2013 Per Ferentino un motivo di grande onore, che rafforza la nostra offerta di istruzione di qualit\u00e0, ma potr\u00e0 determinare benefiche ricadute anche per le attivit\u00e0 commerciali. Questo \u00e8 il nostro modo di amministrare: portare a casa risultati concreti, ottenere servizi, dotare la citt\u00e0 di nuove opere e nuove opportunit\u00e0. Oggi \u00e8 un giorno di festa per Ferentino e ringrazio l\u2019Accademia, il presidente De Vellis e il direttore Fiorletta per la collaborazione\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco Pompeo: \u201cImpegno mantenuto. Per la nostra citt\u00e0 un\u2019ulteriore opportunit\u00e0\u201d &nbsp; Ferentino si conferma citt\u00e0 in controtendenza. In un momento di difficolt\u00e0, di tagli e di accorpamenti, il centro [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Il sindaco Pompeo: \u201cImpegno mantenuto. Per la nostra citt\u00e0 un\u2019ulteriore opportunit\u00e0\u201d &nbsp; Ferentino si conferma citt\u00e0 in controtendenza. In un momento di difficolt\u00e0, di tagli e di accorpamenti, il centro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-02T13:30:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-02T13:54:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/accademia-inaugurazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra\",\"datePublished\":\"2017-12-02T13:30:17+00:00\",\"dateModified\":\"2017-12-02T13:54:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/\"},\"wordCount\":374,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/accademia-inaugurazione.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/\",\"name\":\"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/accademia-inaugurazione.jpg\",\"datePublished\":\"2017-12-02T13:30:17+00:00\",\"dateModified\":\"2017-12-02T13:54:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/accademia-inaugurazione.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/accademia-inaugurazione.jpg\",\"width\":1067,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/02\\\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra - Ferentino","og_description":"Il sindaco Pompeo: \u201cImpegno mantenuto. Per la nostra citt\u00e0 un\u2019ulteriore opportunit\u00e0\u201d &nbsp; Ferentino si conferma citt\u00e0 in controtendenza. In un momento di difficolt\u00e0, di tagli e di accorpamenti, il centro [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-12-02T13:30:17+00:00","article_modified_time":"2017-12-02T13:54:12+00:00","og_image":[{"width":1067,"height":800,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/accademia-inaugurazione.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra","datePublished":"2017-12-02T13:30:17+00:00","dateModified":"2017-12-02T13:54:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/"},"wordCount":374,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/accademia-inaugurazione.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/","name":"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/accademia-inaugurazione.jpg","datePublished":"2017-12-02T13:30:17+00:00","dateModified":"2017-12-02T13:54:12+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/accademia-inaugurazione.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/accademia-inaugurazione.jpg","width":1067,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/02\/ferentino-sede-dellaccademia-di-belle-arti-da-lunedi-al-via-i-corsi-di-arte-sacra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Ferentino sede dell\u2019Accademia di Belle Arti, da luned\u00ec al via i corsi di Arte sacra"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1259"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1259\/revisions"}],"predecessor-version":[{"id":1264,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1259\/revisions\/1264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1260"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}