{"id":1399,"date":"2017-12-21T15:35:05","date_gmt":"2017-12-21T14:35:05","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1399"},"modified":"2017-12-21T15:35:05","modified_gmt":"2017-12-21T14:35:05","slug":"ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/","title":{"rendered":"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA"},"content":{"rendered":"<p>Lo spettacolo dei ragazzi del Centro diurno Luca Malancona di Ferentino ha inaugurato le manifestazioni natalizie del contenitore di eventi del settore Politiche Sociali del Comune, \u201cBrilla una Stella\u201d.<\/p>\n<p>Ripensando le Tradizioni, il titolo dell\u2019evento promosso, che ha previsto teatrino di burattini e canti natalizi, con protagonisti i ragazzi del centro e gli operatori.<\/p>\n<p>Un evento molto suggestivo che ha emozionato e coinvolto il folto pubblico presente. In prima fila, come sempre avviene in queste occasioni, il sindaco Antonio Pompeo e il vicesindaco Luigi Vittori.<\/p>\n<p>\u201cUno spettacolo veramente emozionante \u2013 ha dichiarato Antonio Pompeo, che si \u00e8 voluto complimentare con i protagonisti \u2013 mi avete veramente emozionato. Ascoltare le toccanti parole, \u201cSi pu\u00f2 dare\u2026si pu\u00f2 amare\u2026si pu\u00f2 fare di pi\u00f9\u201d, mi conferma che quanto abbiamo fatto in questi anni per sostenere il progetto del Centro \u00e8 stato un lavoro che ha dato i suoi frutti. Non solo, ma \u00e8 la spinta ulteriore a fare sempre meglio, perch\u00e9 questi sono i risultati di cui vado pi\u00f9 orgoglioso\u201d.<\/p>\n<p>Stesse parole di apprezzamento per il vicesindaco Luigi Vittori: \u201cVoglio ringraziare tutta la struttura che lavora tutto l\u2019anno per dare vita a momenti come questo. Il Natale di Ferentino ha questa bella caratteristica, di essere un momento di condivisione e di partecipazione durante il quale la citt\u00e0 mostra il suo grande spirito di solidariet\u00e0\u201d.<\/p>\n<p>Dal sindaco Pompeo e da Luigi Vittori conclusione della manifestazione con gli auguri a tutti i presenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo spettacolo dei ragazzi del Centro diurno Luca Malancona di Ferentino ha inaugurato le manifestazioni natalizie del contenitore di eventi del settore Politiche Sociali del Comune, \u201cBrilla una Stella\u201d. Ripensando [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Lo spettacolo dei ragazzi del Centro diurno Luca Malancona di Ferentino ha inaugurato le manifestazioni natalizie del contenitore di eventi del settore Politiche Sociali del Comune, \u201cBrilla una Stella\u201d. Ripensando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-21T14:35:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/luca-malancona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA\",\"datePublished\":\"2017-12-21T14:35:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/\"},\"wordCount\":249,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/luca-malancona.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/\",\"name\":\"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/luca-malancona.jpg\",\"datePublished\":\"2017-12-21T14:35:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/luca-malancona.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/luca-malancona.jpg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/12\\\/21\\\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA - Ferentino","og_description":"Lo spettacolo dei ragazzi del Centro diurno Luca Malancona di Ferentino ha inaugurato le manifestazioni natalizie del contenitore di eventi del settore Politiche Sociali del Comune, \u201cBrilla una Stella\u201d. Ripensando [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-12-21T14:35:05+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/luca-malancona.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA","datePublished":"2017-12-21T14:35:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/"},"wordCount":249,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/luca-malancona.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/","name":"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/luca-malancona.jpg","datePublished":"2017-12-21T14:35:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/luca-malancona.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/luca-malancona.jpg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/12\/21\/ferentino-brilla-una-stella-successo-per-lo-spettacolo-del-centro-diurno-luca-malancona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO, BRILLA UNA STELLA: SUCCESSO PER LO SPETTACOLO DEL CENTRO DIURNO LUCA MALANCONA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1399"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1399\/revisions"}],"predecessor-version":[{"id":1401,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1399\/revisions\/1401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1400"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}