{"id":1480,"date":"2018-01-19T13:47:25","date_gmt":"2018-01-19T12:47:25","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1480"},"modified":"2018-01-19T16:43:05","modified_gmt":"2018-01-19T15:43:05","slug":"ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/","title":{"rendered":"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE"},"content":{"rendered":"<p>Ferentino ha ospitato oggi, in occasione della ricorrenza di S. Sebastiano, la Festa provinciale della Polizia locale. Una cerimonia solenne alla quale hanno partecipato il Prefetto di Frosinone Emilia Zarrilli, il Vescovo Ambrogio Spreafico, il Questore Rosaria Amato, il comandante provinciale della Finanza, il comandante della stazione dei Carabinieri di Ferentino, Raffaele Alborino, i comuni del territorio, accompagnati dai gonfaloni, i rappresentanti dell\u2019esercito e delle forze dell\u2019ordine, delle scuole e delle associazioni e soprattutto i vigili urbani, oltre naturalmente al padrone di casa, il sindaco di Ferentino e presidente della Provincia Antonio Pompeo.<\/p>\n<p>Dopo il ritrovo in piazza Matteotti, la giornata ha previsto la celebrazione della messa nella Chiesa di San Francesco, presieduta da monsignor Spreafico e la conclusione della mattinata presso il Martino Filetico.<\/p>\n<p>\u201cVoglio ringraziare tutti i presenti \u2013 ha dichiarato il sindaco Antonio Pompeo \u2013 per Ferentino \u00e8 un grande onore ospitare un evento del genere, in cui \u00e8 coinvolto l\u2019intero territorio. La Polizia locale rappresenta un strumento fondamentale e imprescindibile per l\u2019azione amministrativa e di controllo, con funzioni e competenze \u00a0in continua crescita. A tutti i vigili che svolgono con capacit\u00e0 e professionalit\u00e0 il loro compito, va l\u2019apprezzamento sincero delle istituzioni, degli amministratori e dei cittadini\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ferentino ha ospitato oggi, in occasione della ricorrenza di S. Sebastiano, la Festa provinciale della Polizia locale. Una cerimonia solenne alla quale hanno partecipato il Prefetto di Frosinone Emilia Zarrilli, [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Ferentino ha ospitato oggi, in occasione della ricorrenza di S. Sebastiano, la Festa provinciale della Polizia locale. Una cerimonia solenne alla quale hanno partecipato il Prefetto di Frosinone Emilia Zarrilli, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-19T12:47:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-19T15:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/01\/Festa-San-Sebastiano-Prov-L.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE\",\"datePublished\":\"2018-01-19T12:47:25+00:00\",\"dateModified\":\"2018-01-19T15:43:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/\"},\"wordCount\":211,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/01\\\/Festa-San-Sebastiano-Prov-L.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/\",\"name\":\"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/01\\\/Festa-San-Sebastiano-Prov-L.jpg\",\"datePublished\":\"2018-01-19T12:47:25+00:00\",\"dateModified\":\"2018-01-19T15:43:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/01\\\/Festa-San-Sebastiano-Prov-L.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/01\\\/Festa-San-Sebastiano-Prov-L.jpg\",\"width\":1067,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/01\\\/19\\\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE - Ferentino","og_description":"Ferentino ha ospitato oggi, in occasione della ricorrenza di S. Sebastiano, la Festa provinciale della Polizia locale. Una cerimonia solenne alla quale hanno partecipato il Prefetto di Frosinone Emilia Zarrilli, [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-01-19T12:47:25+00:00","article_modified_time":"2018-01-19T15:43:05+00:00","og_image":[{"width":1067,"height":800,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/01\/Festa-San-Sebastiano-Prov-L.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE","datePublished":"2018-01-19T12:47:25+00:00","dateModified":"2018-01-19T15:43:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/"},"wordCount":211,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/01\/Festa-San-Sebastiano-Prov-L.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/","url":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/","name":"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/01\/Festa-San-Sebastiano-Prov-L.jpg","datePublished":"2018-01-19T12:47:25+00:00","dateModified":"2018-01-19T15:43:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/01\/Festa-San-Sebastiano-Prov-L.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/01\/Festa-San-Sebastiano-Prov-L.jpg","width":1067,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/01\/19\/ferentino-grande-partecipazione-per-la-festa-provinciale-della-polizia-locale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO, GRANDE PARTECIPAZIONE PER LA FESTA PROVINCIALE DELLA POLIZIA LOCALE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1480"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1480\/revisions"}],"predecessor-version":[{"id":1484,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1480\/revisions\/1484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1481"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}