{"id":1529,"date":"2018-02-12T14:50:54","date_gmt":"2018-02-12T13:50:54","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1529"},"modified":"2018-02-12T14:50:54","modified_gmt":"2018-02-12T13:50:54","slug":"ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/","title":{"rendered":"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO"},"content":{"rendered":"<p>Conti perfettamente in ordine a Ferentino e maggioranza granitica, tanto che il consiglio comunale ha gi\u00e0 approvato oggi, con 12 voti a 3, \u00a0il bilancio 2018, cos\u00ec da permettere alla macchina di governo di essere pienamente funzionante. Anche questo un risultato che la maggioranza del sindaco Pompeo pu\u00f2 giustamente rivendicare con orgoglio. \u201cA met\u00e0 febbraio \u2013 ha spiegato il primo cittadino \u2013 abbiamo gi\u00e0 il bilancio, frutto di una solidit\u00e0 e di una qualit\u00e0 dell\u2019azione amministrativa che va sottolineata. Nei numeri del bilancio c\u2019\u00e8 scritto che possiamo programmare lo sviluppo e il futuro della citt\u00e0, garantire servizi importanti e soprattutto mantenere invariata la pressione fiscale, anzi abbassiamo costantemente le tasse, venendo incontro alle esigenze di coloro che vivono situazioni di disagio\u201d.<\/p>\n<p>Scendono le tasse<\/p>\n<p>Per il 2018 l\u2019Amministrazione Pompeo riduce ancora la Tosap, meno 10%. Un provvedimento che si affianca a quello del 2017, dunque meno 20% in due anni. Questo per favorire le attivit\u00e0 commerciali e le attivit\u00e0 edilizie. Lieve flessione anche per la tassa sui rifiuti. Confermati gli incentivi per l\u2019apertura di nuovi esercizi commerciali, in particolare nel centro storico: tre mila euro di sconto sulle imposte comunali per coloro che avviano un\u2019attivit\u00e0 o che l\u2019hanno avviata da un massimo di sei mesi. Il settore commercio potr\u00e0 beneficiare anche delle opportunit\u00e0 del progetto Reti d\u2019impresa. Conferma di tutti i servizi a domanda.<\/p>\n<p>Conferma del servizio civico per coloro che sono senza lavoro<\/p>\n<p>E\u2019 stata una delle grandi intuizioni del sindaco Pompeo e della sua maggioranza: quella di mettere a disposizione delle persone prive di occupazione la possibilit\u00e0 di essere impiegate in lavori di pubblica utilit\u00e0, assicurando dignit\u00e0 agli interessati dal progetto e un beneficio alla collettivit\u00e0.<\/p>\n<p>Incentivi per lo smaltimento amianto<\/p>\n<p>Conferma anche degli incentivi per i lavori di smaltimento del cemento-amianto. Si tratta di interventi indispensabili per la tutela della salute e per sorvegliare il corretto smaltimento dei rifiuti pericolosi.<\/p>\n<p>Borse di studio \u201cIl Meritevole\u201d<\/p>\n<p>Una delle iniziative pi\u00f9 apprezzate dell\u2019Amministrazione Pompeo, che ha istituito le borse di studio per premiare l\u2019impegno dei ragazzi e quello delle famiglie, valorizzando il ruolo della scuola e confermando la continua collaborazione che caratterizza il rapporto tra Comune e Istituzioni scolastiche.<\/p>\n<p>Consueta attenzione per i servizi sociali e la cultura<\/p>\n<p>Particolare attenzione alle famiglie, ai giovani, agli anziani, a coloro che vivono situazioni di disagio e di difficolt\u00e0. In pi\u00f9, spazio alla cultura e per i numerosi eventi che Ferentino ospita nel corso dell\u2019anno: tutti confermati. Oltre a sorprese dell\u2019ultima ora come il concerto di Cristina D\u2019Avena<\/p>\n<p>&#8211; Manutenzione, lavori pubblici e decoro urbano:<\/p>\n<p>Anche per il 2018, il settore della manutenzione, lavori pubblici e decoro urbano sar\u00e0 parte importante della programmazione delle attivit\u00e0 dell\u2019Amministrazione comunale di Ferentino, al fine di continuare il processo di crescita e ammodernamento della citt\u00e0.<\/p>\n<p>Obiettivi 2018:<\/p>\n<p>Inaugurazione stazione ferroviaria dopo i lavori di restyling; completamento scuola Simone Cola e dell\u2019Itis, Villa Gasbarra, Cimitero, Rotatoria Pontegrande, parcheggio casello Autostradale, Rotatoria Pontegrande, parcheggio casa della salute, Videosorveglianza, parcheggio Consolare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conti perfettamente in ordine a Ferentino e maggioranza granitica, tanto che il consiglio comunale ha gi\u00e0 approvato oggi, con 12 voti a 3, \u00a0il bilancio 2018, cos\u00ec da permettere alla [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Conti perfettamente in ordine a Ferentino e maggioranza granitica, tanto che il consiglio comunale ha gi\u00e0 approvato oggi, con 12 voti a 3, \u00a0il bilancio 2018, cos\u00ec da permettere alla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-12T13:50:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO\",\"datePublished\":\"2018-02-12T13:50:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/\"},\"wordCount\":530,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/08\\\/comune.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/\",\"name\":\"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/08\\\/comune.jpg\",\"datePublished\":\"2018-02-12T13:50:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/08\\\/comune.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/08\\\/comune.jpg\",\"width\":550,\"height\":412},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/02\\\/12\\\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO - Ferentino","og_description":"Conti perfettamente in ordine a Ferentino e maggioranza granitica, tanto che il consiglio comunale ha gi\u00e0 approvato oggi, con 12 voti a 3, \u00a0il bilancio 2018, cos\u00ec da permettere alla [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-02-12T13:50:54+00:00","og_image":[{"width":550,"height":412,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO","datePublished":"2018-02-12T13:50:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/"},"wordCount":530,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/","url":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/","name":"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","datePublished":"2018-02-12T13:50:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","width":550,"height":412},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/02\/12\/ferentino-gia-approvato-il-bilancio-2018-tasse-in-diminuzione-servizi-in-aumento-borse-di-studio-per-i-ragazzi-servizio-civico-per-i-senza-lavoro-incentivi-per-commercio-e-smaltimento-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO, GIA\u2019 APPROVATO IL BILANCIO 2018: TASSE IN DIMINUZIONE, SERVIZI IN AUMENTO. BORSE DI STUDIO PER I RAGAZZI, SERVIZIO CIVICO PER I SENZA LAVORO, INCENTIVI PER COMMERCIO E SMALTIMENTO AMIANTO. MANUTENZIONE E OPERE PUBBLICHE IN PRIMO PIANO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1529"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1529\/revisions"}],"predecessor-version":[{"id":1530,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1529\/revisions\/1530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/874"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}