{"id":1609,"date":"2018-03-19T09:15:11","date_gmt":"2018-03-19T08:15:11","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1609"},"modified":"2018-03-19T16:06:06","modified_gmt":"2018-03-19T15:06:06","slug":"acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/","title":{"rendered":"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone"},"content":{"rendered":"<p>Lavori di manutenzione programmata da effettuarsi sulla rete in Via Casilina: sospensione flusso idrico<\/p>\n<p><strong>GIOVEDI\u2019 22.03.2018 DALLE ORE 8.00 FINO AL PRIMO POMERIGGIO<\/strong><\/p>\n<p><strong>Zone interessate<\/strong>: parte di Via Ponte del Cantoro, Via Casilina Nord, Via Giovina Tofe Morolo, Via Aldo Moro (Zona Pontegrande) Via Casilina, Via Caduti di Via Fani, Via Borgo Belvedere, Via Sant\u2019Agata, Via Ambrogio Pettorini, Largo Don Guanella, parte di Via Stazione, Via dei Mulini, parte di Via Stufa Pigna Castello, zona Via San Nicola, Ponte Chivi San Benedetto, parte di Via della Fornace.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1610\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/03\/ACEA135_22-marzo.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/03\/ACEA135_22-marzo.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ACEA135_22 marzo<\/a><\/li>\n<li><a id=\"wpba_attachment_list_1636\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/03\/acea-22-marzo-2018-aggiornamento.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/03\/acea-22-marzo-2018-aggiornamento.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>acea 22 marzo 2018 aggiornamento<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lavori di manutenzione programmata da effettuarsi sulla rete in Via Casilina: sospensione flusso idrico GIOVEDI\u2019 22.03.2018 DALLE ORE 8.00 FINO AL PRIMO POMERIGGIO Zone interessate: parte di Via Ponte del [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Lavori di manutenzione programmata da effettuarsi sulla rete in Via Casilina: sospensione flusso idrico GIOVEDI\u2019 22.03.2018 DALLE ORE 8.00 FINO AL PRIMO POMERIGGIO Zone interessate: parte di Via Ponte del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-19T08:15:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-19T15:06:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Logo_Acea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"493\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone\",\"datePublished\":\"2018-03-19T08:15:11+00:00\",\"dateModified\":\"2018-03-19T15:06:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/\"},\"wordCount\":94,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/Logo_Acea.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/\",\"name\":\"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/Logo_Acea.jpg\",\"datePublished\":\"2018-03-19T08:15:11+00:00\",\"dateModified\":\"2018-03-19T15:06:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/Logo_Acea.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/Logo_Acea.jpg\",\"width\":493,\"height\":502},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/03\\\/19\\\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/","og_locale":"it_IT","og_type":"article","og_title":"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone - Ferentino","og_description":"Lavori di manutenzione programmata da effettuarsi sulla rete in Via Casilina: sospensione flusso idrico GIOVEDI\u2019 22.03.2018 DALLE ORE 8.00 FINO AL PRIMO POMERIGGIO Zone interessate: parte di Via Ponte del [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-03-19T08:15:11+00:00","article_modified_time":"2018-03-19T15:06:06+00:00","og_image":[{"width":493,"height":502,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Logo_Acea.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone","datePublished":"2018-03-19T08:15:11+00:00","dateModified":"2018-03-19T15:06:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/"},"wordCount":94,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Logo_Acea.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/","url":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/","name":"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Logo_Acea.jpg","datePublished":"2018-03-19T08:15:11+00:00","dateModified":"2018-03-19T15:06:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Logo_Acea.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Logo_Acea.jpg","width":493,"height":502},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/03\/19\/acea-ato-5-preavviso-sospensione-idrica-giovedi-22-03-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"ACEA ATO 5 Preavviso sospensione idrica GIOVEDI\u2019 22.03.2018 aggiornamento zone"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1609"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1609\/revisions"}],"predecessor-version":[{"id":1638,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1609\/revisions\/1638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/368"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}