{"id":1716,"date":"2018-04-20T09:00:22","date_gmt":"2018-04-20T07:00:22","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1716"},"modified":"2018-04-19T11:49:40","modified_gmt":"2018-04-19T09:49:40","slug":"ferentino-festa-della-liberazione-25-aprile-2018","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/","title":{"rendered":"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018"},"content":{"rendered":"<p>25<strong> Aprile 2018 Festa della Liberazione<\/strong> per ricordare la fine della dittatura fascista e della guerra, celebrare la vittoria nel 1945 della <strong>Resistenza<\/strong>: <strong>una giornata per manifestare e rinnovare la comune volont\u00e0 di non dimenticare.<\/strong><\/p>\n<p><strong>Mercoled\u00ec 25 aprile,<\/strong> in Piazza Duomo, il ritrovo di autorit\u00e0, associazioni e cittadini, <strong>alle 19.00 la Santa Messa<\/strong> in suffragio dei caduti e dispersi nelle guerre. <strong>Alle 20.00 nella Cappella-Sacrario, la deposizione di una corona<\/strong> presso le lapidi che elencano le <strong>vittime civili della II Guerra mondiale. <\/strong><\/p>\n<p><strong>Il criptoportico dell\u2019Acropoli<\/strong>, anch\u2019esso rifugio durante la guerra, ospita la <strong>mostra permanente il Valore della Memoria,<\/strong> con le gigantografie sulle devastazioni e rovine della citt\u00e0, immagini di tragici eventi, che videro Ferentino distrutta dai violenti bombardamenti, iniziati il 30 dicembre 1943 fino a tutto il mese di maggio 1944, anno in cui la citt\u00e0 vers\u00f2 il suo maggior tributo di sangue e di distruzione con il 75% degli edifici privati abbattuti e oltre 400 vittime. Per non dimenticare quelle vittime e quegli eroi, Ferentino ha dedicato loro la<strong> Casa del Memoriale, <\/strong>un percorso, ricostruito sulle abitazioni distrutte dalle bombe, a ridosso di porta Sant\u2019Agata, inaugurato il 25 aprile 2003, nello stesso giorno in cui alla citt\u00e0 \u00e8 stata conferita dal Presidente della Repubblica, Carlo Azeglio Ciampi, <strong>la Medaglia d\u2019Oro al Merito Civile<\/strong>. E nella <strong>Casa del Memoriale<\/strong>, sono collocate le lapidi in memoria degli sfollati dai Comuni del Cassinate per sfuggire alla guerra, vittime di un tragico destino.<\/p>\n<p><strong>Il sindaco, Antonio Pompeo<\/strong>: <em>Lo scopo di queste celebrazioni \u00e8 ravvivare e condividere la memoria e i significati di tali ricorrenze, il <strong>25 Aprile,<\/strong> la <strong>Festa della Liberazione e il 2 Giugno, la Festa della Repubblica<\/strong>, esprimere i sentimenti pi\u00f9 alti di osservanza per le Istituzioni repubblicane e di riconoscenza per tutti coloro che per noi le hanno costruite, difendendo la libert\u00e0 e assicurando la democrazia. L\u2019invito \u00e8 rivolto ai concittadini, associazioni, comitati, giovani, studenti, per rendere omaggio ai nostri caduti, affinch\u00e9 il ricordo del loro sacrificio sia d&#8217;esempio\u00a0 e per riaffermare i diritti sanciti dalla nostra Costituzione nella convinzione che i riferimenti alle prospettive di pace e di promozione umana, in essa contenuti, siano il modo pi\u00f9 degno per onorarne la memoria.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1719\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-2018-201x300.jpg\" alt=\"\" width=\"225\" height=\"336\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-2018-201x300.jpg 201w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-2018.jpg 537w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1718\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Cronologia-bombardamenti-43_44-256x300.jpg\" alt=\"\" width=\"286\" height=\"335\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Cronologia-bombardamenti-43_44-256x300.jpg 256w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Cronologia-bombardamenti-43_44-768x900.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Cronologia-bombardamenti-43_44-680x797.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Cronologia-bombardamenti-43_44.jpg 804w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1723\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Criptoportico-Lapidi-caduti-guerre-300x225.jpg\" alt=\"\" width=\"447\" height=\"335\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Criptoportico-Lapidi-caduti-guerre-300x225.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Criptoportico-Lapidi-caduti-guerre-768x576.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Criptoportico-Lapidi-caduti-guerre-680x510.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Criptoportico-Lapidi-caduti-guerre-800x600.jpg 800w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Criptoportico-Lapidi-caduti-guerre.jpg 960w\" sizes=\"auto, (max-width: 447px) 100vw, 447px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1721\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Memoriale-bas-ris-300x225.jpg\" alt=\"\" width=\"405\" height=\"304\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Memoriale-bas-ris-300x225.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Memoriale-bas-ris-768x576.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Memoriale-bas-ris-1024x768.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Memoriale-bas-ris-680x510.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Memoriale-bas-ris.jpg 2048w\" sizes=\"auto, (max-width: 405px) 100vw, 405px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1722\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Monumento-Europa-casa-del-Memoriale-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Monumento-Europa-casa-del-Memoriale-225x300.jpg 225w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/Monumento-Europa-casa-del-Memoriale.jpg 540w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>25 Aprile 2018 Festa della Liberazione per ricordare la fine della dittatura fascista e della guerra, celebrare la vittoria nel 1945 della Resistenza: una giornata per manifestare e rinnovare la [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018 - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018 - Ferentino\" \/>\n<meta property=\"og:description\" content=\"25 Aprile 2018 Festa della Liberazione per ricordare la fine della dittatura fascista e della guerra, celebrare la vittoria nel 1945 della Resistenza: una giornata per manifestare e rinnovare la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-20T07:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-rid.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"233\" \/>\n\t<meta property=\"og:image:height\" content=\"192\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018\",\"datePublished\":\"2018-04-20T07:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/\"},\"wordCount\":356,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/04\\\/25-aprile-rid.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/\",\"name\":\"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018 - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/04\\\/25-aprile-rid.jpg\",\"datePublished\":\"2018-04-20T07:00:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/04\\\/25-aprile-rid.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/04\\\/25-aprile-rid.jpg\",\"width\":233,\"height\":192},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/04\\\/20\\\/ferentino-festa-della-liberazione-25-aprile-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018 - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018 - Ferentino","og_description":"25 Aprile 2018 Festa della Liberazione per ricordare la fine della dittatura fascista e della guerra, celebrare la vittoria nel 1945 della Resistenza: una giornata per manifestare e rinnovare la [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-04-20T07:00:22+00:00","og_image":[{"width":233,"height":192,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-rid.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018","datePublished":"2018-04-20T07:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/"},"wordCount":356,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-rid.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/","url":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/","name":"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018 - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-rid.jpg","datePublished":"2018-04-20T07:00:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-rid.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/04\/25-aprile-rid.jpg","width":233,"height":192},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/04\/20\/ferentino-festa-della-liberazione-25-aprile-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO FESTA DELLA LIBERAZIONE 25 APRILE 2018"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1716"}],"version-history":[{"count":6,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1716\/revisions"}],"predecessor-version":[{"id":1730,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1716\/revisions\/1730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1727"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}