{"id":1821,"date":"2018-06-29T19:00:16","date_gmt":"2018-06-29T17:00:16","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=1821"},"modified":"2018-06-29T19:09:10","modified_gmt":"2018-06-29T17:09:10","slug":"ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/","title":{"rendered":"FERENTINO, UN\u2019ESTATE  CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE"},"content":{"rendered":"<p>Il modello Ferentino \u00e8 anche questo. A circa venti giorni dalla vittoria elettorale di Antonio Pompeo, a dieci dalla nomina della giunta e ad un giorno esatto dal primo consiglio comunale, \u00e8 stato gi\u00e0 presentato oggi il cartellone delle manifestazioni estive.<\/p>\n<p>Ancora una volta la citt\u00e0 del riconfermato primo cittadino di Ferentino dimostra la qualit\u00e0, l\u2019efficacia e la validit\u00e0 della macchina amministrativa.<\/p>\n<p>Sar\u00e0, come al solito, un\u2019estate\u00a0di grandi eventi. Un cartellone di appuntamenti di qualit\u00e0, che spaziano su tutti i generi e per tutti i gusti. Un invito a trascorrere le serate estive nelle piazze e tra i bellissimi monumenti della citt\u00e0, per assistere a spettacoli, concerti, ridere, divertirsi e gustare buon cibo.<\/p>\n<p>Un aspetto da sottolineare, infine: la consueta collaborazione tra l\u2019Amministrazione comunale, la Pro loco e le tante associazioni del territorio, protagoniste degli eventi in programma.<\/p>\n<p>\u201cFerentino\u00a0Estate\u00a02018. Vivi la Citt\u00e0\u201d, \u00e8 lo slogan scelto per il manifesto. Si compone di otto appuntamenti. Si parte il 12, 13, 14 e 15 luglio con Ferentino Acustica. Segue il 19, 20, 21 e 22 luglio, con Fiati in Concerto. C\u2019\u00e8 poi il tradizionale Agosto Ferentinate, durante il quale spiccano: il confermatissimo Grande Cinema in piazza Mazzini, dal 3 al 12, visto il successo della scorsa edizione; il Teatro per ragazzi, dal 21 al 25, che da quest\u2019anno si amplia e diventa Festival, e lo Street Food,\u00a0 25 e 26 agosto. Infine, a settembre, il 21 e il 22 Ferentino Rock Art e conclusione con Ferentino \u00e8, dal 20 al 23 settembre.<\/p>\n<p>A presentare il cartellone degli appuntamenti nella sala consiglio, il sindaco Antonio Pompeo, gli assessori Angelica Schietroma e Andrea Valenti Martinez e diversi rappresentanti delle associazioni.<\/p>\n<p>\u201cVoglio ringraziare tutti coloro che hanno permesso di realizzare questo cartellone di eventi \u2013 ha dichiarato il sindaco Antonio Pompeo \u2013 sono diversi, abbracciano tutti i generi, sono di grande qualit\u00e0 e nascono dal coinvolgimento delle associazioni e dei nostri migliori talenti. Non posso che concludere con lo slogan del cartellone e con l\u2019invito: vivi la citt\u00e0\u201d.<\/p>\n<p>Anche gli altri due esponenti dell\u2019amministrazione, Schietroma e Martinez hanno espresso il loro apprezzamento per il cartellone: \u201cTanti appuntamenti, tante serate all\u2019insegna della qualit\u00e0. E\u2019 stato fatto un lavoro egregio\u201d.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il modello Ferentino \u00e8 anche questo. A circa venti giorni dalla vittoria elettorale di Antonio Pompeo, a dieci dalla nomina della giunta e ad un giorno esatto dal primo consiglio [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Il modello Ferentino \u00e8 anche questo. A circa venti giorni dalla vittoria elettorale di Antonio Pompeo, a dieci dalla nomina della giunta e ad un giorno esatto dal primo consiglio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-29T17:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-29T17:09:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/06\/eventi-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE\",\"datePublished\":\"2018-06-29T17:00:16+00:00\",\"dateModified\":\"2018-06-29T17:09:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/\"},\"wordCount\":359,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/06\\\/eventi-2018.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/\",\"name\":\"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/06\\\/eventi-2018.jpg\",\"datePublished\":\"2018-06-29T17:00:16+00:00\",\"dateModified\":\"2018-06-29T17:09:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/06\\\/eventi-2018.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/06\\\/eventi-2018.jpg\",\"width\":400,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/06\\\/29\\\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE - Ferentino","og_description":"Il modello Ferentino \u00e8 anche questo. A circa venti giorni dalla vittoria elettorale di Antonio Pompeo, a dieci dalla nomina della giunta e ad un giorno esatto dal primo consiglio [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-06-29T17:00:16+00:00","article_modified_time":"2018-06-29T17:09:10+00:00","og_image":[{"width":400,"height":800,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/06\/eventi-2018.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE","datePublished":"2018-06-29T17:00:16+00:00","dateModified":"2018-06-29T17:09:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/"},"wordCount":359,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/06\/eventi-2018.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/","url":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/","name":"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/06\/eventi-2018.jpg","datePublished":"2018-06-29T17:00:16+00:00","dateModified":"2018-06-29T17:09:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/06\/eventi-2018.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/06\/eventi-2018.jpg","width":400,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/06\/29\/ferentino-unestate-con-tanti-eventi-gia-presentato-il-cartellone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO, UN\u2019ESTATE CON TANTI EVENTI. GIA\u2019 PRESENTATO IL CARTELLONE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=1821"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1821\/revisions"}],"predecessor-version":[{"id":1825,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/1821\/revisions\/1825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1822"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=1821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=1821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=1821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}