{"id":191,"date":"2017-02-09T09:50:11","date_gmt":"2017-02-09T08:50:11","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=191"},"modified":"2017-02-09T10:14:38","modified_gmt":"2017-02-09T09:14:38","slug":"eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/","title":{"rendered":"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO &#8211; BIBLIOTECA COMUNALE:  &#8211; Progetto Lettura  Incontri con gli Autori &#8211; Conferenza sugli statuti di Ferentino."},"content":{"rendered":"<p>SCUOLA MEDIA GIORGI-FRACCO: 09 Febbraio &#8211; Il Giorno della memoria e del Ricordo.<\/p>\n<p>Biblioteca Comunale. Nell\u2019ambito del progetto, dedicato agli statuti cittadini, finanziato dalla Regione Lazio al Sistema Documentario e Bibliotecario \u201cValle del Sacco\u201d, si terr\u00e0 il 15 Febbraio una conferenza sugli statuti di Ferentino. Invitiamo tutti gli interessati a partecipare alle ore 10,30 presso la sala Consiliare del Comune,dove verranno proposti interventi di G. Giammaria, V. Crescenzi,\u00a0 M. Di Cosmo e F. Prontri, che illustreranno gli antichi Statuti Cittadini, curiosit\u00e0 e vicende, legate ai \u00a0documenti. Un modo per conoscere meglio la storia della Citt\u00e0 attraverso gli strumenti che ne hanno regolato la vita sociale e amministrativa.<\/p>\n<p>PROGETTO LETTURA BIBLIOTECA COMUNALE FERENTINO, ASSESSORATO Pubblica Istruzione. Il progetto anche per l\u2019anno scolastico 2016\/2017, \u00a0prevede incontri con autori rivolti alle scuola primarie e secondarie della Citta. Grazie alla collaborazione con l\u2019Assessorato alla Pubblica Istruzione, la Biblioteca Comunale, \u00e8 riuscita ad organizzare tale attivit\u00e0. Il 13\u00a0 ed il 14 Febbraio i bambini delle Scuola primarie incontreranno Stefano Bordiglioni, noto autore per ragazzi con numerosissimi titoli pubblicati per le maggiori case editrici, autore anche di canzoni e programmi televisivi. Il 13 ed il 14 Febbraio, alle 16,30 nel salone di rappresentanza del Palazzo Martino Filetico, i bambini\u00a0 incontreranno l\u2019autore, un invito a tutti a partecipare.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_192\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/MEMORIA-2017-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/MEMORIA-2017-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>memoria-2017-1<\/a><\/li>\n<li><a id=\"wpba_attachment_list_196\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/bIBLIOTECA-EVENTI-febbraio-2017.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/bIBLIOTECA-EVENTI-febbraio-2017.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>biblioteca-eventi-febbraio-2017<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SCUOLA MEDIA GIORGI-FRACCO: 09 Febbraio &#8211; Il Giorno della memoria e del Ricordo. Biblioteca Comunale. Nell\u2019ambito del progetto, dedicato agli statuti cittadini, finanziato dalla Regione Lazio al Sistema Documentario e [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":102,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO - BIBLIOTECA COMUNALE: - Progetto Lettura Incontri con gli Autori - Conferenza sugli statuti di Ferentino. - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO - BIBLIOTECA COMUNALE: - Progetto Lettura Incontri con gli Autori - Conferenza sugli statuti di Ferentino. - Ferentino\" \/>\n<meta property=\"og:description\" content=\"SCUOLA MEDIA GIORGI-FRACCO: 09 Febbraio &#8211; Il Giorno della memoria e del Ricordo. Biblioteca Comunale. Nell\u2019ambito del progetto, dedicato agli statuti cittadini, finanziato dalla Regione Lazio al Sistema Documentario e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-09T08:50:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-09T09:14:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/r_mazzini_7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"827\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO &#8211; BIBLIOTECA COMUNALE: &#8211; Progetto Lettura Incontri con gli Autori &#8211; Conferenza sugli statuti di Ferentino.\",\"datePublished\":\"2017-02-09T08:50:11+00:00\",\"dateModified\":\"2017-02-09T09:14:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/\"},\"wordCount\":231,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/r_mazzini_7.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/\",\"name\":\"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO - BIBLIOTECA COMUNALE: - Progetto Lettura Incontri con gli Autori - Conferenza sugli statuti di Ferentino. - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/r_mazzini_7.jpg\",\"datePublished\":\"2017-02-09T08:50:11+00:00\",\"dateModified\":\"2017-02-09T09:14:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/r_mazzini_7.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/r_mazzini_7.jpg\",\"width\":620,\"height\":827},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/09\\\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO &#8211; BIBLIOTECA COMUNALE: &#8211; Progetto Lettura Incontri con gli Autori &#8211; Conferenza sugli statuti di Ferentino.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO - BIBLIOTECA COMUNALE: - Progetto Lettura Incontri con gli Autori - Conferenza sugli statuti di Ferentino. - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/","og_locale":"it_IT","og_type":"article","og_title":"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO - BIBLIOTECA COMUNALE: - Progetto Lettura Incontri con gli Autori - Conferenza sugli statuti di Ferentino. - Ferentino","og_description":"SCUOLA MEDIA GIORGI-FRACCO: 09 Febbraio &#8211; Il Giorno della memoria e del Ricordo. Biblioteca Comunale. Nell\u2019ambito del progetto, dedicato agli statuti cittadini, finanziato dalla Regione Lazio al Sistema Documentario e [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-02-09T08:50:11+00:00","article_modified_time":"2017-02-09T09:14:38+00:00","og_image":[{"width":620,"height":827,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/r_mazzini_7.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO &#8211; BIBLIOTECA COMUNALE: &#8211; Progetto Lettura Incontri con gli Autori &#8211; Conferenza sugli statuti di Ferentino.","datePublished":"2017-02-09T08:50:11+00:00","dateModified":"2017-02-09T09:14:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/"},"wordCount":231,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/r_mazzini_7.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/","name":"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO - BIBLIOTECA COMUNALE: - Progetto Lettura Incontri con gli Autori - Conferenza sugli statuti di Ferentino. - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/r_mazzini_7.jpg","datePublished":"2017-02-09T08:50:11+00:00","dateModified":"2017-02-09T09:14:38+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/r_mazzini_7.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/r_mazzini_7.jpg","width":620,"height":827},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/09\/eventi-culturali-il-giorno-della-memoria-e-del-ricordo-biblioteca-comunale-progetto-lettura-incontri-con-gli-autori-conferenza-sugli-statuti-di-ferentino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Eventi Culturali: IL GIORNO DELLA MEMORIA E DEL RICORDO &#8211; BIBLIOTECA COMUNALE: &#8211; Progetto Lettura Incontri con gli Autori &#8211; Conferenza sugli statuti di Ferentino."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=191"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/191\/revisions"}],"predecessor-version":[{"id":195,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/191\/revisions\/195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/102"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}