{"id":2065,"date":"2018-08-18T09:30:43","date_gmt":"2018-08-18T07:30:43","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=2065"},"modified":"2018-08-18T10:08:29","modified_gmt":"2018-08-18T08:08:29","slug":"2065","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/","title":{"rendered":"&#8220;Ferentino in Fiaba  Festival del Teatro ragazzi e del Teatro fantasy&#8221;  dal 21 al 25 agosto 2018         &#8211;                                                             &#8220;Bambini in Citt\u00e0 2^ Edizione&#8221; &#8211;  dal 21 al 24 agosto 2018"},"content":{"rendered":"<p style=\"text-align: left\"><!--more--><strong>Il Sindaco Antonio Pompeo<\/strong>: \u201cLa rassegna, che giunge quest&#8217;anno alla sua decima edizione, ha riscosso sin da subito un ottimo successo di pubblico. Nel corso delle dieci stagioni sono state rappresentate oltre cinquanta favole, raccolte tra la tradizione popolare italiana e tra le pi\u00f9 famose fiabe o racconti conosciuti in tutto il mondo, <strong>con l\u2019obbiettivo di realizzare, non solo un intervento di divertente intrattenimento, ma anche di avvicinamento al libro, e quindi alla lettura o narrazione.<\/strong><strong> Si \u00e8 voluto creare un momento che metta insieme: educazione all\u2019ascolto, scoperta del valore che le fiabe hanno sempre avuto, e divertimento.<\/strong><br \/>\nOgni spettacolo \u00e8 concepito con struttura di racconto. Il Narratore presenta situazioni e personaggi che si animano attraverso l\u2019interpretazione degli attori, e coinvolgono direttamente i bambini all\u2019interno dell\u2019azione teatrale. Fatto che ha sempre suscitato molto interesse e divertimento per bimbi e genitori.<br \/>\nAncora una volta la direzione artistica della rassegna \u00e8 affidata a <strong>Zenone Benedetto, referente della compagnia teatrale I Guardiani dell\u2019Oca<\/strong> il quale sottolinea l&#8217;importanza delle fiabe.<br \/>\n\u201cLa fiaba, la favola, mentre intrattiene il bambino, gli permette di conoscersi e favorisce lo sviluppo della sua personalit\u00e0, arricchendo l\u2019esistenza del bambino in tanti modi diversi. Il piacere che proviamo quando ci lasciamo coinvolgere da una fiaba, l\u2019incanto che avvertiamo, proviene non dal significato psicologico di una storia (bench\u00e9 anch\u2019esso abbia il suo peso) ma dalle sue qualit\u00e0 letterarie: dalla fiaba come opera d\u2019arte. <strong>La fiaba non potrebbe esercitare il suo impatto psicologico sul bambino se non fosse in primo luogo e soprattutto un\u2019opera d\u2019arte\u201d.<\/strong><br \/>\nDiverse saranno le compagnie teatrali che si avvicenderanno sul palco di Piazza Mazzini, tutte al pari meritevoli di apprezzamento ed ampiamente conosciute su tutto il territorio nazionale.<\/p>\n<p style=\"text-align: left\"><strong>Gli assessori alla Cultura, Angelica Schietroma, e alla Pubblica Istruzione, Evelina Di Marco<\/strong> sottolineano le motivazioni e le finalit\u00e0 dell\u2019iniziativa che intende promuovere: occasioni culturali fruibili dall&#8217;intera cittadinanza, nel sensibilizzare i ragazzi all&#8217;ascolto dei racconti e alla lettura delle fiabe; stimolare la creativit\u00e0 e la fantasia, incentivare attraverso il Progetto\/Rassegna, la crescita artistica delle compagnie teatrali dedite al teatro ragazzi- teatro di figura. Inoltre, promuovere in termini culturali e turistici l&#8217;immagine del territorio comunale e incrementare le attivit\u00e0 di spettacolo sotto il punto di vista dell&#8217;offerta culturale.<\/p>\n<p><strong>ARTICOLAZIONE DEL PROGETTO.<\/strong> Questa edizione prevede un giorno in pi\u00f9 di programmazione. Alla normale proposta di N\u00b04 spettacoli su palco (Piazza Mazzini), si aggiunger\u00e0 una giornata interamente dedicata al teatro di strada, con trampolieri, giocolieri, musici e attori che allieteranno il pubblico, a partire d<strong>alle 18,00 del giorno 24 agosto<\/strong>, lungo le vie del centro e presso il parco pubblico Orto del Vescovo, <strong>doppio appuntamento<\/strong> che si replicher\u00e0 anche <strong>sabato 25 agosto<\/strong>.<br \/>\nOltre a gli spettacoli teatrali, in Piazza Matteotti, l&#8217;animazione per i pi\u00f9 piccoli prosegue con l\u2019iniziativa <strong>BAMBINI IN CITTA\u2019 giunta alla sua 2^ edizione, dopo i grandi consensi raccolti la scorsa estate: previsti caccia al tesoro, cantastorie, giochi popolari, baby dance, il clown Skarabokkio, grazie al supporto delle Associazioni Il Gabbiano e le Stenghe.<\/strong><\/p>\n<p>La rassegna Ferentino in Fiaba si articola in 5 giorni di programmazione e 7 spettacoli, protagoniste compagnie teatrali professionali di rilevanza nazionale, nei giorni 21- 22 &#8211; 23 &#8211; 24 e 25 Agosto.<\/p>\n<p><strong>CARTELLONE GENERALE &#8211;<\/strong> Titoli e compagnie selezionate<\/p>\n<p><strong>Marted\u00ec 21 ore 21,15<\/strong> &#8211; Piazza Mazzini &#8211; <strong>La bella e la bestia<\/strong> &#8211; Teatro Blu, Varese<br \/>\nSpettacolo con attori e figure<\/p>\n<p><strong>Mercoled\u00ec 22 ore 21,15<\/strong> &#8211; Piazza Mazzini &#8211; <strong>Moby Dick<\/strong> &#8211; I Guardiani dell\u2019oca, Chieti<br \/>\nSpettacolo con attori e pupazzi<\/p>\n<p><strong>Gioved\u00ec 23 ore 21,15<\/strong> &#8211; Piazza Mazzini &#8211; <strong>Peter Pan<\/strong> &#8211; Mulino D\u2019arte, Altamura<br \/>\nSpettacolo con attori e figure<\/p>\n<p><strong>Venerd\u00ec 24 ore 18.00<\/strong> Orto del Vescovo <strong>Passeggiando tra le fiabe<\/strong> &#8211; La mansarda, Caserta<br \/>\nSpettacolo itinerante con attori e maschere<\/p>\n<p><strong>Venerd\u00ec 24 ore 21.15<\/strong> &#8211; Piazza Mazzini &#8211; <strong>Virtus e Luxsuria<\/strong> &#8211; Compagnia teatro del Ramino<br \/>\nSpettacolo con trampoli e fuochi<\/p>\n<p><strong>Sabato 25 ore 18.00<\/strong> &#8211; Orto del Vescovo &#8211; <strong>La formica e la cicala<\/strong> &#8211; Teatro Eidos, Benevento<br \/>\nSpettacolo con attori e Maschere<\/p>\n<p><strong>Sabato 25 ore 21,15<\/strong> &#8211; Piazza Mazzini &#8211; <strong>Il Gatto con gli stivali<\/strong> &#8211; Teatro Verde, Roma<br \/>\nSpettacolo musicale con attori e figure<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PROGRAMMAZIONE RASSEGNA\u00a0 <em>&#8220;BAMBINI IN CITTA\u2019 2^ EDIZIONE&#8221;<\/em><\/strong><em><strong>\u00a0 &#8211;\u00a0<\/strong><\/em><strong>\u00a021 al 24 agosto ore 22.30\u00a0 Piazza Matteotti<\/strong><\/p>\n<p><strong>Marted\u00ec 21 agosto ore 22.30: \u201cUna Piazza piena di storie\u201d, <\/strong>fiabe e canzoni per piccoli e grandi a cura di <strong>Cataldo Nalli\u00a0<\/strong><\/p>\n<p>A seguire\u00a0 BabyDance\u00a0 \u00a0&#8211;\u00a0 \u00a0Intrattenimento musicale\u00a0 a cura di\u00a0 <em>Andrea Festone<\/em><\/p>\n<p><strong>\u00a0Mercoled\u00ec\u00a0<\/strong><strong>22 agosto ore 22.30 : \u201cTreasureLand, storia di un tesoro!\u201d <\/strong>caccia al tesoro notturna a cura dell\u2019Associazione Culturale<strong> Le StreNghe<\/strong><\/p>\n<p>A seguire Babydance\u00a0 \u00a0&#8211;\u00a0 Intrattenimento musicale\u00a0 a cura di\u00a0\u00a0<em>Andrea Festone<\/em><\/p>\n<p><strong>Gioved\u00ec 23 agosto ore 22.30 : \u201cMettiamoci in gioco\u201d, giochi popolari e di strada <\/strong>a cura dell\u2019Associazione di Animatori<strong> Il Gabbiano &amp; Skarabokkio<\/strong><\/p>\n<p>Intrattenimento musicale\u00a0 a cura di\u00a0\u00a0<em>Andrea Festone<\/em><\/p>\n<p><strong>24 agosto<\/strong> <strong>ore 22.30 : Skarabokkio Show \u2013 Spettacolo di Magia<\/strong><\/p>\n<p>Intrattenimento musicale\u00a0 a cura di\u00a0\u00a0<em>Andrea Festone<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2051\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/La-Bella-e-la-Bestia-locandina-21-08-230x300.jpg\" alt=\"\" width=\"248\" height=\"323\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/La-Bella-e-la-Bestia-locandina-21-08-230x300.jpg 230w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/La-Bella-e-la-Bestia-locandina-21-08-768x1001.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/La-Bella-e-la-Bestia-locandina-21-08-680x886.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/La-Bella-e-la-Bestia-locandina-21-08.jpg 785w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/>\u00a0 \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2053\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Moby-Dick-locandina-22-08-200x300.jpg\" alt=\"\" width=\"255\" height=\"383\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Moby-Dick-locandina-22-08-200x300.jpg 200w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Moby-Dick-locandina-22-08-768x1152.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Moby-Dick-locandina-22-08-682x1024.jpg 682w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Moby-Dick-locandina-22-08-680x1020.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Moby-Dick-locandina-22-08.jpg 799w\" sizes=\"auto, (max-width: 255px) 100vw, 255px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2055\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Peter-Pan-locandina-23-08-300x117.jpg\" alt=\"\" width=\"323\" height=\"126\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Peter-Pan-locandina-23-08-300x117.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Peter-Pan-locandina-23-08-768x299.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Peter-Pan-locandina-23-08-1024x399.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Peter-Pan-locandina-23-08-680x265.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Peter-Pan-locandina-23-08-800x312.jpg 800w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Peter-Pan-locandina-23-08.jpg 1207w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/>\u00a0 \u00a0<img decoding=\"async\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Passeggiando-tra-le-fiabe-locandina-24-08-orto-del-vescovo-ore-18-247x300.jpg\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2058\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/virtus-e-luxsuria-locandina-24-08-ore-21.15-221x300.jpg\" alt=\"\" width=\"261\" height=\"354\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/virtus-e-luxsuria-locandina-24-08-ore-21.15-221x300.jpg 221w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/virtus-e-luxsuria-locandina-24-08-ore-21.15.jpg 656w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2071\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200955_WhatsApp-257x300.jpg\" alt=\"\" width=\"276\" height=\"322\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200955_WhatsApp-257x300.jpg 257w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200955_WhatsApp-680x794.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200955_WhatsApp.jpg 685w\" sizes=\"auto, (max-width: 276px) 100vw, 276px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2072\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200916_WhatsApp-300x211.jpg\" alt=\"\" width=\"344\" height=\"242\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200916_WhatsApp-300x211.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200916_WhatsApp-768x540.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200916_WhatsApp-1024x720.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200916_WhatsApp-680x478.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200916_WhatsApp-800x563.jpg 800w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180811-200916_WhatsApp.jpg 1031w\" sizes=\"auto, (max-width: 344px) 100vw, 344px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":223,"featured_media":2016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy&quot; dal 21 al 25 agosto 2018     -                               &quot;Bambini in Citt\u00e0 2^ Edizione&quot; - dal 21 al 24 agosto 2018 - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy&quot; dal 21 al 25 agosto 2018     -                               &quot;Bambini in Citt\u00e0 2^ Edizione&quot; - dal 21 al 24 agosto 2018 - Ferentino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-18T07:30:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-18T08:08:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180728-132639_Drive.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"&#8220;Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy&#8221; dal 21 al 25 agosto 2018 &#8211; &#8220;Bambini in Citt\u00e0 2^ Edizione&#8221; &#8211; dal 21 al 24 agosto 2018\",\"datePublished\":\"2018-08-18T07:30:43+00:00\",\"dateModified\":\"2018-08-18T08:08:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/\"},\"wordCount\":816,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/08\\\/Screenshot_20180728-132639_Drive.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/\",\"name\":\"\\\"Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy\\\" dal 21 al 25 agosto 2018 - \\\"Bambini in Citt\u00e0 2^ Edizione\\\" - dal 21 al 24 agosto 2018 - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/08\\\/Screenshot_20180728-132639_Drive.jpg\",\"datePublished\":\"2018-08-18T07:30:43+00:00\",\"dateModified\":\"2018-08-18T08:08:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/08\\\/Screenshot_20180728-132639_Drive.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/08\\\/Screenshot_20180728-132639_Drive.jpg\",\"width\":560,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/08\\\/18\\\/2065\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy&#8221; dal 21 al 25 agosto 2018 &#8211; &#8220;Bambini in Citt\u00e0 2^ Edizione&#8221; &#8211; dal 21 al 24 agosto 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy\" dal 21 al 25 agosto 2018     -                               \"Bambini in Citt\u00e0 2^ Edizione\" - dal 21 al 24 agosto 2018 - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/","og_locale":"it_IT","og_type":"article","og_title":"\"Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy\" dal 21 al 25 agosto 2018     -                               \"Bambini in Citt\u00e0 2^ Edizione\" - dal 21 al 24 agosto 2018 - Ferentino","og_url":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-08-18T07:30:43+00:00","article_modified_time":"2018-08-18T08:08:29+00:00","og_image":[{"width":560,"height":800,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180728-132639_Drive.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"&#8220;Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy&#8221; dal 21 al 25 agosto 2018 &#8211; &#8220;Bambini in Citt\u00e0 2^ Edizione&#8221; &#8211; dal 21 al 24 agosto 2018","datePublished":"2018-08-18T07:30:43+00:00","dateModified":"2018-08-18T08:08:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/"},"wordCount":816,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180728-132639_Drive.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/","url":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/","name":"\"Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy\" dal 21 al 25 agosto 2018 - \"Bambini in Citt\u00e0 2^ Edizione\" - dal 21 al 24 agosto 2018 - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180728-132639_Drive.jpg","datePublished":"2018-08-18T07:30:43+00:00","dateModified":"2018-08-18T08:08:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180728-132639_Drive.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/08\/Screenshot_20180728-132639_Drive.jpg","width":560,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/08\/18\/2065\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"&#8220;Ferentino in Fiaba Festival del Teatro ragazzi e del Teatro fantasy&#8221; dal 21 al 25 agosto 2018 &#8211; &#8220;Bambini in Citt\u00e0 2^ Edizione&#8221; &#8211; dal 21 al 24 agosto 2018"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=2065"}],"version-history":[{"count":16,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2065\/revisions"}],"predecessor-version":[{"id":2067,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2065\/revisions\/2067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/2016"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=2065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=2065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=2065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}