{"id":2296,"date":"2018-10-19T09:08:09","date_gmt":"2018-10-19T07:08:09","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=2296"},"modified":"2018-10-19T09:08:09","modified_gmt":"2018-10-19T07:08:09","slug":"ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/","title":{"rendered":"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA"},"content":{"rendered":"<p class=\"yiv7538539027MsoNormal\">Priorit\u00e0 all\u2019ambiente e azione diretta e incisiva per la salvaguardia del territorio da parte del Comune di Ferentino. Il Sindaco Antonio Pompeo, in questi giorni, ha indirizzato una nota ufficiale al Ministero dell\u2019Ambiente per richiedere l\u2019erogazione dei fondi necessari alla bonifica del sito della ex Cartiera.<\/p>\n<p class=\"yiv7538539027MsoNormal\">La Cartiera di Ferentino gi\u00e0 a novembre dello scorso anno era stata inserita tra gli otto interventi di bonifica della Valle del Sacco subito finanziabili da parte del Ministero. Un grande risultato, va ricordato, ottenuto grazie all\u2019efficace e preventiva azione messa in campo dal Comune di Ferentino, in collaborazione con l\u2019associazione Civis, che ha attivato tutte le procedure necessarie fra cui l\u2019azione in danno del responsabile della contaminazione.<\/p>\n<p class=\"yiv7538539027MsoNormal\">Ad oggi, purtroppo, nonostante la velocit\u00e0 del Comune nel predisporre la pratica e l\u2019ok ministeriale, i fondi ancora non sono arrivati e l\u2019Amministrazione comunale, attraverso il sindaco Pompeo, ha deciso di sollecitare direttamente il Ministro Costa e la struttura responsabile, in particolare chiedendo la stipula dell\u2019Accordo di Programma necessario a sbloccare le risorse.<\/p>\n<p class=\"yiv7538539027MsoNormal\">\u201cC\u2019\u00e8 bisogno di scongiurare ulteriori ritardi \u2013 spiega il primo cittadino di Ferentino, insieme all\u2019assessore all\u2019ambiente Evelina Di Marco \u2013 per questo abbiamo voluto interessare direttamente il Ministero dell\u2019Ambiente. Le risorse ci sono, sono state stanziate e ora occorre renderle disponibili. Al Ministero abbiamo rappresentato la situazione di criticit\u00e0 ambientale del sito della Cartiera che necessit\u00e0 di un intervento urgente per la bonifica in primo luogo e successivamente per il recupero e il riutilizzo per fini pubblici del complesso industriale dismesso, sia per tutelare la salute dei cittadini, sia per dimostrare come una criticit\u00e0, se affrontata con responsabilit\u00e0 e impegno, pu\u00f2 diventare un\u2019opportunit\u00e0. Non \u00e8 giusto che, nonostante l\u2019impegno che ci abbiamo messo nel seguire l\u2019intero iter, nel preparare la documentazione, nel farla approvare, sia passato un anno quasi e ancora non abbiamo risposte. E\u2019 necessario che l\u2019Accordo di programma venga firmato nel pi\u00f9 breve tempo possibile\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Priorit\u00e0 all\u2019ambiente e azione diretta e incisiva per la salvaguardia del territorio da parte del Comune di Ferentino. Il Sindaco Antonio Pompeo, in questi giorni, ha indirizzato una nota ufficiale [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Priorit\u00e0 all\u2019ambiente e azione diretta e incisiva per la salvaguardia del territorio da parte del Comune di Ferentino. Il Sindaco Antonio Pompeo, in questi giorni, ha indirizzato una nota ufficiale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-19T07:08:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA\",\"datePublished\":\"2018-10-19T07:08:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/\"},\"wordCount\":346,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/08\\\/comune.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/\",\"name\":\"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/08\\\/comune.jpg\",\"datePublished\":\"2018-10-19T07:08:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/08\\\/comune.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/08\\\/comune.jpg\",\"width\":550,\"height\":412},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/10\\\/19\\\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA - Ferentino","og_description":"Priorit\u00e0 all\u2019ambiente e azione diretta e incisiva per la salvaguardia del territorio da parte del Comune di Ferentino. Il Sindaco Antonio Pompeo, in questi giorni, ha indirizzato una nota ufficiale [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-10-19T07:08:09+00:00","og_image":[{"width":550,"height":412,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA","datePublished":"2018-10-19T07:08:09+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/"},"wordCount":346,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/","url":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/","name":"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","datePublished":"2018-10-19T07:08:09+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/comune.jpg","width":550,"height":412},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/10\/19\/ferentino-attenzione-allambiente-il-sindaco-pompeo-chiede-al-ministero-lo-sblocco-dei-fondi-per-la-bonifica-della-cartiera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO, ATTENZIONE ALL\u2019AMBIENTE: IL SINDACO POMPEO CHIEDE AL MINISTERO LO SBLOCCO DEI FONDI PER LA BONIFICA DELLA CARTIERA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=2296"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2296\/revisions"}],"predecessor-version":[{"id":2297,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2296\/revisions\/2297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/874"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=2296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=2296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=2296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}