{"id":233,"date":"2017-02-18T15:27:02","date_gmt":"2017-02-18T14:27:02","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=233"},"modified":"2017-02-18T15:27:02","modified_gmt":"2017-02-18T14:27:02","slug":"ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/","title":{"rendered":"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA&#8217;\u201d"},"content":{"rendered":"<p>\u201cCondanna forte, senza se e senza ma, per i diversi episodi di mancanza di rispetto e di incivilt\u00e0 nei riguardi del nostro ambiente: dall\u2019abbandono di rifiuti, a tutte le altre infrazioni che sono state registrate in quest\u2019ultimo periodo. Massimo impegno, insieme alle forze dell\u2019ordine con le quali la collaborazione e la condivisione \u00e8 quotidiana su questo tema, per sanzionare chi non rispetta il territorio e mettere la parola fine ad un andazzo non pi\u00f9 tollerabile\u201d.<\/p>\n<p>E\u2019 quanto afferma il sindaco di Ferentino Antonio Pompeo, che aggiunge: \u201cCome Amministrazione comunale e come cittadino ritengo inconcepibile che si possano continuare a registrare fenomeni come quello delle discariche abusive lungo le strade di periferia; scarichi non autorizzati; scempio di un patrimonio ambientale come quello della Valle del Sacco. Per questo non intendiamo assolutamente abbassare la guardia, anzi rafforzeremo, insieme alle Forze dell\u2019ordine, l\u2019azione di controllo del territorio per punire chi trasgredisce le regole\u201d.<\/p>\n<p>\u201cIl Comune gi\u00e0 si \u00e8 attivato in tal senso attraverso la Polizia locale e diverse sono state le sanzioni inflitte ai trasgressori. Potenzieremo ancor di pi\u00f9 questa azione, a cui abbiamo affiancato il lavoro in sinergia con alcune associazioni e realt\u00e0 di volontariato sull\u2019importanza dei valori della tutela ambientale\u201d.<\/p>\n<p>\u201cL\u2019ambiente, infatti, \u00e8 lo spazio fisico in cui ciascuno di noi vive e in cui vivono i nostri figli, per cui deve essere un impegno comune quello di preservarlo, un valore nei confronti del quale tutti devono remare dalla stessa parte. Le Istituzioni, ma anche i privai cittadini\u201d.<\/p>\n<p>\u201cDa parte dell\u2019Amministrazione di Ferentino l\u2019attenzione sul tema \u00e8 massima \u2013 ha aggiunto il sindaco \u2013 lo dimostrano l\u2019avvio del servizio di raccolta differenziata, il cui ottimo funzionamento ha permesso di abbassare anche l\u2019imposta sui rifiuti. Lo dimostrano gli incentivi, confermati anche nel bilancio 2017, per lo smaltimento dell\u2019amianto, oppure lo sportello Sin attivato per supportare i cittadini nelle pratiche a seguito della riperimetrazione del bacino della Valle del Sacco\u201d.<\/p>\n<p>\u201cLe politiche di tutela ambientale \u2013 ha concluso il sindaco Pompeo \u2013 possono funzionare per\u00f2, solamente con il contributo da parte di tutti, come stanno a dimostrare le domeniche ecologiche e i provvedimenti sul traffico, recepiti in maniera ottimale dalla cittadinanza: \u00e8 questo il modello che occorre replicare. Senza tralasciare naturalmente, anzi potenziando ulteriormente l\u2019azione di controllo del territorio e la repressione di comportamenti dolosi, affinch\u00e9 non si verifichino pi\u00f9. Nei prossimi giorni, infine, l\u2019Amministrazione comunale ufficializzer\u00e0 ulteriori provvedimenti proprio a tutela e salvaguardia del nostro ambiente\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCondanna forte, senza se e senza ma, per i diversi episodi di mancanza di rispetto e di incivilt\u00e0 nei riguardi del nostro ambiente: dall\u2019abbandono di rifiuti, a tutte le altre [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA&#039;\u201d - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA&#039;\u201d - Ferentino\" \/>\n<meta property=\"og:description\" content=\"\u201cCondanna forte, senza se e senza ma, per i diversi episodi di mancanza di rispetto e di incivilt\u00e0 nei riguardi del nostro ambiente: dall\u2019abbandono di rifiuti, a tutte le altre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-18T14:27:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/comune.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA&#8217;\u201d\",\"datePublished\":\"2017-02-18T14:27:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/\"},\"wordCount\":427,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/comune.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/\",\"name\":\"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA'\u201d - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/comune.jpg\",\"datePublished\":\"2017-02-18T14:27:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/comune.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/02\\\/comune.jpg\",\"width\":550,\"height\":412},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/02\\\/18\\\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA&#8217;\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA'\u201d - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/","og_locale":"it_IT","og_type":"article","og_title":"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA'\u201d - Ferentino","og_description":"\u201cCondanna forte, senza se e senza ma, per i diversi episodi di mancanza di rispetto e di incivilt\u00e0 nei riguardi del nostro ambiente: dall\u2019abbandono di rifiuti, a tutte le altre [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-02-18T14:27:02+00:00","og_image":[{"width":550,"height":412,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/comune.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA&#8217;\u201d","datePublished":"2017-02-18T14:27:02+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/"},"wordCount":427,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/comune.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/","name":"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA'\u201d - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/comune.jpg","datePublished":"2017-02-18T14:27:02+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/comune.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/02\/comune.jpg","width":550,"height":412},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/02\/18\/ambiente-il-sindaco-pompeo-condanna-forte-e-repressione-di-tutti-gli-episodi-di-incivilta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"AMBIENTE, IL SINDACO POMPEO: \u201cCONDANNA FORTE E REPRESSIONE DI TUTTI GLI EPISODI DI INCIVILTA&#8217;\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=233"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/233\/revisions"}],"predecessor-version":[{"id":235,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/233\/revisions\/235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/234"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}