{"id":2457,"date":"2018-12-12T17:00:41","date_gmt":"2018-12-12T16:00:41","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=2457"},"modified":"2018-12-12T13:00:52","modified_gmt":"2018-12-12T12:00:52","slug":"ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/","title":{"rendered":"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT"},"content":{"rendered":"<p style=\"font-weight: 400\">Cresce l\u2019attesa a Ferentino per il tradizionale Concerto di solidariet\u00e0 con il quale la citt\u00e0 si prepara, come ogni anno, alle festivit\u00e0 di Natale.<\/p>\n<p style=\"font-weight: 400\">Sabato prossimo, 15 dicembre, alle ore 19, nella Chiesa Abbaziale di S. Maria Maggiore, si svolger\u00e0 il tradizionale appuntamento con la musica gospel. Ad esibirsi una vera e propria istituzione di questo genere musicale, per la prima volta in Italia: Laura Wilson &amp; Nu&#8217; Movement.<\/p>\n<p style=\"font-weight: 400\">Toni robusti, suono energico, ritmi sonori marcatamente soul made in Usa sono gli elementi che fanno emergere tutta la personalit\u00e0 di Laura Wilson &amp; Nu\u2019 Movement che gioca un ruolo fondamentale nell&#8217;esuberante spinta di veracit\u00e0 live dei suoi concerti. Laura ha pochi eguali nelle escursioni e timbriche vocali ed \u00e8 questa la sua nuova veste sonora, meno rivolta alle regole del gospel romantico \u00e8 pi\u00f9 incline alla\u00a0\u00a0moderna spiritualit\u00e0 che si manifesta con ritmi e ballate, ricche di groove, alzando il livello emotivo con enfasi e destinato a\u00a0\u00a0trasportare il pubblico dentro a ogni canzone.<\/p>\n<p style=\"font-weight: 400\">Tradizione e modernit\u00e0 vanno a braccetto, come negli episodi migliori, ed in questa dimensione, tra gli apporti ritmici e vocali del gruppo, che si assesta uno dei pi\u00f9 corposi live set Gospel a cui si pu\u00f2 assistere. Tentazioni piacevoli e esuberanti, energia vocale, giocano un ruolo fondamentale del gruppo guidato da Laura.<\/p>\n<p style=\"font-weight: 400\">Molte le collaborazioni e le partecipazioni con altre Star del Gospel americano e partner artistica di Travis Greene, vera icona in USA,\u00a0\u00a0Laura Wilson acquisisce un ruolo di primaria presenza sulle scene artistiche del Gospel &amp; Soul in USA.<\/p>\n<p style=\"font-weight: 400\">Per la prima volta in Italia, questa formazione \u00e8 un insieme di musica religiosa tra spirituals tradizionali neri e suoni moderni, opportunamente rivisitati e resi popolari dalla tradizione classica per una messa in opera perfetta, tra precisione e bellezza delle voci, profondit\u00e0 delle canzoni sacre, il tutto collegato al lato pi\u00f9 moderno e contemporaneo del Coro. Il successo \u00e8 immediato e considerevole.<\/p>\n<p style=\"font-weight: 400\">Tutto questo a Ferentino, per un evento di grande qualit\u00e0, che unisce l\u2019aspetto artistico e culturale, con il valore della solidariet\u00e0.<\/p>\n<p style=\"font-weight: 400\"><strong>Il sindaco Antonio Pompeo<\/strong>: \u201cFerentino Gospel \u00e8 un\u2019iniziativa unica in Ciociaria, un punto di riferimento per tutti coloro che amano questo genere musicale, che si svolge nella suggestiva cornice dell\u2019Abbazia gotico-cistercense di Santa Maria Maggiore.\u00a0 L&#8217;evento \u00e8 riuscito negli anni ad offrire al pubblico non solo cittadino il meglio della produzione artistica di alcuni tra i migliori cori Gospel internazionali. Edizione dopo edizione, l\u2019interesse \u00e8 aumentato sia da parte del pubblico sia da parte degli artisti, che hanno definito l\u2019appuntamento uno dei pi\u00f9 interessanti a livello nazionale per la specificit\u00e0 della proposta. Il concerto di Laura Wilson &amp; Nu\u2019 Movement sar\u00e0 presentato dalla madrina della manifestazione Zaira Montico.\u00a0Per il Natale 2018 proponiamo un\u2019artista gi\u00e0 apprezzata a livello internazionale. Sonorit\u00e0 moderne, ritmi coinvolgenti, ballate incantevoli, testi intensi, queste le caratteristiche della solista accompagnata da grandi interpreti del genere. Il Ferentino Gospel \u00e8 un\u2019occasione speciale da non mancare. L\u2019Amministrazione Comunale augura Buon Natale e Felice Anno Nuovo\u201d.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Cresce l\u2019attesa a Ferentino per il tradizionale Concerto di solidariet\u00e0 con il quale la citt\u00e0 si prepara, come ogni anno, alle festivit\u00e0 di Natale. Sabato prossimo, 15 dicembre, alle ore [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":2458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Cresce l\u2019attesa a Ferentino per il tradizionale Concerto di solidariet\u00e0 con il quale la citt\u00e0 si prepara, come ogni anno, alle festivit\u00e0 di Natale. Sabato prossimo, 15 dicembre, alle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-12T16:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/12\/gospel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1486\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT\",\"datePublished\":\"2018-12-12T16:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/\"},\"wordCount\":506,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/12\\\/gospel.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/\",\"name\":\"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/12\\\/gospel.jpg\",\"datePublished\":\"2018-12-12T16:00:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/12\\\/gospel.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2018\\\/12\\\/gospel.jpg\",\"width\":1486,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2018\\\/12\\\/12\\\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT - Ferentino","og_description":"Cresce l\u2019attesa a Ferentino per il tradizionale Concerto di solidariet\u00e0 con il quale la citt\u00e0 si prepara, come ogni anno, alle festivit\u00e0 di Natale. Sabato prossimo, 15 dicembre, alle ore [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-12-12T16:00:41+00:00","og_image":[{"width":1486,"height":1080,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/12\/gospel.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT","datePublished":"2018-12-12T16:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/"},"wordCount":506,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/12\/gospel.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/","url":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/","name":"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/12\/gospel.jpg","datePublished":"2018-12-12T16:00:41+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/12\/gospel.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2018\/12\/gospel.jpg","width":1486,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2018\/12\/12\/ferentino-sabato-15-dicembre-appuntamento-col-concerto-di-gospel-con-laura-wilson-nu-movement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO, SABATO 15 DICEMBRE APPUNTAMENTO COL CONCERTO DI GOSPEL CON LAURA WILSON &amp; NU\u2019 MOVEMENT"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=2457"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2457\/revisions"}],"predecessor-version":[{"id":2459,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2457\/revisions\/2459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/2458"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=2457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=2457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=2457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}