{"id":2685,"date":"2019-03-19T15:00:47","date_gmt":"2019-03-19T14:00:47","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=2685"},"modified":"2019-03-19T13:24:10","modified_gmt":"2019-03-19T12:24:10","slug":"alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/","title":{"rendered":"ALLA SCOPERTA DEL LAZIO &#8211; In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d"},"content":{"rendered":"<p>Domani, mercoled\u00ec 20 marzo, alle ore 11.00, il Comune di Ferentino sar\u00e0 gradito ospite del\u00a0 Presidente della Regione Lazio Nicola Zingaretti, nell&#8217;ambito del progetto\u00a0\u00a0 &#8211; <strong>ALLA SCOPERTA DEL LAZIO &#8211; In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d<\/strong> . L&#8217;evento si svolger\u00e0 a Roma, presso <em>WEGIL,\u00a0<\/em> Largo Ascianghi 5.<\/p>\n<p>La giornata sar\u00e0 aperta dalla Tavola Rotonda\u00a0 : \u201c<em>La Cultura come motore di sviluppo del territorio<\/em>\u201d<\/p>\n<p>Contestualmente sar\u00e0 possibile partecipare ai seguenti laboratori prenotandosi direttamente sul posto:<\/p>\n<ul>\n<li>Gli oli d\u2019oliva made in Lazio<\/li>\n<li>Freschi speziati e stagionati: l\u2019arte casearia del Lazio<\/li>\n<li>La norcineria regionale<\/li>\n<li>Il Lazio goloso: prodotti da forno e pasticceria<\/li>\n<\/ul>\n<p><em>Per info e prenotazioni : ufficiosindaco@comune.ferentino.fr.it<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2686\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/IMG-20190319-WA0005-213x300.jpg\" alt=\"\" width=\"213\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/IMG-20190319-WA0005-213x300.jpg 213w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/IMG-20190319-WA0005.jpg 447w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani, mercoled\u00ec 20 marzo, alle ore 11.00, il Comune di Ferentino sar\u00e0 gradito ospite del\u00a0 Presidente della Regione Lazio Nicola Zingaretti, nell&#8217;ambito del progetto\u00a0\u00a0 &#8211; ALLA SCOPERTA DEL LAZIO &#8211; [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":2687,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALLA SCOPERTA DEL LAZIO - In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALLA SCOPERTA DEL LAZIO - In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Domani, mercoled\u00ec 20 marzo, alle ore 11.00, il Comune di Ferentino sar\u00e0 gradito ospite del\u00a0 Presidente della Regione Lazio Nicola Zingaretti, nell&#8217;ambito del progetto\u00a0\u00a0 &#8211; ALLA SCOPERTA DEL LAZIO &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-19T14:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/20190319_131858.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"444\" \/>\n\t<meta property=\"og:image:height\" content=\"140\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"ALLA SCOPERTA DEL LAZIO &#8211; In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d\",\"datePublished\":\"2019-03-19T14:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/\"},\"wordCount\":130,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/03\\\/20190319_131858.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/\",\"name\":\"ALLA SCOPERTA DEL LAZIO - In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/03\\\/20190319_131858.jpg\",\"datePublished\":\"2019-03-19T14:00:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/03\\\/20190319_131858.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/03\\\/20190319_131858.jpg\",\"width\":444,\"height\":140},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/03\\\/19\\\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLA SCOPERTA DEL LAZIO &#8211; In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALLA SCOPERTA DEL LAZIO - In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/","og_locale":"it_IT","og_type":"article","og_title":"ALLA SCOPERTA DEL LAZIO - In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d - Ferentino","og_description":"Domani, mercoled\u00ec 20 marzo, alle ore 11.00, il Comune di Ferentino sar\u00e0 gradito ospite del\u00a0 Presidente della Regione Lazio Nicola Zingaretti, nell&#8217;ambito del progetto\u00a0\u00a0 &#8211; ALLA SCOPERTA DEL LAZIO &#8211; [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-03-19T14:00:47+00:00","og_image":[{"width":444,"height":140,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/20190319_131858.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"ALLA SCOPERTA DEL LAZIO &#8211; In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d","datePublished":"2019-03-19T14:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/"},"wordCount":130,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/20190319_131858.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/","url":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/","name":"ALLA SCOPERTA DEL LAZIO - In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/20190319_131858.jpg","datePublished":"2019-03-19T14:00:47+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/20190319_131858.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/03\/20190319_131858.jpg","width":444,"height":140},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/03\/19\/alla-scoperta-del-lazio-in-viaggio-tra-i-comuni-che-hanno-concorso-al-titolo-citta-della-cultura-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"ALLA SCOPERTA DEL LAZIO &#8211; In viaggio tra i comuni che hanno concorso al titolo \u201cCitt\u00e0 della Cultura 2019\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=2685"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2685\/revisions"}],"predecessor-version":[{"id":2691,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2685\/revisions\/2691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/2687"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=2685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=2685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=2685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}