{"id":2879,"date":"2019-05-02T15:13:53","date_gmt":"2019-05-02T13:13:53","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=2879"},"modified":"2019-05-02T15:13:53","modified_gmt":"2019-05-02T13:13:53","slug":"festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/","title":{"rendered":"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d"},"content":{"rendered":"<p class=\"yiv7452768023MsoNormal\">\u201cNelle celebrazioni in onore di Sant\u2019Ambrogio si rinnova il sentimento di devozione nei confronti del Martire cristiano e il senso dell\u2019appartenenza e del legame alla storia della nostra citt\u00e0\u201d.<\/p>\n<p class=\"yiv7452768023MsoNormal\">E\u2019 quanto afferma il sindaco di Ferentino Antonio Pompeo.<\/p>\n<p class=\"yiv7452768023MsoNormal\">\u201cAnche quest\u2019anno c\u2019\u00e8 stata una partecipazione di fedeli di grande rilievo, nonostante il tempo inclemente. Non solo di Ferentino, ma provenienti anche dai paesi limitrofi, essendo S. Ambrogio un culto molto sentito nell\u2019intero territorio, in quanto patrono della nostra diocesi\u201d.<\/p>\n<p class=\"yiv7452768023MsoNormal\">\u201cVoglio evidenziare ancora una volta \u2013 ha aggiunto il sindaco \u2013\u00a0 il perfetto funzionamento della macchina organizzativa: sia quella degli eventi religiosi che di quelli civili, a dimostrazione di una collaborazione e di una condivisione ottimale, frutto di una programmazione ormai collaudata\u201d.<\/p>\n<p class=\"yiv7452768023MsoNormal\">Entrando nello specifico della macchina organizzativa, il sindaco Pompeo sottolinea: \u201cOttima \u00e8 stata la gestione della logistica, con un servizio navetta efficiente e funzionale. Ottima la gestione della sicurezza. Ottimo \u00e8 stato il lavoro di manutenzione e decoro del territorio. Tutto ha funzionato per il meglio. Per questo voglio ringraziare l\u2019intera cittadinanza: Ferentino ha dato una bellissima immagine di s\u00e9 e delle sue capacit\u00e0 organizzative ed \u00e8 stato straordinario vedere le nostre strade, le nostre piazze, i nostri monumenti e le nostre chiese piene di visitatori\u201d.<\/p>\n<p class=\"yiv7452768023MsoNormal\">\u201cUn ringraziamento particolare al nostro Vescovo, Monsignor Ambrogio Spreafico, al parroco della Cattedrale di San Giovanni e Paolo, don Giuseppe Principali. Grazie agli incollatori. Non posso non sottolineare, infine, l\u2019impegno di tutta l\u2019Amministrazione comunale, dei nostri uffici e di tutto il personale\u201d.<\/p>\n<p class=\"yiv7452768023MsoNormal\">\u201cPeccato per le avverse condizioni metereologiche \u00a0\u2013 ha concluso Pompeo \u2013 che hanno impedito lo svolgimento del tanto atteso concerto di Riccardo Fogli, che verr\u00e0 recuperato il prossimo 15 giugno. Ne approfitto per ringraziare Riccardo della sua pronta disponibilit\u00e0 a trovare una nuova data e mi piace sottolineare la sua straordinaria simpatia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNelle celebrazioni in onore di Sant\u2019Ambrogio si rinnova il sentimento di devozione nei confronti del Martire cristiano e il senso dell\u2019appartenenza e del legame alla storia della nostra citt\u00e0\u201d. E\u2019 [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":2880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d - Ferentino\" \/>\n<meta property=\"og:description\" content=\"\u201cNelle celebrazioni in onore di Sant\u2019Ambrogio si rinnova il sentimento di devozione nei confronti del Martire cristiano e il senso dell\u2019appartenenza e del legame alla storia della nostra citt\u00e0\u201d. E\u2019 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-02T13:13:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/05\/s-ambrogio_2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d\",\"datePublished\":\"2019-05-02T13:13:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/\"},\"wordCount\":324,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/05\\\/s-ambrogio_2019.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/\",\"name\":\"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/05\\\/s-ambrogio_2019.jpg\",\"datePublished\":\"2019-05-02T13:13:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/05\\\/s-ambrogio_2019.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/05\\\/s-ambrogio_2019.jpg\",\"width\":720,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/05\\\/02\\\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/","og_locale":"it_IT","og_type":"article","og_title":"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d - Ferentino","og_description":"\u201cNelle celebrazioni in onore di Sant\u2019Ambrogio si rinnova il sentimento di devozione nei confronti del Martire cristiano e il senso dell\u2019appartenenza e del legame alla storia della nostra citt\u00e0\u201d. E\u2019 [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-05-02T13:13:53+00:00","og_image":[{"width":720,"height":960,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/05\/s-ambrogio_2019.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d","datePublished":"2019-05-02T13:13:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/"},"wordCount":324,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/05\/s-ambrogio_2019.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/","url":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/","name":"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/05\/s-ambrogio_2019.jpg","datePublished":"2019-05-02T13:13:53+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/05\/s-ambrogio_2019.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/05\/s-ambrogio_2019.jpg","width":720,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/05\/02\/festeggiamenti-s-ambrogio-il-sindaco-pompeo-momento-di-fede-e-di-tradizione-tutto-ha-funzionato-per-il-meglio-la-piu-bella-immagine-della-nostra-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FESTEGGIAMENTI S. AMBROGIO, IL SINDACO POMPEO: \u201cMOMENTO DI FEDE E DI TRADIZIONE, TUTTO HA FUNZIONATO PER IL MEGLIO: LA PIU\u2019 BELLA IMMAGINE DELLA NOSTRA CITT\u00c0\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=2879"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2879\/revisions"}],"predecessor-version":[{"id":2881,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/2879\/revisions\/2881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/2880"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=2879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=2879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=2879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}