{"id":3117,"date":"2019-07-15T10:00:59","date_gmt":"2019-07-15T08:00:59","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=3117"},"modified":"2019-07-15T09:20:05","modified_gmt":"2019-07-15T07:20:05","slug":"fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/","title":{"rendered":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb   16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d"},"content":{"rendered":"<p>Dopo la prima serata del 15 luglio, tutta dedicata a un pilastro della musica jazz internazionale, il 16 luglio Fiati in Concerto \u201cVisioni\u201d focalizza tutta la sua attenzione a un particolare tipo di talento: quello dei giovani. Il concerto rientra infatti nello \u201cSpazio Giovani Talenti\u201d, fortemente voluto dal direttore artistico della rassegna, proprio per porre un accento forte e immediato sulla valorizzazione delle nuove realt\u00e0 artistico-musicali giovani e giovanili del territorio della provincia di Frosinone.<\/p>\n<p>Per questo, nel suggestivo chiostro di S. Antonio Abate in Ferentino, marted\u00ec 16 alle 21.30 si potr\u00e0 apprezzare il talento di una formazione decisamente recente, quale \u00e8 l\u2019Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d di Frosinone, diretta dal M\u00b0 Marco Attura, personalit\u00e0 di spicco del nostro territorio, che gi\u00e0 da giovanissimo si \u00e8 addentrato nel campo della direzione d\u2019orchestra, conseguendo prestigiosi titoli e dirigendo diverse formazioni in tutto il territorio italiano e all\u2019estero.<\/p>\n<p>L\u2019Orchestra Sinfonica Giovanile nasce infatti dalla volont\u00e0 M\u00b0 Marco Attura, che, ampliando l\u2019organico di un gruppo preesistente, ne ridefinisce i tratti essenziali dando dunque nuova vita a una formazione che vede la partecipazione dei ragazzi dell\u2019intero quinquennio di scuola superiore presso l\u2019omonimo istituto. Una valida formazione orchestrale quindi, integrata da quella tecnica e teorica previste dal piano di studi, che permettono l\u2019acquisizione di nozioni di tipo stilistico, tecnico ed espressivo collegate alla prassi esecutiva del repertorio affrontato, e che fornisce agli studenti la dotazione necessaria per percorrere la giusta strada verso un futuro professionale.<\/p>\n<p>Il programma scelto per la serata, una rarit\u00e0, vedr\u00e0 l\u2019esecuzione di alcune colonne sonore che solitamente non trovano degno spazio nelle sale da concerto italiane ma che vengono regolarmente eseguite oltreoceano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3101\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-203x300.jpg\" alt=\"\" width=\"203\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-203x300.jpg 203w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-768x1136.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-692x1024.jpg 692w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-680x1006.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1.jpg 1082w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3102\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-203x300.jpg\" alt=\"\" width=\"203\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-203x300.jpg 203w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-768x1136.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-692x1024.jpg 692w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-680x1006.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3.jpg 1082w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Dopo la prima serata del 15 luglio, tutta dedicata a un pilastro della musica jazz internazionale, il 16 luglio Fiati in Concerto \u201cVisioni\u201d focalizza tutta la sua attenzione a un [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":3153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb  16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb  16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Dopo la prima serata del 15 luglio, tutta dedicata a un pilastro della musica jazz internazionale, il 16 luglio Fiati in Concerto \u201cVisioni\u201d focalizza tutta la sua attenzione a un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-15T08:00:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/marco-attura-fiati-2-giorno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5315\" \/>\n\t<meta property=\"og:image:height\" content=\"3543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d\",\"datePublished\":\"2019-07-15T08:00:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/\"},\"wordCount\":293,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/marco-attura-fiati-2-giorno.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/\",\"name\":\"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/marco-attura-fiati-2-giorno.jpg\",\"datePublished\":\"2019-07-15T08:00:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/marco-attura-fiati-2-giorno.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/marco-attura-fiati-2-giorno.jpg\",\"width\":5315,\"height\":3543},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/15\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb  16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/","og_locale":"it_IT","og_type":"article","og_title":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb  16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d - Ferentino","og_description":"Dopo la prima serata del 15 luglio, tutta dedicata a un pilastro della musica jazz internazionale, il 16 luglio Fiati in Concerto \u201cVisioni\u201d focalizza tutta la sua attenzione a un [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-07-15T08:00:59+00:00","og_image":[{"width":5315,"height":3543,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/marco-attura-fiati-2-giorno.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d","datePublished":"2019-07-15T08:00:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/"},"wordCount":293,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/marco-attura-fiati-2-giorno.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/","url":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/","name":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/marco-attura-fiati-2-giorno.jpg","datePublished":"2019-07-15T08:00:59+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/marco-attura-fiati-2-giorno.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/marco-attura-fiati-2-giorno.jpg","width":5315,"height":3543},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/15\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-16-luglio-orchestra-sinfonica-giovanile-iis-a-g-bragaglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 16 luglio \u2013 Orchestra Sinfonica Giovanile \u201cIIS A.G. Bragaglia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=3117"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3117\/revisions"}],"predecessor-version":[{"id":3154,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3117\/revisions\/3154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/3153"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=3117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=3117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=3117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}