{"id":3134,"date":"2019-07-18T10:00:54","date_gmt":"2019-07-18T08:00:54","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=3134"},"modified":"2019-07-13T17:33:59","modified_gmt":"2019-07-13T15:33:59","slug":"fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/","title":{"rendered":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb  19 luglio  FerentinoFluteEnsemble  Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini"},"content":{"rendered":"<p>Si susseguono senza sosta i concerti della straordinaria quattordicesima edizione della rassegna Fiati in Concerto \u201cVisioni\u201d. Cos\u00ec come avvenuto marted\u00ec 16 Luglio, il cartellone focalizza di nuovo la sua attenzione al talento giovanile. \u201cSpazio Giovani Talenti\u201d incontrer\u00e0 per questo quinto concerto i giovani studenti del corso di perfezionamento di Flauto ed Ottavino organizzato dalla Scuola di Musica di Ferentino e tenuto dal M\u00b0 Fabio Angelo Colajanni, i giovani instancabili della Banda Giovanile \u201cCitt\u00e0 di Ferentino\u201d ed il talento dell\u2019 attrice marchigiana Melissa Conigli. Il concerto vedr\u00e0 poi la partecipazione straordinaria dello stesso M\u00b0 Colajanni e del M\u00b0 Beatrice Petrocchi rispettivamente all\u2019ottavino e al flauto.<br \/>\nGruzzolino, fiaba musicale nata dalla penna della compositrice Clara Lombardi, diventer\u00e0 per l\u2019occasione Un Gruzzolino da favola!,momento fiabesco in cui il pubblico potr\u00e0 incontrare i personaggi pi\u00f9 significativi della propria infanzia. Immersi nel verde, i protagonisti di questo concerto prenderanno per mano grandi e piccini e li faranno viaggiare ad occhi chiusi nella fantastica cornice delle mura ciclopiche di Porta Sanguinaria<br \/>\nAlla guida di questo viaggio ci sar\u00e0 il M\u00b0 Luigi Bartolini, anima ed artefice dello straordinario risultato musicale della formazione giovanile, che ormai ogni anno arricchisce Fiati in Concerto con nuove ed entusiasmanti proposte atte alla divulgazione della musica bandistica giovanile nella nostra citt\u00e0.<br \/>\nIl concerto di oggi sar\u00e0 il preludio al gran finale di Sabato 20 e domenica 21, giorni in cui la rassegna torner\u00e0 nella sua location originaria, ovvero P.zza Mazzini. Con le graditissime partecipazioni delle Sorelle Marinetti e dell\u2019attore Enzo Decaro ci prepariamo dunque ad una chiusura degna di questa quattordicesima &#8211; itinerante ed innovativa &#8211; edizione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3138\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Screenshot_20190713-172947_Libero-Mail-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Screenshot_20190713-172947_Libero-Mail-300x200.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Screenshot_20190713-172947_Libero-Mail-768x512.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Screenshot_20190713-172947_Libero-Mail-1024x683.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Screenshot_20190713-172947_Libero-Mail-680x454.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Screenshot_20190713-172947_Libero-Mail.jpg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3101\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-203x300.jpg\" alt=\"\" width=\"203\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-203x300.jpg 203w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-768x1136.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-692x1024.jpg 692w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1-680x1006.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/FIATI-LOCANDINA-1.jpg 1082w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3102\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-203x300.jpg\" alt=\"\" width=\"203\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-203x300.jpg 203w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-768x1136.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-692x1024.jpg 692w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3-680x1006.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/Fiati-3.jpg 1082w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Si susseguono senza sosta i concerti della straordinaria quattordicesima edizione della rassegna Fiati in Concerto \u201cVisioni\u201d. Cos\u00ec come avvenuto marted\u00ec 16 Luglio, il cartellone focalizza di nuovo la sua attenzione [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":3137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Si susseguono senza sosta i concerti della straordinaria quattordicesima edizione della rassegna Fiati in Concerto \u201cVisioni\u201d. Cos\u00ec come avvenuto marted\u00ec 16 Luglio, il cartellone focalizza di nuovo la sua attenzione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-18T08:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190713_173032.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2896\" \/>\n\t<meta property=\"og:image:height\" content=\"2896\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini\",\"datePublished\":\"2019-07-18T08:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/\"},\"wordCount\":294,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/20190713_173032.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/\",\"name\":\"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/20190713_173032.jpg\",\"datePublished\":\"2019-07-18T08:00:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/20190713_173032.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/20190713_173032.jpg\",\"width\":2896,\"height\":2896},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/07\\\/18\\\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/","og_locale":"it_IT","og_type":"article","og_title":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini - Ferentino","og_description":"Si susseguono senza sosta i concerti della straordinaria quattordicesima edizione della rassegna Fiati in Concerto \u201cVisioni\u201d. Cos\u00ec come avvenuto marted\u00ec 16 Luglio, il cartellone focalizza di nuovo la sua attenzione [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-07-18T08:00:54+00:00","og_image":[{"width":2896,"height":2896,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190713_173032.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini","datePublished":"2019-07-18T08:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/"},"wordCount":294,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190713_173032.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/","url":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/","name":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190713_173032.jpg","datePublished":"2019-07-18T08:00:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190713_173032.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190713_173032.jpg","width":2896,"height":2896},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/07\/18\/fiati-in-concerto-xiv-edizione-visioni-visioni-laterali-19-luglio-ferentinofluteensemble-banda-giovanile-citta-di-ferentino-con-m-conigli-f-a-col\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Fiati in Concerto XIV Edizione \u00abVISIONI\u00bb &amp; \u00abVISIONI LATERALI\u00bb 19 luglio FerentinoFluteEnsemble Banda Giovanile Citt\u00e0 di Ferentino con M. Conigli, F.A. Colajanni, B. Petrocchi e L.Bartolini"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=3134"}],"version-history":[{"count":5,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3134\/revisions"}],"predecessor-version":[{"id":3141,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3134\/revisions\/3141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/3137"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=3134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=3134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=3134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}