{"id":3271,"date":"2019-08-10T10:52:50","date_gmt":"2019-08-10T08:52:50","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=3271"},"modified":"2019-07-30T11:51:08","modified_gmt":"2019-07-30T09:51:08","slug":"il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/","title":{"rendered":"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 &#8211; &#8220;Bohemian Rapsody &#8220;"},"content":{"rendered":"<div class=\"p\"><b>Data di uscita:<\/b> 29 novembre 2018<\/div>\n<div class=\"p\"><b>Genere:<\/b> Biografico, Drammatico, Musicale<\/div>\n<div class=\"p\"><b>Anno:<\/b> 2018<\/div>\n<div class=\"p\"><b>Regia:<\/b> <a title=\"Dexter Fletcher\" href=\"https:\/\/www.comingsoon.it\/personaggi\/dexter-fletcher\/38886\/biografia\/\">Dexter Fletcher<\/a>, <a title=\"Bryan Singer\" href=\"https:\/\/www.comingsoon.it\/personaggi\/bryan-singer\/96348\/biografia\/\">Bryan Singer<\/a><\/div>\n<div class=\"p\"><b>Attori:<\/b> <a title=\"Rami Malek\" href=\"https:\/\/www.comingsoon.it\/personaggi\/rami-malek\/166707\/biografia\/\">Rami Malek<\/a>, <a title=\"Mike Myers\" href=\"https:\/\/www.comingsoon.it\/personaggi\/mike-myers\/75266\/biografia\/\">Mike Myers<\/a>, <a title=\"Aidan Gillen\" href=\"https:\/\/www.comingsoon.it\/personaggi\/aidan-gillen\/44463\/biografia\/\">Aidan Gillen<\/a>, <a title=\"Tom Hollander\" href=\"https:\/\/www.comingsoon.it\/personaggi\/tom-hollander\/51398\/biografia\/\">Tom Hollander<\/a>, <a title=\"Joseph Mazzello\" href=\"https:\/\/www.comingsoon.it\/personaggi\/joseph-mazzello\/71561\/biografia\/\">Joseph Mazzello<\/a>, <a title=\"Lucy Boynton\" href=\"https:\/\/www.comingsoon.it\/personaggi\/lucy-boynton\/208884\/biografia\/\">Lucy Boynton<\/a>, <a title=\"Allen Leech\" href=\"https:\/\/www.comingsoon.it\/personaggi\/allen-leech\/239871\/biografia\/\">Allen Leech<\/a>, <a title=\"Michelle Duncan\" href=\"https:\/\/www.comingsoon.it\/personaggi\/michelle-duncan\/222288\/biografia\/\">Michelle Duncan<\/a>, <a title=\"Aaron McCusker\" href=\"https:\/\/www.comingsoon.it\/personaggi\/aaron-mccusker\/247686\/biografia\/\">Aaron McCusker<\/a>, <a title=\"Max Bennett\" href=\"https:\/\/www.comingsoon.it\/personaggi\/max-bennett\/251896\/biografia\/\">Max Bennett<\/a>, <a title=\"Gwilym Lee\" href=\"https:\/\/www.comingsoon.it\/personaggi\/gwilym-lee\/256962\/biografia\/\">Gwilym Lee<\/a>, <a title=\"Ben Hardy\" href=\"https:\/\/www.comingsoon.it\/personaggi\/ben-hardy\/249216\/biografia\/\">Ben Hardy<\/a><\/div>\n<div class=\"p\"><b>Paese:<\/b> Gran Bretagna, USA<\/div>\n<div class=\"p\"><b>Durata:<\/b> 106 min<\/div>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3277\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/A-scuola-da-John-Vignola-Bohemian-Rhapsody-1280x620-300x145.jpg\" alt=\"\" width=\"300\" height=\"145\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/A-scuola-da-John-Vignola-Bohemian-Rhapsody-1280x620-300x145.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/A-scuola-da-John-Vignola-Bohemian-Rhapsody-1280x620-768x372.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/A-scuola-da-John-Vignola-Bohemian-Rhapsody-1280x620-1024x496.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/A-scuola-da-John-Vignola-Bohemian-Rhapsody-1280x620-680x329.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/A-scuola-da-John-Vignola-Bohemian-Rhapsody-1280x620.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n<div><\/div>\n<div><strong>Bohemian Rhapsody<\/strong>, il film diretto da Bryan Singer e Dexter Fletcher, \u00e8 una coinvolgente celebrazione dei <strong>Queen<\/strong>, della loro musica e del loro leggendario frontman <strong>Freddie Mercury<\/strong> (<a title=\"Rami Malek\" href=\"https:\/\/www.comingsoon.it\/personaggi\/rami-malek\/166707\/biografia\/\" target=\"_blank\" rel=\"noopener\"><strong>Rami Malek<\/strong><\/a>), che sfid\u00f2 gli stereotipi e infranse le convenzioni, diventando uno degli artisti pi\u00f9 amati al mondo.<br \/>\nIl film ricostruisce la meteorica ascesa della band attraverso le sue iconiche canzoni e il suo sound rivoluzionario, la sua crisi quasi fatale, man mano che lo stile di vita vita di Mercury andava fuori controllo, e la sua trionfante reunion alla vigilia del Live Aid, quando Mercury, afflitto da una gravissima malattia, condusse la band in una delle performance pi\u00f9 grandiose della storia del rock.<br \/>\nFacendo questo, il film cementa l&#8217;eredit\u00e0 di una band che \u00e8 sempre stata pi\u00f9 di una famiglia e che continua ancora oggi a ispirare gli outsider, i sognatori e gli appassionati di musica.<br \/>\nOltre a Rami Malek nei panni di Freddie Mercury, <strong>il film vede nel suo cast<\/strong> <a title=\"Lucy Boynton\" href=\"https:\/\/www.comingsoon.it\/personaggi\/lucy-boynton\/208884\/biografia\/\" target=\"_blank\" rel=\"noopener\"><strong>Lucy Boynton<\/strong><\/a>, nel ruolo di <strong>Mary Austin<\/strong>, grande amore di Freddie, <a title=\"Gwilym Lee\" href=\"https:\/\/www.comingsoon.it\/personaggi\/gwilym-lee\/256962\/biografia\/\" target=\"_blank\" rel=\"noopener\"><strong>Gwilym Lee<\/strong><\/a> nei panni di <strong>Brian May<\/strong>, chitarrista dei Queen, <a title=\"Ben Hardy\" href=\"https:\/\/www.comingsoon.it\/personaggi\/ben-hardy\/249216\/biografia\/\" target=\"_blank\" rel=\"noopener\"><strong>Ben Hardy<\/strong><\/a> in quelli del batterista <strong>Roger Taylor<\/strong>, <a title=\"Joe Mazzello\" href=\"https:\/\/www.comingsoon.it\/personaggi\/joseph-mazzello\/71561\/biografia\/\" target=\"_blank\" rel=\"noopener\"><strong>Joe Mazzello<\/strong><\/a> interpreta il bassista <strong>John Deacy Deacon<\/strong>, <a title=\"Aidan Gillen\" href=\"https:\/\/www.comingsoon.it\/personaggi\/aidan-gillen\/44463\/biografia\/\" target=\"_blank\" rel=\"noopener\"><strong>Aidan Gillen<\/strong><\/a> \u00e8 invece John Reid, primo manager del gruppo, <strong>Aaron McCusker<\/strong> ha il ruolo di Jim Hutton, a lungo il ragazzo di Mercury e <a title=\"Mike Myers\" href=\"https:\/\/www.comingsoon.it\/personaggi\/mike-myers\/75266\/biografia\/\" target=\"_blank\" rel=\"noopener\"><strong>Mike Myers<\/strong><\/a> nei panni di Ray Foster della casa discografica EMI.<\/div>\n<div><\/div>\n<div><strong><em>Ingresso gratuito<\/em><\/strong><\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Data di uscita: 29 novembre 2018 Genere: Biografico, Drammatico, Musicale Anno: 2018 Regia: Dexter Fletcher, Bryan Singer Attori: Rami Malek, Mike Myers, Aidan Gillen, Tom Hollander, Joseph Mazzello, Lucy Boynton, [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":3213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 - &quot;Bohemian Rapsody &quot; - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 - &quot;Bohemian Rapsody &quot; - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Data di uscita: 29 novembre 2018 Genere: Biografico, Drammatico, Musicale Anno: 2018 Regia: Dexter Fletcher, Bryan Singer Attori: Rami Malek, Mike Myers, Aidan Gillen, Tom Hollander, Joseph Mazzello, Lucy Boynton, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-10T08:52:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190726_202809.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1075\" \/>\n\t<meta property=\"og:image:height\" content=\"1005\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 &#8211; &#8220;Bohemian Rapsody &#8220;\",\"datePublished\":\"2019-08-10T08:52:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/\"},\"wordCount\":288,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/20190726_202809.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/\",\"name\":\"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 - \\\"Bohemian Rapsody \\\" - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/20190726_202809.jpg\",\"datePublished\":\"2019-08-10T08:52:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/20190726_202809.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/07\\\/20190726_202809.jpg\",\"width\":1075,\"height\":1005},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/10\\\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 &#8211; &#8220;Bohemian Rapsody &#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 - \"Bohemian Rapsody \" - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/","og_locale":"it_IT","og_type":"article","og_title":"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 - \"Bohemian Rapsody \" - Ferentino","og_description":"Data di uscita: 29 novembre 2018 Genere: Biografico, Drammatico, Musicale Anno: 2018 Regia: Dexter Fletcher, Bryan Singer Attori: Rami Malek, Mike Myers, Aidan Gillen, Tom Hollander, Joseph Mazzello, Lucy Boynton, [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-10T08:52:50+00:00","og_image":[{"width":1075,"height":1005,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190726_202809.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 &#8211; &#8220;Bohemian Rapsody &#8220;","datePublished":"2019-08-10T08:52:50+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/"},"wordCount":288,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190726_202809.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/","url":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/","name":"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 - \"Bohemian Rapsody \" - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190726_202809.jpg","datePublished":"2019-08-10T08:52:50+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190726_202809.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/07\/20190726_202809.jpg","width":1075,"height":1005},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/10\/il-grande-cinema-a-piazza-mazzini-sabato-10-agosto-ore-21-30-bohemian-rapsody\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Il grande cinema a Piazza Mazzini- sabato 10 agosto ore 21.30 &#8211; &#8220;Bohemian Rapsody &#8220;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=3271"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3271\/revisions"}],"predecessor-version":[{"id":3278,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3271\/revisions\/3278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/3213"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=3271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=3271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=3271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}