{"id":3360,"date":"2019-08-25T10:34:01","date_gmt":"2019-08-25T08:34:01","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=3360"},"modified":"2019-08-24T17:32:40","modified_gmt":"2019-08-24T15:32:40","slug":"ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/","title":{"rendered":"FERENTINO in fiaba 25 Agosto ore 18.00 &#8220;Pulcinella e la cassa magica&#8221;- ore 21.15 &#8221; Il Pifferaio di Hamelin &#8220;"},"content":{"rendered":"<p>Anche oggi doppio appuntamento per la rassegna &#8220;Ferentino in Fiaba&#8221;, che questa sera caler\u00e0 il sipario sulla sua undicesima edizione.<\/p>\n<p><strong>Ore 18.00 Piazza Matteotti\u00a0 &#8211; Pulcinella e la cassa magica<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3338\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/pulcinella-174x300.jpg\" alt=\"\" width=\"174\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/pulcinella-174x300.jpg 174w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/pulcinella-768x1321.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/pulcinella-595x1024.jpg 595w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/pulcinella-680x1170.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/pulcinella.jpg 922w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/><\/p>\n<p><span class=\"color_11\">Pulcinella Citrulo \u00e8 innamorato della bella Teresina, figlia dell\u2019albergatore Don Pancrazio Codadivacca e promessa sposa al giovane possidente Don Felice Sciosciammocca, pensionato della locanda. Pulcinella, travestito da donna prende alloggio nella locanda per scoprire il segreto della ricchezza del suo rivale.<br \/>\nE\u2019 mezzanotte e Pulcinella, nascosto dietro una tenda, scorge Don Felice invocare niente di meno che&#8230;Il diavolo!!<br \/>\nFra colpi di scena, travestimenti, filtri magici, diavoli veri, e diavoli finti, si dipana una matassa complicatissima che vedr\u00e0 Pulcinella scendere all\u2019inferno come un eroe mitologico e trovarsi alla fine promesso sposo&#8230;di un uomo!<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ore 21.15 Piazza Mazzini\u00a0 &#8211; &#8221; Il Pifferaio di Hamelin&#8221;<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3337\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/locand-pifferaio-016-171x300-171x300.jpg\" alt=\"\" width=\"171\" height=\"300\" \/><\/p>\n<p>La storia, nota a grandi e piccini, ha un\u2019amara conclusione. Il sindaco e gli abitanti del paese di Hamelin vengono puniti per le loro cattive azioni e la punizione consiste in una delle pi\u00f9 crudeli trovate delle fiabe di tutti i tempi: la scomparsa dei bambini, quindi della creativit\u00e0, dello stupore, valori a cui l\u2019umanit\u00e0 deve far riferimento per liberarsi dall\u2019inevitabilit\u00e0 degli eventi (guerre, distruzioni, sfruttamento, intolleranza). Vi sono naturalmente tutti gli elementi costitutivi della fiaba: il tempo indefinito (il c\u2019era una volta), gli antagonisti della fiaba, l\u2019elemento negativo rappresentato dal sindaco, ovvero l\u2019arroganza del potere e la vilt\u00e0 del popolino\/massa che rifiuta le proprie responsabilit\u00e0 e accetta indistintamente le decisioni prese dai vertici; e l\u2019elemento positivo, rappresentato dal pifferaio, che non \u00e8 un principe azzurro ma un\u2019artista di strada, un personaggio misterioso, un \u201cdiverso\u201d; quindi la \u201ccrisi drammatica\u201d nella presenza ad Hamelin di milioni di topi, la loro cacciata ad opera del pifferaio e poi le promesse non mantenute da parte dei potenti (vedi politici). Infine, la punizione, inaspettata, crudele. Ma, diversamente da tante altre fiabe, la punizione \u00e8 a tempo indefinito e la colpa mai espiata. Crediamo che gli abitanti di Hamelin abbiano patito abbastanza e quindi abbiamo voluto offrire una possibilit\u00e0 di salvezza; una soluzione all\u2019evento irrisolto, che mantenendo il linguaggio fiabesco, riportasse la vita ad Hamelin, introducendo il sogno, l\u2019utopia, di cui abbiamo ancora bisogno nonostante (o proprio per?) i livelli supertecnologizzati della nostra epoca. Finale a sorpresa dunque nel paese dei bambini.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3361\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/piffer-e1478342193391-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/piffer-e1478342193391-300x200.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/piffer-e1478342193391.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div><strong>Ingresso gratuito\u00a0<\/strong><\/div>\n<div id=\"gallery-1\" class=\"gallery galleryid-25 gallery-columns-6 gallery-size-thumbnail\">\n<div class=\"gallery-inner-wrapper\"><\/div>\n<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Anche oggi doppio appuntamento per la rassegna &#8220;Ferentino in Fiaba&#8221;, che questa sera caler\u00e0 il sipario sulla sua undicesima edizione. Ore 18.00 Piazza Matteotti\u00a0 &#8211; Pulcinella e la cassa magica [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":3332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO in fiaba 25 Agosto ore 18.00 &quot;Pulcinella e la cassa magica&quot;- ore 21.15 &quot; Il Pifferaio di Hamelin &quot; - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO in fiaba 25 Agosto ore 18.00 &quot;Pulcinella e la cassa magica&quot;- ore 21.15 &quot; Il Pifferaio di Hamelin &quot; - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Anche oggi doppio appuntamento per la rassegna &#8220;Ferentino in Fiaba&#8221;, che questa sera caler\u00e0 il sipario sulla sua undicesima edizione. Ore 18.00 Piazza Matteotti\u00a0 &#8211; Pulcinella e la cassa magica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-25T08:34:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/fiabe-2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1004\" \/>\n\t<meta property=\"og:image:height\" content=\"1526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO in fiaba 25 Agosto ore 18.00 &#8220;Pulcinella e la cassa magica&#8221;- ore 21.15 &#8221; Il Pifferaio di Hamelin &#8220;\",\"datePublished\":\"2019-08-25T08:34:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/\"},\"wordCount\":407,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/08\\\/fiabe-2019.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/\",\"name\":\"FERENTINO in fiaba 25 Agosto ore 18.00 \\\"Pulcinella e la cassa magica\\\"- ore 21.15 \\\" Il Pifferaio di Hamelin \\\" - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/08\\\/fiabe-2019.jpg\",\"datePublished\":\"2019-08-25T08:34:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/08\\\/fiabe-2019.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2019\\\/08\\\/fiabe-2019.jpg\",\"width\":1004,\"height\":1526},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2019\\\/08\\\/25\\\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO in fiaba 25 Agosto ore 18.00 &#8220;Pulcinella e la cassa magica&#8221;- ore 21.15 &#8221; Il Pifferaio di Hamelin &#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO in fiaba 25 Agosto ore 18.00 \"Pulcinella e la cassa magica\"- ore 21.15 \" Il Pifferaio di Hamelin \" - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO in fiaba 25 Agosto ore 18.00 \"Pulcinella e la cassa magica\"- ore 21.15 \" Il Pifferaio di Hamelin \" - Ferentino","og_description":"Anche oggi doppio appuntamento per la rassegna &#8220;Ferentino in Fiaba&#8221;, che questa sera caler\u00e0 il sipario sulla sua undicesima edizione. Ore 18.00 Piazza Matteotti\u00a0 &#8211; Pulcinella e la cassa magica [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-25T08:34:01+00:00","og_image":[{"width":1004,"height":1526,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/fiabe-2019.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO in fiaba 25 Agosto ore 18.00 &#8220;Pulcinella e la cassa magica&#8221;- ore 21.15 &#8221; Il Pifferaio di Hamelin &#8220;","datePublished":"2019-08-25T08:34:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/"},"wordCount":407,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/fiabe-2019.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/","url":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/","name":"FERENTINO in fiaba 25 Agosto ore 18.00 \"Pulcinella e la cassa magica\"- ore 21.15 \" Il Pifferaio di Hamelin \" - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/fiabe-2019.jpg","datePublished":"2019-08-25T08:34:01+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/fiabe-2019.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2019\/08\/fiabe-2019.jpg","width":1004,"height":1526},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2019\/08\/25\/ferentino-in-fiaba-il-pifferaio-magico-23-agosto-ore-21-15-piazza-mazzini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO in fiaba 25 Agosto ore 18.00 &#8220;Pulcinella e la cassa magica&#8221;- ore 21.15 &#8221; Il Pifferaio di Hamelin &#8220;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=3360"}],"version-history":[{"count":6,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3360\/revisions"}],"predecessor-version":[{"id":3389,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3360\/revisions\/3389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/3332"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=3360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=3360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=3360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}