{"id":341,"date":"2017-03-21T16:33:23","date_gmt":"2017-03-21T15:33:23","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=341"},"modified":"2017-03-21T16:33:23","modified_gmt":"2017-03-21T15:33:23","slug":"venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/","title":{"rendered":"VENERDI&#8217; 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO."},"content":{"rendered":"<p><strong>PARTE IL CONCORSO A PREMI <em>LAVORGNA TI PAGA LA TARI &#8211; <\/em><\/strong>dal 22\/03 al 31\/07\/2017\u00a0 &#8211; chi si registra <strong>CITTAPULITA.NET<\/strong> parteciper\u00e0 all\u2019estrazione di 5 buoni per azzerare la bolletta.<\/p>\n<p>E&#8217; in programma <strong>venerd\u00ec<\/strong> <strong>24<\/strong> <strong>marzo,<\/strong> con inizio alle ore 11.00, presso la Sala Consiliare del Comune di Ferentino (FR) la conferenza stampa di presentazione del Concorso a Premi denominato \u201c<strong>la Tari in Omaggio<\/strong>\u201d, promosso dalla societ\u00e0 di gestione del servizio di raccolta differenziata \u201cporta a porta\u201d, <strong>Lavorgna srl.<\/strong><\/p>\n<p>Il concorso a premi, patrocinato dall\u2019Amministrazione comunale, ha l\u2019obiettivo di incentivare le iscrizioni al portale <strong><a href=\"http:\/\/www.cittapulita.net\">www.cittapulita.net<\/a> <\/strong>degli utenti per offrirgli una serie di servizi di informazioni e assistenza legati alla gestione integrata della raccolta differenziata cittadina. Con la registrazione, ovviamente, gratuita, il cittadino potr\u00e0 prendere parte al Concorso a premi che prevede due fasce di premialit\u00e0, la prima, alla quale accedono i cittadini iscritti al ruolo TARI 2016 in qualit\u00e0 di intestatari di utenza domestica sull\u2019abitazione principale, che mette in palio <strong>n. cinque buoni<\/strong> il cui valore corrisponder\u00e0 all<strong>\u2019importo della bolletta TARI<\/strong> del singolo vincitore estratto. La seconda fascia, alla quale parteciperanno tutti gli iscritti al ruolo TARI, senza alcuna distinzione tra utenze domestiche e commerciali, ha un montepremi finale di <strong>dieci buoni spesa<\/strong> dal valore unitario di <strong>50,00 euro<\/strong> spendibile negli esercizi commerciali cittadini convenzionati.<\/p>\n<p>\u201c<em>Il Concorso a Premi<\/em> \u2013 ha dichiarato <strong>Sandro Lavorgna<\/strong>, amministratore della societ\u00e0 \u2013 <em>\u00e8 una delle iniziative che durante l\u2019anno, come gestori del servizio di raccolta differenziata, attiviamo per alimentare nei cittadini la sensibilit\u00e0 alla tutela e salvaguardia dell\u2019ambiente. Inoltre, il concorso \u00e8 innestato in una strategia di comunicazione che la nostra azienda sta portando avanti con l\u2019intento di incentivare l\u2019uso di canali digitali e social per qualificare e migliorare il rapporto con i cittadini delle singole realt\u00e0 dove operiamo\u201d.<\/em><\/p>\n<p>L\u2019assessore all\u2019ambiente, Franco Martini: A<em>ttraverso questa iniziativa, la nostra amministrazione vuole lanciare un impegno da trasmettere ai cittadini: rispettare l\u2019ambiente, fare una buona differenziata, segnalare i comportamenti incivili, legati all\u2019abbandono dei rifiuti, perch\u00e9 tutto ci\u00f2 comporter\u00e0 ulteriori riduzioni sul pagamento della Tari.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-343\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/Ferentino_lavorgna-ti-paga-la-tari-300x128.jpg\" alt=\"\" width=\"375\" height=\"160\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/Ferentino_lavorgna-ti-paga-la-tari-300x128.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/Ferentino_lavorgna-ti-paga-la-tari.jpg 618w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PARTE IL CONCORSO A PREMI LAVORGNA TI PAGA LA TARI &#8211; dal 22\/03 al 31\/07\/2017\u00a0 &#8211; chi si registra CITTAPULITA.NET parteciper\u00e0 all\u2019estrazione di 5 buoni per azzerare la bolletta. E&#8217; [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VENERDI&#039; 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO. - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VENERDI&#039; 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO. - Ferentino\" \/>\n<meta property=\"og:description\" content=\"PARTE IL CONCORSO A PREMI LAVORGNA TI PAGA LA TARI &#8211; dal 22\/03 al 31\/07\/2017\u00a0 &#8211; chi si registra CITTAPULITA.NET parteciper\u00e0 all\u2019estrazione di 5 buoni per azzerare la bolletta. E&#8217; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-21T15:33:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/CITTA_PULITA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"135\" \/>\n\t<meta property=\"og:image:height\" content=\"92\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"VENERDI&#8217; 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO.\",\"datePublished\":\"2017-03-21T15:33:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/\"},\"wordCount\":351,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/03\\\/CITTA_PULITA.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/\",\"name\":\"VENERDI' 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO. - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/03\\\/CITTA_PULITA.jpg\",\"datePublished\":\"2017-03-21T15:33:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/03\\\/CITTA_PULITA.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/03\\\/CITTA_PULITA.jpg\",\"width\":135,\"height\":92},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/03\\\/21\\\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VENERDI&#8217; 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VENERDI' 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO. - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/","og_locale":"it_IT","og_type":"article","og_title":"VENERDI' 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO. - Ferentino","og_description":"PARTE IL CONCORSO A PREMI LAVORGNA TI PAGA LA TARI &#8211; dal 22\/03 al 31\/07\/2017\u00a0 &#8211; chi si registra CITTAPULITA.NET parteciper\u00e0 all\u2019estrazione di 5 buoni per azzerare la bolletta. E&#8217; [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-03-21T15:33:23+00:00","og_image":[{"width":135,"height":92,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/CITTA_PULITA.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"VENERDI&#8217; 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO.","datePublished":"2017-03-21T15:33:23+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/"},"wordCount":351,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/CITTA_PULITA.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/","name":"VENERDI' 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO. - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/CITTA_PULITA.jpg","datePublished":"2017-03-21T15:33:23+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/CITTA_PULITA.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/03\/CITTA_PULITA.jpg","width":135,"height":92},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/03\/21\/venerdi-24-marzo-ore-11-00-conferenza-stampa-concorso-la-tari-in-omaggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"VENERDI&#8217; 24 MARZO ORE 11.00 CONFERENZA STAMPA: CONCORSO LA TARI IN OMAGGIO."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/341\/revisions"}],"predecessor-version":[{"id":344,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/341\/revisions\/344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/342"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}