{"id":3751,"date":"2020-01-23T14:10:43","date_gmt":"2020-01-23T13:10:43","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=3751"},"modified":"2020-01-23T14:04:18","modified_gmt":"2020-01-23T13:04:18","slug":"piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/","title":{"rendered":"Piano di intervento operativo per il risanamento della qualit\u00e0 dell&#8217;aria. Interventi emergenziali.  Fase 1"},"content":{"rendered":"<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3752\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/01\/ord.-15-del-23.01.20.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/01\/ord.-15-del-23.01.20.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ord. 15 del 23.01.20<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce Allegatiord. 15 del 23.01.20<\/p>\n","protected":false},"author":223,"featured_media":1356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piano di intervento operativo per il risanamento della qualit\u00e0 dell&#039;aria. Interventi emergenziali. Fase 1 - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piano di intervento operativo per il risanamento della qualit\u00e0 dell&#039;aria. Interventi emergenziali. Fase 1 - Ferentino\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce Allegatiord. 15 del 23.01.20\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-23T13:10:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Piano di intervento operativo per il risanamento della qualit\u00e0 dell&#8217;aria. Interventi emergenziali. Fase 1\",\"datePublished\":\"2020-01-23T13:10:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/\"},\"wordCount\":13,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/\",\"name\":\"Piano di intervento operativo per il risanamento della qualit\u00e0 dell'aria. Interventi emergenziali. Fase 1 - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"datePublished\":\"2020-01-23T13:10:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"width\":585,\"height\":439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/01\\\/23\\\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piano di intervento operativo per il risanamento della qualit\u00e0 dell&#8217;aria. Interventi emergenziali. Fase 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piano di intervento operativo per il risanamento della qualit\u00e0 dell'aria. Interventi emergenziali. Fase 1 - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/","og_locale":"it_IT","og_type":"article","og_title":"Piano di intervento operativo per il risanamento della qualit\u00e0 dell'aria. Interventi emergenziali. Fase 1 - Ferentino","og_description":"\ud83d\udcce Allegatiord. 15 del 23.01.20","og_url":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-01-23T13:10:43+00:00","og_image":[{"width":585,"height":439,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Piano di intervento operativo per il risanamento della qualit\u00e0 dell&#8217;aria. Interventi emergenziali. Fase 1","datePublished":"2020-01-23T13:10:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/"},"wordCount":13,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/","url":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/","name":"Piano di intervento operativo per il risanamento della qualit\u00e0 dell'aria. Interventi emergenziali. Fase 1 - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","datePublished":"2020-01-23T13:10:43+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","width":585,"height":439},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/01\/23\/piano-di-intervento-operativo-per-il-risanamento-della-qualita-dellaria-interventi-ai-sensi-dellart-5-2-2-2-2-3-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Piano di intervento operativo per il risanamento della qualit\u00e0 dell&#8217;aria. Interventi emergenziali. Fase 1"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=3751"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3751\/revisions"}],"predecessor-version":[{"id":3753,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3751\/revisions\/3753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1356"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=3751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=3751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=3751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}