{"id":3902,"date":"2020-03-23T09:35:54","date_gmt":"2020-03-23T08:35:54","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=3902"},"modified":"2020-03-23T09:28:56","modified_gmt":"2020-03-23T08:28:56","slug":"ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/","title":{"rendered":"ORDINANZA DEL Ministero  della salute e del Ministero dell&#8217; Interno  per la GESTIONE DELL&#8217;EMERGENZA EPIDEMIOLOGICA DA COVID-2019."},"content":{"rendered":"<p><strong>Ulteriori misure urgenti di contenimento del contagio sull&#8217;intero territorio nazionale<\/strong><\/p>\n<p>\ud83d\udd35 Allo scopo di contrastare e contenere il diffondersi del virus COVID-19, \u00e8 fatto divieto a tutte le persone fisiche di trasferirsi o spostarsi con mezzi di trasporto pubblici o privati in comune diverso da quello in cui si trovano, salvo che per comprovate esigenze lavorative, di assoluta urgenza ovvero per motivi di salute.<\/p>\n<p>\ud83d\udd35 Le disposizioni della presente ordinanza producono effetto dalla data del 22 marzo 2020 .<\/p>\n<p>Allegato file pdf<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3903\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/73727_1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/73727_1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>73727_1<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ulteriori misure urgenti di contenimento del contagio sull&#8217;intero territorio nazionale \ud83d\udd35 Allo scopo di contrastare e contenere il diffondersi del virus COVID-19, \u00e8 fatto divieto a tutte le persone fisiche [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ORDINANZA DEL Ministero della salute e del Ministero dell&#039; Interno per la GESTIONE DELL&#039;EMERGENZA EPIDEMIOLOGICA DA COVID-2019. - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ORDINANZA DEL Ministero della salute e del Ministero dell&#039; Interno per la GESTIONE DELL&#039;EMERGENZA EPIDEMIOLOGICA DA COVID-2019. - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Ulteriori misure urgenti di contenimento del contagio sull&#8217;intero territorio nazionale \ud83d\udd35 Allo scopo di contrastare e contenere il diffondersi del virus COVID-19, \u00e8 fatto divieto a tutte le persone fisiche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T08:35:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"ORDINANZA DEL Ministero della salute e del Ministero dell&#8217; Interno per la GESTIONE DELL&#8217;EMERGENZA EPIDEMIOLOGICA DA COVID-2019.\",\"datePublished\":\"2020-03-23T08:35:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/\"},\"wordCount\":93,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/\",\"name\":\"ORDINANZA DEL Ministero della salute e del Ministero dell' Interno per la GESTIONE DELL'EMERGENZA EPIDEMIOLOGICA DA COVID-2019. - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"datePublished\":\"2020-03-23T08:35:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"width\":585,\"height\":439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/23\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ORDINANZA DEL Ministero della salute e del Ministero dell&#8217; Interno per la GESTIONE DELL&#8217;EMERGENZA EPIDEMIOLOGICA DA COVID-2019.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ORDINANZA DEL Ministero della salute e del Ministero dell' Interno per la GESTIONE DELL'EMERGENZA EPIDEMIOLOGICA DA COVID-2019. - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/","og_locale":"it_IT","og_type":"article","og_title":"ORDINANZA DEL Ministero della salute e del Ministero dell' Interno per la GESTIONE DELL'EMERGENZA EPIDEMIOLOGICA DA COVID-2019. - Ferentino","og_description":"Ulteriori misure urgenti di contenimento del contagio sull&#8217;intero territorio nazionale \ud83d\udd35 Allo scopo di contrastare e contenere il diffondersi del virus COVID-19, \u00e8 fatto divieto a tutte le persone fisiche [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-23T08:35:54+00:00","og_image":[{"width":585,"height":439,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"ORDINANZA DEL Ministero della salute e del Ministero dell&#8217; Interno per la GESTIONE DELL&#8217;EMERGENZA EPIDEMIOLOGICA DA COVID-2019.","datePublished":"2020-03-23T08:35:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/"},"wordCount":93,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/","url":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/","name":"ORDINANZA DEL Ministero della salute e del Ministero dell' Interno per la GESTIONE DELL'EMERGENZA EPIDEMIOLOGICA DA COVID-2019. - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","datePublished":"2020-03-23T08:35:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","width":585,"height":439},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/23\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"ORDINANZA DEL Ministero della salute e del Ministero dell&#8217; Interno per la GESTIONE DELL&#8217;EMERGENZA EPIDEMIOLOGICA DA COVID-2019."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=3902"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3902\/revisions"}],"predecessor-version":[{"id":3905,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3902\/revisions\/3905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1356"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=3902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=3902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=3902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}