{"id":3917,"date":"2020-03-31T15:05:05","date_gmt":"2020-03-31T13:05:05","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=3917"},"modified":"2020-03-31T15:00:09","modified_gmt":"2020-03-31T13:00:09","slug":"sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/","title":{"rendered":"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra &#8216;salva famiglia&#8217;"},"content":{"rendered":"<p align=\"CENTER\"><span style=\"font-size: medium\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3919\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-276x300.jpg\" alt=\"\" width=\"276\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-276x300.jpg 276w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-942x1024.jpg 942w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-768x835.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-1413x1536.jpg 1413w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-680x739.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026.jpg 1472w\" sizes=\"auto, (max-width: 276px) 100vw, 276px\" \/><\/b><\/span><\/p>\n<p>L&#8217;emergenza da Covid-19 non \u00e8 solo sanitaria. Il dramma di cittadini, famiglie, anziani e commercianti \u00e8 anche economico e sociale. Per questo la Giunta di Ferentino ha varato oggi la &#8216;MANOVRA SALVA FAMIGLIA&#8217;.<br \/>\nQueste le misure:<br \/>\n\u2733 sospensione di tutti i tributi comunali (avvisi di accertamento e ingiunzioni di pagamento gi\u00e0 notificati e rateizzazioni in atto) al 30 GIUGNO 2020<br \/>\n\u2733 sospensione\/compensazione\/restituzione delle rette per mensa e trasporto scolastici, asili nido e assistente familiare fino alla ripresa dei servizi<br \/>\n\u2747 spostamento dei versamenti di Tosap e Icp al 30 GIUGNO 2020<br \/>\n\u2734 in valutazione la possibilit\u00e0 di determinare le scadenze per la Tari 2020 e altre misure tributarie a sostegno delle famiglie<\/p>\n<p>Voi continuate a rispettare tutte le misure di sicurezza e restate a casa. Noi ci impegneremo al massimo per sostenervi e aiutarvi con qualunque mezzo a nostra disposizione.<br \/>\nE TUTTI INSIEME CE LA FAREMO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;emergenza da Covid-19 non \u00e8 solo sanitaria. Il dramma di cittadini, famiglie, anziani e commercianti \u00e8 anche economico e sociale. Per questo la Giunta di Ferentino ha varato oggi la [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3917","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra &#039;salva famiglia&#039; - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra &#039;salva famiglia&#039; - Ferentino\" \/>\n<meta property=\"og:description\" content=\"L&#8217;emergenza da Covid-19 non \u00e8 solo sanitaria. Il dramma di cittadini, famiglie, anziani e commercianti \u00e8 anche economico e sociale. Per questo la Giunta di Ferentino ha varato oggi la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-31T13:05:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-276x300.jpg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra &#8216;salva famiglia&#8217;\",\"datePublished\":\"2020-03-31T13:05:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/\"},\"wordCount\":159,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2020\\\/03\\\/IMG-20200330-WA0026-276x300.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/\",\"name\":\"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra 'salva famiglia' - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2020\\\/03\\\/IMG-20200330-WA0026-276x300.jpg\",\"datePublished\":\"2020-03-31T13:05:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2020\\\/03\\\/IMG-20200330-WA0026-276x300.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2020\\\/03\\\/IMG-20200330-WA0026-276x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/03\\\/31\\\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra &#8216;salva famiglia&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra 'salva famiglia' - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra 'salva famiglia' - Ferentino","og_description":"L&#8217;emergenza da Covid-19 non \u00e8 solo sanitaria. Il dramma di cittadini, famiglie, anziani e commercianti \u00e8 anche economico e sociale. Per questo la Giunta di Ferentino ha varato oggi la [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-31T13:05:05+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-276x300.jpg","type":"","width":"","height":""}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra &#8216;salva famiglia&#8217;","datePublished":"2020-03-31T13:05:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/"},"wordCount":159,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-276x300.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/","url":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/","name":"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra 'salva famiglia' - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-276x300.jpg","datePublished":"2020-03-31T13:05:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-276x300.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/03\/IMG-20200330-WA0026-276x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/03\/31\/sospensione-dei-tributi-comunali-e-delle-tariffe-per-mensa-e-trasporto-scolastici-la-giunta-comunale-di-ferentino-vara-la-manovra-salva-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Sospensione dei tributi comunali e delle tariffe per mensa e trasporto scolastici La Giunta comunale di Ferentino vara la manovra &#8216;salva famiglia&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=3917"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3917\/revisions"}],"predecessor-version":[{"id":3920,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3917\/revisions\/3920"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=3917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=3917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=3917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}