{"id":394,"date":"2017-04-05T18:33:55","date_gmt":"2017-04-05T16:33:55","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=394"},"modified":"2017-04-05T18:33:55","modified_gmt":"2017-04-05T16:33:55","slug":"ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/","title":{"rendered":"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI."},"content":{"rendered":"<p style=\"margin-bottom: .0001pt;text-align: justify\"><span style=\"font-family: 'Calibri',sans-serif;color: #222222\">Per il dodicesimo anno consecutivo, il <\/span><span style=\"font-family: 'Calibri',sans-serif;color: #222222\"><strong>rendiconto di gestione, annualit\u00e0 201<\/strong><\/span><span style=\"font-family: 'Calibri',sans-serif;color: #222222\"><strong>6<\/strong>, del Comune di Ferentino chiude con un <strong>avanzo di amministrazione.<\/strong><\/span><\/p>\n<p style=\"margin-bottom: .0001pt;text-align: justify\"><span style=\"font-family: 'Calibri',sans-serif;color: #222222\">\u201cIl nostro \u2013 dice il sindaco, <strong>Antonio Pompeo<\/strong> \u2013 \u00e8 un andamento gestionale consolidato, <strong>la contabilit\u00e0 \u00e8 in ordine e la stabilit\u00e0 assicurata<\/strong>. Abbiamo conseguito questi risultati grazie all\u2019apporto unanime dell\u2019intera amministrazione. Giunta, Consiglio comunale, responsabili dei settori e tutti i dipendenti, hanno saputo dare impulso, spesso superando notevoli difficolt\u00e0. L\u2019ennesimo risultato positivo, ottenuto quest\u2019anno, permette all\u2019amministrazione di compiere <strong>scelte strategiche d\u2019investimento e riservare un\u2019attenzione ancora maggiore ai servizi.<\/strong> Faccio qualche esempio: abbiamo sostenuto con le nostre risorse gli interventi socio-assistenziali, come l\u2019assegno economico per il servizio civico, il progetto SPRAR in collaborazione con molti Comuni limitrofi e un progetto di solidariet\u00e0 per la raccolta di fondi in favore delle popolazioni terremotate. Il Comune ha rispettato l\u2019indicatore di tempestivit\u00e0 dei pagamenti ai creditori e, anzi, ha ancora migliorato rispetto al passato, scendendo a 44 giorni contro i 53 del 2015\u201d. <\/span><\/p>\n<p style=\"margin-bottom: .0001pt;text-align: justify\"><span style=\"font-family: 'Calibri',sans-serif;color: #222222\">\u201cLa quota di avanzo libero \u2013 sostiene l\u2019assessore al Bilancio, Franco Martini \u2013 \u00e8 di 589.819,22 euro. Un risultato oggettivo che vogliamo evidenziare con orgoglio. <strong>Ferentino risulta uno dei migliori Comuni nella tempistica dei pagamenti<\/strong>. Abbiamo agito con la massima prudenza per evitare situazioni di squilibrio, rischi di anticipazione di cassa, e sono stati garantiti tutti i servizi ai cittadini, con un adeguato livello quantitativo e qualitativo, nonostante i tagli ai trasferimenti da parte dello Stato e della Regione.<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-396\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Ferentino-La-Giunta-comunale-3-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Ferentino-La-Giunta-comunale-3-300x198.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/Ferentino-La-Giunta-comunale-3.jpg 670w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per il dodicesimo anno consecutivo, il rendiconto di gestione, annualit\u00e0 2016, del Comune di Ferentino chiude con un avanzo di amministrazione. \u201cIl nostro \u2013 dice il sindaco, Antonio Pompeo \u2013 [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tributi-e-finanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI. - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI. - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Per il dodicesimo anno consecutivo, il rendiconto di gestione, annualit\u00e0 2016, del Comune di Ferentino chiude con un avanzo di amministrazione. \u201cIl nostro \u2013 dice il sindaco, Antonio Pompeo \u2013 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-05T16:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"827\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI.\",\"datePublished\":\"2017-04-05T16:33:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/\"},\"wordCount\":259,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/r_mazzini_7.jpg\",\"articleSection\":[\"Tributi e Finanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/\",\"name\":\"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI. - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/r_mazzini_7.jpg\",\"datePublished\":\"2017-04-05T16:33:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/r_mazzini_7.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/r_mazzini_7.jpg\",\"width\":620,\"height\":827},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/04\\\/05\\\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI. - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI. - Ferentino","og_description":"Per il dodicesimo anno consecutivo, il rendiconto di gestione, annualit\u00e0 2016, del Comune di Ferentino chiude con un avanzo di amministrazione. \u201cIl nostro \u2013 dice il sindaco, Antonio Pompeo \u2013 [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-04-05T16:33:55+00:00","og_image":[{"width":620,"height":827,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI.","datePublished":"2017-04-05T16:33:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/"},"wordCount":259,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","articleSection":["Tributi e Finanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/","name":"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI. - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","datePublished":"2017-04-05T16:33:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","width":620,"height":827},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/04\/05\/ferentino-la-giunta-ha-approvato-il-consuntivo-2016-ancora-una-volta-in-attivo-ridotti-ulteriormente-anche-i-tempi-di-pagamento-ai-creditori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Ferentino, LA GIUNTA HA APPROVATO IL CONSUNTIVO 2016: ANCORA UNA VOLTA IN ATTIVO. RIDOTTI ULTERIORMENTE ANCHE I TEMPI DI PAGAMENTO AI CREDITORI."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=394"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/394\/revisions"}],"predecessor-version":[{"id":397,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/394\/revisions\/397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/395"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}