{"id":3954,"date":"2020-04-13T19:10:16","date_gmt":"2020-04-13T17:10:16","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=3954"},"modified":"2020-04-13T19:03:09","modified_gmt":"2020-04-13T17:03:09","slug":"ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/","title":{"rendered":"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\/04\/2020"},"content":{"rendered":"<p><strong>Modifica e Integrazione all&#8217;Ordinanza del Presidente della Regione Lazio 17 marzo 2020, n. Z00010, recante &#8220;Ulteriori misure per la prevenzione e gestione dell&#8217;emergenza epidemiologica da COVID-2019&#8221;, integrata e modificata dall&#8217;Ordinanza del Presidente della Regione Lazio 18 marzo 2020, n. Z00011, recante &#8220;Ordinanza ai sensi dell&#8217;articolo 32, comma 3 della legge 23<\/strong><br \/>\n<strong>dicembre 1978, n. 833 in materia di igiene e sanit\u00e0 pubblica&#8221;<\/strong><\/p>\n<p>Il provvedimento dispone:<\/p>\n<p>\ud83d\udccc di prorogare al termine del 3 maggio l\u2019efficacia delle seguenti ordinanze:<br \/>\na. ordinanza n. Z0006 del 10 marzo 2020;<br \/>\nb. ordinanza n. Z0008 del 13 marzo 2020;<br \/>\nc. ordinanza n. Z0010 del 17 marzo 2020;<br \/>\nd. ordinanza n. Z0011 del 18 marzo 2020;<\/p>\n<p>\ud83d\udccc\u00a0 l\u2019apertura degli esercizi commerciali di qualsiasi dimensione per la vendita di generi alimentari esentati dalla sospensione disposta con DPCM del 10 aprile 2020, compresi gli esercizi interni ai centri commerciali, \u00e8 vietata nelle giornate di sabato 25 aprile 2020 e venerd\u00ec 1 maggio 2020, ad eccezione dei centri agroalimentari all\u2019ingrosso, delle farmacie, parafarmacie, edicole, tabaccai e aree di servizio.<\/p>\n<p>\ud83d\udccc di differire al 20 aprile 2020 la riapertura delle attivit\u00e0 di vendita di libri al dettaglio allo scopo di consentire l\u2019organizzazione da parte degli esercenti di ogni misura atta ad assicurare il distanziamento minimo tra le persone nell\u2019accesso, nel deflusso e durante la presenza nei locali commerciali, il reperimento dei guanti monouso da distribuire all\u2019ingresso nonch\u00e9 di ogni altro prodotto per effettuare l\u2019igienizzazione dei locali;<\/p>\n<p>\ud83d\udccc di prorogare le disposizioni relative al Mercato ortofrutticolo di Fondi contenute nell\u2019ordinanza n. Z0012 del 19 marzo 2020, come integrata dall\u2019ordinanza n. Z0020 del 27 marzo 2020.<\/p>\n<p>\ud83d\udd35 L\u2019efficacia della presente ordinanza decorre dalla data di pubblicazione ed ha validit\u00e0 fino al 3 maggio 2020, salvo nuovo provvedimento.<\/p>\n<p>&nbsp;<\/p>\n<div>\n<p style=\"text-align: left\">Allegato file pdf<\/p>\n<\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3955\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/04\/BUR-2020-42-0.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/04\/BUR-2020-42-0.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>BUR-2020-42-0<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Modifica e Integrazione all&#8217;Ordinanza del Presidente della Regione Lazio 17 marzo 2020, n. Z00010, recante &#8220;Ulteriori misure per la prevenzione e gestione dell&#8217;emergenza epidemiologica da COVID-2019&#8221;, integrata e modificata dall&#8217;Ordinanza [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":1356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\/04\/2020 - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\/04\/2020 - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Modifica e Integrazione all&#8217;Ordinanza del Presidente della Regione Lazio 17 marzo 2020, n. Z00010, recante &#8220;Ulteriori misure per la prevenzione e gestione dell&#8217;emergenza epidemiologica da COVID-2019&#8221;, integrata e modificata dall&#8217;Ordinanza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-13T17:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\\\/04\\\/2020\",\"datePublished\":\"2020-04-13T17:10:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/\"},\"wordCount\":269,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/\",\"name\":\"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\\\/04\\\/2020 - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"datePublished\":\"2020-04-13T17:10:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/12\\\/ordinanze.jpg\",\"width\":585,\"height\":439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2020\\\/04\\\/13\\\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\\\/04\\\/2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\/04\/2020 - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\/04\/2020 - Ferentino","og_description":"Modifica e Integrazione all&#8217;Ordinanza del Presidente della Regione Lazio 17 marzo 2020, n. Z00010, recante &#8220;Ulteriori misure per la prevenzione e gestione dell&#8217;emergenza epidemiologica da COVID-2019&#8221;, integrata e modificata dall&#8217;Ordinanza [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-04-13T17:10:16+00:00","og_image":[{"width":585,"height":439,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\/04\/2020","datePublished":"2020-04-13T17:10:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/"},"wordCount":269,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/","url":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/","name":"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\/04\/2020 - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","datePublished":"2020-04-13T17:10:16+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/12\/ordinanze.jpg","width":585,"height":439},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2020\/04\/13\/ordinanza-del-presidente-n-z00010-del-17-03-2020-ulteriori-misure-per-la-prevenzione-e-gesione-dellemergenza-epidemiologica-da-covid-2019-2-2-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Ordinanza del Presidente della Regione Lazio n. Z00026 del 13\/04\/2020"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=3954"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3954\/revisions"}],"predecessor-version":[{"id":3959,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/3954\/revisions\/3959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/1356"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=3954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=3954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=3954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}