{"id":4449,"date":"2021-04-19T18:59:40","date_gmt":"2021-04-19T16:59:40","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=4449"},"modified":"2021-04-19T18:54:38","modified_gmt":"2021-04-19T16:54:38","slug":"santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/","title":{"rendered":"SANT&#8217;AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE"},"content":{"rendered":"<p style=\"text-align: left\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4450\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0037-1024x674.jpg\" alt=\"\" width=\"640\" height=\"421\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0037-1024x674.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0037-300x197.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0037-768x505.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0037.jpg 1423w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4451\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0034-1024x730.jpg\" alt=\"\" width=\"640\" height=\"456\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0034-1024x730.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0034-300x214.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0034-768x548.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0034.jpg 1371w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4452\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0036-1024x497.jpg\" alt=\"\" width=\"640\" height=\"311\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0036-1024x497.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0036-300x146.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0036-768x373.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0036-1536x746.jpg 1536w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210419-WA0036.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong><em>Il volto storico dei Pooh si complimenta con Ferentino: citt\u00e0 che non ha mai perso la speranza<\/em><\/strong><br \/>\n<strong><em>Sua e di Stefano D&#8217;Orazio, morto a causa del virus, la canzone diventata un inno alla vita<\/em><\/strong><\/p>\n<p><strong><em>Il sindaco Pompeo: una presenza significativa che testimonia l&#8217;importanza<\/em><\/strong><br \/>\n<strong><em>di combattere contro il virus e il coraggio di chi ha sempre avuto fede<\/em><\/strong><\/p>\n<p>Si \u00e8 aperta con un videomessaggio di Roby Facchinetti, volto storico dei Pooh, la conferenza stampa di presentazione delle celebrazioni in onore di Sant&#8217;Ambrogio, patrono della citt\u00e0 di Ferentino.<br \/>\nNella sala consiliare di piazza Matteotti, alla presenza del sindaco, Antonio Pompeo; dell&#8217;assessore a Cultura e Turismo, Angelica Schietroma; del parroco, don Giuseppe Principali e dei membri della Giunta comunale, l&#8217;artista bergamasco ha sottolineato il grande potere della musica in un momento storico come quello che stiamo vivendo, alle prese con una pandemia che ha spezzato migliaia di vite nel nostro Paese.<br \/>\nUn&#8217;emergenza drammatica per la quale, insieme al suo amico e collega, Stefano D&#8217;Orazio, morto nel novembre scorso a causa del Covid, Facchinetti ha composto il brano &#8216;Rinascer\u00f2 Rinascerai&#8217;, canzone simbolo della speranza e della voglia di rinascita di un intero Paese.<br \/>\n&#8220;Avere come ospite per Sant&#8217;Ambrogio un artista simbolo della lotta al Covid come Roby Facchinetti \u2013 ha spiegato il sindaco Pompeo \u2013 \u00e8 per noi il modo pi\u00f9 vicino e pi\u00f9 sentito di celebrare la ricorrenza del nostro patrono, che per noi \u00e8 stato un faro anche in questi momenti difficili. A lui, lo scorso anno, non potendo festeggiarlo come da consuetudine, affidai le preghiere e le speranze di tutta la comunit\u00e0, in una cerimonia intima, in solitudine ed estremamente carica di significato e di emozione. Quest&#8217;anno, anche se non possiamo ancora tornare ai tradizionali festeggiamenti, abbiamo voluto che fosse ancora pi\u00f9 simbolico il nostro tributo a Sant&#8217;Ambrogio: attraverso la musica, le parole e il vissuto di chi \u00e8 stato testimone oculare della violenza e del dramma legati al Covid. Ha perso un amico e un collega con il quale ha scritto un meraviglioso brano dedicato a Bergamo, la citt\u00e0 italiana pi\u00f9 colpita dal virus e dalla quale abbiamo visto arrivare immagini terribili che non dimenticheremo mai&#8221;.<br \/>\nIl <strong>concerto-evento<\/strong> di <strong>Roby Facchinetti al Monastero di Sant&#8217;Antonio Abate<\/strong> sar\u00e0 trasmesso la sera del <strong>Primo Maggio, a partire dalle ore 21.30, in diretta Facebook sui canali social del sindaco e sulla pagina YouTube del Comune di Ferentino.<\/strong><br \/>\nNell\u2019anteprima del concerto, inoltre, insieme al backstage dell\u2019artista sar\u00e0 trasmesso un video turistico-promozionale della citt\u00e0 di Ferentino, che attraverso una voce narrante consentir\u00e0 di fare un tour nei punti pi\u00f9 belli e suggestivi della citt\u00e0, permettendo di apprezzarne bellezze naturalistiche e storiche, patrimonio artistico e culturale, ricchezze architettoniche e tradizioni enogastronomiche apprezzate in tutta la provincia e anche fuori.<br \/>\nLe celebrazioni per il patrono, per\u00f2, inizieranno <strong>sabato 30 aprile 2021<\/strong>, con una rappresentazione teatrale a cura dell&#8217;associazione culturale &#8216;<strong>Le Strenghe<\/strong>&#8216;, dal titolo &#8216;<strong>Il Centurione Ambrogio<\/strong>&#8216;, anche questa trasmessa sui canali social e sulla pagina Youtube del Comune.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4455\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210415-WA0004-726x1024.jpg\" alt=\"\" width=\"640\" height=\"903\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210415-WA0004-726x1024.jpg 726w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210415-WA0004-213x300.jpg 213w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210415-WA0004-768x1083.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210415-WA0004-1090x1536.jpg 1090w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210415-WA0004.jpg 1135w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Si tratta di uno spettacolo che narra il martirio di Sant&#8217;Ambrogio partendo dal testo che Salvatore Morosini, fratello del compianto don Giuseppe \u2013 medaglia d&#8217;oro al valor militare nel 1945 \u2013 scrisse nel 1930 senza che mai fosse portato in scena prima d&#8217;ora. La rappresentazione avr\u00e0 come interpreti gli allievi del laboratorio teatrale diretto da Cataldo Nalli, in collaborazione con la Pro loco di Ferentino e con la partecipazione della Legio Alatrensis. Le musiche sono dirette dal maestro Donato Cedrone mentre la regia \u00e8 di Cataldo Nalli.<br \/>\nAltra particolarit\u00e0 di questa edizione della festa di Sant&#8217;Ambrogio consister\u00e0 nella presenza di grandi installazioni grafiche, posizionate in punti strategici della citt\u00e0, che riproducono le scene e i momenti storici pi\u00f9 significativi delle celebrazioni in onore del patrono, a partire dagli anni immediatamente successivi al secondo conflitto mondiale e fino ai nostri giorni. Un percorso virtuale che testimonia il profondo sentimento e l&#8217;inossidabile legame della citt\u00e0 di Ferentino al suo Sant&#8217;Ambrogio.<br \/>\nAccanto agli appuntamenti civili, sono stati predisposti anche gli eventi religiosi, con celebrazioni di messe e visite alla statua del Santo, nella cattedrale di Ferentino, rigorosamente organizzati nel pieno rispetto delle regole anti-Covid, con orari e modalit\u00e0 di svolgimento che garantiscono la sicurezza per i fedeli, evitando assembramenti e situazioni di rischio.<br \/>\nA tal proposito, il primo cittadino e il parroco, don Giuseppe, ribadendo la necessit\u00e0 di onorare il patrono, hanno invitato tutti i cittadini a osservare scrupolosamente le norme, gli orari e le prescrizioni affinch\u00e9 tutto possa svolgersi nel modo pi\u00f9 tranquillo e sicuro possibile.<\/p>\n<p>&#8220;Anche se dovremo aspettare ancora per festeggiare Sant&#8217;Ambrogio come abbiamo sempre fatto \u2013 ha sottolineato l&#8217;assessore a Cultura e Turismo, Angelica Schietroma \u2013 quest&#8217;anno la presenza di un artista che ha vissuto sulla propria pelle il dramma del Covid e ha composto il brano simbolo del riscatto e della speranza, ci \u00e8 sembrato il messaggio pi\u00f9 forte che potessimo dare a tutta la comunit\u00e0. Che ha sempre dimostrato di essere forte e solidale anche nei momenti pi\u00f9 bui dell&#8217;emergenza&#8221;.<br \/>\n&#8220;Un modo, infine \u2013 ha concluso il sindaco Pompeo, anche a nome del presidente della Proloco, Luigi Sonni \u2013 di promuovere le bellezze artistiche, storiche, culturali e paesaggistiche della nostra citt\u00e0, attraverso il canale della musica. Noi tutti abbiamo voglia di rinascere: e da qui, dal nostro amatissimo patrono, vogliamo ripartire pi\u00f9 uniti, determinati e coraggiosi che mai. Evviva Sant&#8217;Ambrogio!&#8221;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4458\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210418-WA0012.jpg\" alt=\"\" width=\"649\" height=\"960\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210418-WA0012.jpg 649w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/IMG-20210418-WA0012-203x300.jpg 203w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il volto storico dei Pooh si complimenta con Ferentino: citt\u00e0 che non ha mai perso la speranza Sua e di Stefano D&#8217;Orazio, morto a causa del virus, la canzone diventata [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":4429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SANT&#039;AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SANT&#039;AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Il volto storico dei Pooh si complimenta con Ferentino: citt\u00e0 che non ha mai perso la speranza Sua e di Stefano D&#8217;Orazio, morto a causa del virus, la canzone diventata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-19T16:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/conferenza-stampa-ambrogio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"646\" \/>\n\t<meta property=\"og:image:height\" content=\"980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"SANT&#8217;AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE\",\"datePublished\":\"2021-04-19T16:59:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/\"},\"wordCount\":883,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2021\\\/04\\\/conferenza-stampa-ambrogio.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/\",\"name\":\"SANT'AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2021\\\/04\\\/conferenza-stampa-ambrogio.jpg\",\"datePublished\":\"2021-04-19T16:59:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2021\\\/04\\\/conferenza-stampa-ambrogio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2021\\\/04\\\/conferenza-stampa-ambrogio.jpg\",\"width\":646,\"height\":980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/04\\\/19\\\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SANT&#8217;AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SANT'AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/","og_locale":"it_IT","og_type":"article","og_title":"SANT'AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE - Ferentino","og_description":"Il volto storico dei Pooh si complimenta con Ferentino: citt\u00e0 che non ha mai perso la speranza Sua e di Stefano D&#8217;Orazio, morto a causa del virus, la canzone diventata [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-04-19T16:59:40+00:00","og_image":[{"width":646,"height":980,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/conferenza-stampa-ambrogio.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"SANT&#8217;AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE","datePublished":"2021-04-19T16:59:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/"},"wordCount":883,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/conferenza-stampa-ambrogio.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/","url":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/","name":"SANT'AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/conferenza-stampa-ambrogio.jpg","datePublished":"2021-04-19T16:59:40+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/conferenza-stampa-ambrogio.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/04\/conferenza-stampa-ambrogio.jpg","width":646,"height":980},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2021\/04\/19\/santambrogio-simbolo-della-rinascita-dal-covid-concerto-evento-di-roby-facchinetti-al-monastero-di-s-antonio-abate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"SANT&#8217;AMBROGIO SIMBOLO DELLA RINASCITA DAL COVID : CONCERTO-EVENTO DI ROBY FACCHINETTI AL MONASTERO DI S.ANTONIO ABATE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=4449"}],"version-history":[{"count":7,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4449\/revisions"}],"predecessor-version":[{"id":4461,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4449\/revisions\/4461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/4429"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=4449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=4449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=4449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}