{"id":4609,"date":"2021-09-03T21:10:33","date_gmt":"2021-09-03T19:10:33","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=4609"},"modified":"2021-09-03T21:15:51","modified_gmt":"2021-09-03T19:15:51","slug":"ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/","title":{"rendered":"FERENTINO \u00c8\u2019 &#8230;TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4610\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-728x1024.jpg\" alt=\"\" width=\"640\" height=\"900\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-728x1024.jpg 728w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-213x300.jpg 213w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-768x1081.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-1092x1536.jpg 1092w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015.jpg 1137w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>DAL CENTRO ALLE PERIFERIE TRE SERATE DI MUSICA, CABARET E COMICIT\u00c0<\/strong><br \/>\n<strong>PER CHIUDERE L\u2019ESTATE NEL SEGNO DEL DIVERTIMENTO<\/strong><\/p>\n<p><strong>APPUNTAMENTI IL 17\/18\/19 SETTEMBRE 2021<\/strong><\/p>\n<p>Il sindaco Pompeo: un appuntamento fisso della nostra estate<br \/>\nche quest\u2019anno si snoder\u00e0 in tanti punti della citt\u00e0.<\/p>\n<p>L\u2019appuntamento pi\u00f9 atteso, apprezzato e rinomato non soltanto dalla citt\u00e0 in cui ha visto la luce ma dall\u2019intero territorio provinciale. Dopo lo stop forzato a causa dell\u2019emergenza Covid lo scorso anno, torna alla grande \u2018Ferentino \u00e8\u2019, la manifestazione che chiude l\u2019estate 2021 con un programma delle grandi occasioni.<br \/>\nIeri pomeriggio, nella sala consiliare del palazzo municipale in piazza Matteotti a Ferentino, si \u00e8 svolta la conferenza stampa di presentazione, alla presenza del sindaco Antonio Pompeo; del presidente della Pro Loco, Luciano Fiorini e della stampa accreditata. In collegamento da remoto l\u2019assessore a Cultura e Turismo, Angelica Schietroma e i tanti cittadini e curiosi che hanno seguito la conferenza in diretta streaming sul canale YouTube del Comune di Ferentino e sui profili social del primo cittadino.<\/p>\n<p><strong>LA NOVIT\u00c0<\/strong><\/p>\n<p>Un\u2019iniziativa che torna in citt\u00e0 dopo la pausa dello scorso anno a causa della pandemia e lo fa con una prima grande novit\u00e0: le location. Quest\u2019anno, infatti, gli otto spettacoli in programma per le serate del 17, 18 e 19 settembre si svolgeranno in sei diverse piazze della citt\u00e0, coinvolgendo non solo il centro ma anche le zone periferiche. Un modo per condividere e valorizzare pi\u00f9 angoli di Ferentino che ospita, in un lungo weekend, tanti artisti conosciuti e apprezzati dal grande pubblico.<\/p>\n<p><strong>IL PROGRAMMA<\/strong><\/p>\n<p>Si inizia <strong>VENERD\u00cc 17 SETTEMBRE<\/strong>, alle ore 21.30 in piazzale Collepero, con il concerto di Giuliano Palma, gi\u00e0 frontman del gruppo \u2018Casino Royale\u2019, diventato solista nel 1999 e poi ideatore del progetto musicale dei Bluebeaters. Nel 2013 entra a far parte del cast di Zelig dove viene scelto per la parte musicale e nel 2014 partecipa al Festival di Sanremo con i brani \u2018Un bacio crudele\u2019 e \u2018Cos\u00ec lontano\u2019, piazzandosi all\u2019undicesimo posto.<br \/>\nAlle ore 21.30, in via Paolo Borsellino \u2013 localit\u00e0 Giardino, si potr\u00e0 assistere allo spettacolo \u2018Martufello Show\u2019, il comico di Sezze noto per le sue esilaranti barzellette, gi\u00e0 ospite in occasione della \u2018Tombola online\u2019 nel corso delle passate festivit\u00e0 natalizie.<br \/>\nSempre alle ore 21.30, ma nel piazzale della Chiesa del Sacro Cuore in localit\u00e0 Tofe, andr\u00e0 in scena \u2018Pablo e Pedro Show\u2019, il duo comico formato nel 1994 da Fabrizio Nardi e Nico Di Renzo che con la sua comicit\u00e0 ha fatto impazzire il pubblico di \u2018Colorado caf\u00e8\u2019, \u2018Zelig\u2019 e \u2018Zelig off\u2019.<\/p>\n<p>Si prosegue <strong>SABATO 18 SETTEMBRE<\/strong>, con ben quattro appuntamenti.<br \/>\nAlle ore 21.30, in localit\u00e0 Ponte Grande, con lo spettacolo \u2018Dado Show\u2019, il comico romano Gabriele Pellegrini, volto noto della trasmissione \u2018Zelig\u2019 e vincitore del Premio Massimo Troisi. Nel 2014 partecipa a \u2018Made in Sud\u2019 su Rai Due e dal 2015 inizia la collaborazione con \u2018Servizio Pubblico\u2019 di Michele Santoro. Dal 2017 \u00e8 ospite fisso di \u2018Colorado\u2019.<br \/>\nAlle ore 21.30, in via Casilina \u2013 localit\u00e0 Roana, si ride con \u2018Simone Schettino Show\u2019, mentre alle ore 21.30, in piazzale Collepero, un altro momento di musica con il giovane cantautore romano Briga, che dopo \u2018Amici di Maria De Filippi\u2019, dove nel 2015 si \u00e8 classificato al secondo posto, ha ottenuto il successo, partecipando nel 2019 anche al Festival di Sanremo in coppia con Patty Pravo.<br \/>\nSempre alle 21.30, ma al Campo Cartiera, un altro appuntamento con la comicit\u00e0: \u2018Maurizio Mattioli Show\u2019, anche lui gi\u00e0 ospite di Ferentino nel corso della \u2018Tombola online\u2019 dello scorso Natale.<\/p>\n<p>Si chiude <strong>DOMENICA 19 SETTEMBRE<\/strong>, alle ore 21.30, in piazzale Collepero, con lo spettacolo \u2018Max Giusti Show\u2019, attore, comico, imitatore e conduttore televisivo: un poliedrico showman capitolino.<\/p>\n<p><strong>PER PARTECIPARE<\/strong><\/p>\n<p>Per assistere a tutti gli spettacoli in programma sono necessaria la prenotazione e il green pass, nel rispetto delle vigenti normative anti-Covid. Sar\u00e0 possibile effettuarla con un messaggio WhatsApp al numero 353.3756695 oppure cliccando sul link: https:\/\/www.eventbrite.it\/o\/comune-di-ferentino-3377651453.<\/p>\n<p>\u201cQuello con \u2018Ferentino \u00e8\u2019 \u2013 dicono il sindaco Pompeo e l\u2019assessore Schietroma \u2013 \u00e8 un appuntamento che tutti avevamo voglia di rivivere dopo un lungo e difficile periodo che ci ha tenuti fisicamente lontani. Quest\u2019anno, dunque, non solo siamo orgogliosi di poter riproporre una manifestazione che in ogni edizione ha richiamato una grande presenza di pubblico, ma abbiamo deciso di ampliare il ventaglio delle location, che coinvolgeranno non solo le zone centrali della citt\u00e0 ma anche i quartieri periferici, dando la possibilit\u00e0 di scegliere cosa guardare. Musica, cabaret, comicit\u00e0: un mix che certamente incontrer\u00e0 i gusti di famiglie, ragazzi e anziani in tre serate di grandi artisti, volti noti della televisione e del panorama musicale italiano. Momenti di condivisione e divertimento che, siamo certi \u2013 concludono \u2013 si svolgeranno in totale sicurezza e nel pieno rispetto delle norme anti-Covid, per il piacere e il gusto di tornare a vivere le nostre piazze e di salutare l\u2019estate 2021 nel segno della leggerezza\u201d.<\/p>\n<p>\u201cGrazie alla consueta sinergia tra Comune e Pro Loco \u2013 queste le parole del presidente della Pro Loco, Luciano Fiorini \u2013 portiamo in citt\u00e0 una manifestazione di grande impatto che siamo certi incontrer\u00e0 il favore di tutta la cittadinanza e di quanti verranno a Ferentino per assistere agli spettacoli. Un contenitore che da anni non ha mai deluso le aspettative\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4611\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210903-WA0134-597x1024.jpg\" alt=\"\" width=\"597\" height=\"1024\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210903-WA0134-597x1024.jpg 597w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210903-WA0134-175x300.jpg 175w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210903-WA0134.jpg 753w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4613\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/20210903_181735-1024x788.jpg\" alt=\"\" width=\"640\" height=\"493\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/20210903_181735-1024x788.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/20210903_181735-300x231.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/20210903_181735-768x591.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/20210903_181735-1536x1182.jpg 1536w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/20210903_181735-2048x1576.jpg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>DAL CENTRO ALLE PERIFERIE TRE SERATE DI MUSICA, CABARET E COMICIT\u00c0 PER CHIUDERE L\u2019ESTATE NEL SEGNO DEL DIVERTIMENTO APPUNTAMENTI IL 17\/18\/19 SETTEMBRE 2021 Il sindaco Pompeo: un appuntamento fisso della [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4609","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FERENTINO \u00c8\u2019 ...TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERENTINO \u00c8\u2019 ...TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI - Ferentino\" \/>\n<meta property=\"og:description\" content=\"DAL CENTRO ALLE PERIFERIE TRE SERATE DI MUSICA, CABARET E COMICIT\u00c0 PER CHIUDERE L\u2019ESTATE NEL SEGNO DEL DIVERTIMENTO APPUNTAMENTI IL 17\/18\/19 SETTEMBRE 2021 Il sindaco Pompeo: un appuntamento fisso della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-03T19:10:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-03T19:15:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-728x1024.jpg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"FERENTINO \u00c8\u2019 &#8230;TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI\",\"datePublished\":\"2021-09-03T19:10:33+00:00\",\"dateModified\":\"2021-09-03T19:15:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/\"},\"wordCount\":851,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2021\\\/09\\\/IMG-20210902-WA0015-728x1024.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/\",\"name\":\"FERENTINO \u00c8\u2019 ...TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2021\\\/09\\\/IMG-20210902-WA0015-728x1024.jpg\",\"datePublished\":\"2021-09-03T19:10:33+00:00\",\"dateModified\":\"2021-09-03T19:15:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2021\\\/09\\\/IMG-20210902-WA0015.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2021\\\/09\\\/IMG-20210902-WA0015.jpg\",\"width\":1137,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2021\\\/09\\\/03\\\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERENTINO \u00c8\u2019 &#8230;TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FERENTINO \u00c8\u2019 ...TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/","og_locale":"it_IT","og_type":"article","og_title":"FERENTINO \u00c8\u2019 ...TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI - Ferentino","og_description":"DAL CENTRO ALLE PERIFERIE TRE SERATE DI MUSICA, CABARET E COMICIT\u00c0 PER CHIUDERE L\u2019ESTATE NEL SEGNO DEL DIVERTIMENTO APPUNTAMENTI IL 17\/18\/19 SETTEMBRE 2021 Il sindaco Pompeo: un appuntamento fisso della [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-09-03T19:10:33+00:00","article_modified_time":"2021-09-03T19:15:51+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-728x1024.jpg","type":"","width":"","height":""}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"FERENTINO \u00c8\u2019 &#8230;TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI","datePublished":"2021-09-03T19:10:33+00:00","dateModified":"2021-09-03T19:15:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/"},"wordCount":851,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-728x1024.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/","url":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/","name":"FERENTINO \u00c8\u2019 ...TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015-728x1024.jpg","datePublished":"2021-09-03T19:10:33+00:00","dateModified":"2021-09-03T19:15:51+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2021\/09\/IMG-20210902-WA0015.jpg","width":1137,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2021\/09\/03\/ferentino-e-torna-alla-grande-sei-piazze-per-nove-artisti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"FERENTINO \u00c8\u2019 &#8230;TORNA ALLA GRANDE: SEI PIAZZE PER NOVE ARTISTI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=4609"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4609\/revisions"}],"predecessor-version":[{"id":4616,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4609\/revisions\/4616"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=4609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=4609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=4609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}