{"id":4820,"date":"2022-07-21T17:40:57","date_gmt":"2022-07-21T15:40:57","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=4820"},"modified":"2022-07-21T17:36:30","modified_gmt":"2022-07-21T15:36:30","slug":"fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/","title":{"rendered":"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4821\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-1024x1024.jpg\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-1024x1024.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-300x300.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-150x150.jpg 150w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-768x768.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Torna l&#8217;estate e con essa le serate Visionarie di Fiati in Concerto, che quest&#8217;anno celebrer\u00e0 la sua 17\u00aa edizione dal 21 al 24 luglio, in una formula itinerante ormai sperimentata e apprezzata, per circondarsi del bello di una cittadina che fa della proposta culturale la migliore arma di difesa.<\/p>\n<p>Quattro serate poliedriche. Si inizia in Piazza Matteotti con un\u2019icona della musica jazz e fusion italiana, di caratura mondiale, James Senese JNC con il suo nuovo album James is Back.<\/p>\n<p>Il caldo di quella Napoli, centro di sviluppo culturale, accompagner\u00e0 l&#8217;ascoltatore anche nella seconda serata tra gli ulivi e l&#8217;insostituibile quiete dell&#8217;Orto del Vescovo, con l&#8217;incontro straordinario dei Solis String Quartet e Peppe Servillo nel ricordo di un grande artista, indimenticabile. Carosonamente il loro ultimo progetto del 2022.<\/p>\n<p>Il vascello, la piazza e il sapore di quel sabato estivo senza tempo, faranno da palcoscenico ai Nubras Ensemble, giovani di talento, che circonderanno la vita giovanile di Ferentino con suoni etnici di tradizioni lontane, dai Balcani al Medio Oriente, testimoniando ancora una volta che non ci sono confini, non ci sono forti e non ci sono deboli: c&#8217;\u00e8 solo la vita, con le sue regole basate, tutte, sul rispetto tra esseri viventi.<\/p>\n<p>Domenica 24 luglio la chiusura, che sar\u00e0 anche un\u2019apertura allo stesso tempo. Apertura di un tour importante che vedr\u00e0 l&#8217;Orchestra di Fiati \u201cCitt\u00e0 di Ferentino\u201d esportare un prodotto made in Italy, OPERA40, in Austria e in Olanda, al concorso mondiale di Kerkrade.<br \/>\nStrumenti popolari, una danzatrice, un attore, una voce narrante, un quintetto vocale, cento strumentisti sul palco, cinque compositori, un video artista e musiche scritte per l&#8217;occasione convergono in un\u2019idea completamente nuova e travolgente di un grande lavoro intermediale.<br \/>\nCommissionata appositamente per festeggiare il quarantesimo anniversario di fondazione della formazione gigliata, OPERA40 slitta di un anno a causa della pandemia, ma ora \u00e8 finalmente giunto il suo momento. Tutto questo accadr\u00e0 in Piazza Mazzini, dove si torna dopo ben tre anni. E con l&#8217;occasione si ricorder\u00e0 colui che in quel luogo avr\u00e0 sempre una sedia occupata: Luigi Sonni.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Torna l&#8217;estate e con essa le serate Visionarie di Fiati in Concerto, che quest&#8217;anno celebrer\u00e0 la sua 17\u00aa edizione dal 21 al 24 luglio, in una formula itinerante ormai sperimentata [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4820","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Torna l&#8217;estate e con essa le serate Visionarie di Fiati in Concerto, che quest&#8217;anno celebrer\u00e0 la sua 17\u00aa edizione dal 21 al 24 luglio, in una formula itinerante ormai sperimentata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-21T15:40:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-1024x1024.jpg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO\",\"datePublished\":\"2022-07-21T15:40:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/\"},\"wordCount\":351,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2022\\\/07\\\/IMG-20220720-WA0075-1024x1024.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/\",\"name\":\"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2022\\\/07\\\/IMG-20220720-WA0075-1024x1024.jpg\",\"datePublished\":\"2022-07-21T15:40:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2022\\\/07\\\/IMG-20220720-WA0075.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2022\\\/07\\\/IMG-20220720-WA0075.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/07\\\/21\\\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO - Ferentino","og_description":"Torna l&#8217;estate e con essa le serate Visionarie di Fiati in Concerto, che quest&#8217;anno celebrer\u00e0 la sua 17\u00aa edizione dal 21 al 24 luglio, in una formula itinerante ormai sperimentata [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-07-21T15:40:57+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-1024x1024.jpg","type":"","width":"","height":""}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO","datePublished":"2022-07-21T15:40:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/"},"wordCount":351,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-1024x1024.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/","url":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/","name":"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075-1024x1024.jpg","datePublished":"2022-07-21T15:40:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/07\/IMG-20220720-WA0075.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2022\/07\/21\/fiati-in-concerto-2022-xvii-edizione-il-festival-musicale-dellestate-ferentinate-a-partire-dal-21-luglio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"\u201cFIATI IN CONCERTO\u201d 2022 \u2013 XVII edizione IL FESTIVAL MUSICALE DELL\u2019ESTATE FERENTINATE A PARTIRE DAL 21 LUGLIO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=4820"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4820\/revisions"}],"predecessor-version":[{"id":4822,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4820\/revisions\/4822"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=4820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=4820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=4820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}