{"id":4850,"date":"2022-11-15T14:10:42","date_gmt":"2022-11-15T13:10:42","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=4850"},"modified":"2022-11-15T14:07:29","modified_gmt":"2022-11-15T13:07:29","slug":"provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/","title":{"rendered":"Provvedimenti per il risanamento della qualit\u00e0 dell&#8217;aria ed Interventi programmatici di limitazione del traffico 2022\/2023 &#8211; Ordinanze n. 15 e  n. 16 del 15.11.2022"},"content":{"rendered":"<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_4851\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/11\/ordinanza-n.-15.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/11\/ordinanza-n.-15.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanza n. 15<\/a><\/li>\n<li><a id=\"wpba_attachment_list_4852\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/11\/ordinanza-n.-16.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2022\/11\/ordinanza-n.-16.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanza n. 16<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce Allegatiordinanza n. 15 ordinanza n. 16<\/p>\n","protected":false},"author":223,"featured_media":4027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-4850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Provvedimenti per il risanamento della qualit\u00e0 dell&#039;aria ed Interventi programmatici di limitazione del traffico 2022\/2023 - Ordinanze n. 15 e n. 16 del 15.11.2022 - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provvedimenti per il risanamento della qualit\u00e0 dell&#039;aria ed Interventi programmatici di limitazione del traffico 2022\/2023 - Ordinanze n. 15 e n. 16 del 15.11.2022 - Ferentino\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce Allegatiordinanza n. 15 ordinanza n. 16\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-15T13:10:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/05\/unnamed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"505\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Provvedimenti per il risanamento della qualit\u00e0 dell&#8217;aria ed Interventi programmatici di limitazione del traffico 2022\\\/2023 &#8211; Ordinanze n. 15 e n. 16 del 15.11.2022\",\"datePublished\":\"2022-11-15T13:10:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/\"},\"wordCount\":20,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2020\\\/05\\\/unnamed.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/\",\"name\":\"Provvedimenti per il risanamento della qualit\u00e0 dell'aria ed Interventi programmatici di limitazione del traffico 2022\\\/2023 - Ordinanze n. 15 e n. 16 del 15.11.2022 - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2020\\\/05\\\/unnamed.jpg\",\"datePublished\":\"2022-11-15T13:10:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2020\\\/05\\\/unnamed.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2020\\\/05\\\/unnamed.jpg\",\"width\":505,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2022\\\/11\\\/15\\\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provvedimenti per il risanamento della qualit\u00e0 dell&#8217;aria ed Interventi programmatici di limitazione del traffico 2022\\\/2023 &#8211; Ordinanze n. 15 e n. 16 del 15.11.2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provvedimenti per il risanamento della qualit\u00e0 dell'aria ed Interventi programmatici di limitazione del traffico 2022\/2023 - Ordinanze n. 15 e n. 16 del 15.11.2022 - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/","og_locale":"it_IT","og_type":"article","og_title":"Provvedimenti per il risanamento della qualit\u00e0 dell'aria ed Interventi programmatici di limitazione del traffico 2022\/2023 - Ordinanze n. 15 e n. 16 del 15.11.2022 - Ferentino","og_description":"\ud83d\udcce Allegatiordinanza n. 15 ordinanza n. 16","og_url":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-11-15T13:10:42+00:00","og_image":[{"width":505,"height":512,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/05\/unnamed.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Provvedimenti per il risanamento della qualit\u00e0 dell&#8217;aria ed Interventi programmatici di limitazione del traffico 2022\/2023 &#8211; Ordinanze n. 15 e n. 16 del 15.11.2022","datePublished":"2022-11-15T13:10:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/"},"wordCount":20,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/05\/unnamed.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/","url":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/","name":"Provvedimenti per il risanamento della qualit\u00e0 dell'aria ed Interventi programmatici di limitazione del traffico 2022\/2023 - Ordinanze n. 15 e n. 16 del 15.11.2022 - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/05\/unnamed.jpg","datePublished":"2022-11-15T13:10:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/05\/unnamed.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2020\/05\/unnamed.jpg","width":505,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2022\/11\/15\/provvedimenti-per-il-risanamento-della-qualita-dellaria-e-interventi-programmatici-di-limitazione-del-traffico2022-2023-ordinanze-n-15-e-n-16-del-15-11-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Provvedimenti per il risanamento della qualit\u00e0 dell&#8217;aria ed Interventi programmatici di limitazione del traffico 2022\/2023 &#8211; Ordinanze n. 15 e n. 16 del 15.11.2022"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=4850"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4850\/revisions"}],"predecessor-version":[{"id":4855,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4850\/revisions\/4855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/4027"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=4850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=4850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=4850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}