{"id":4871,"date":"2023-06-14T10:42:33","date_gmt":"2023-06-14T08:42:33","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=4871"},"modified":"2023-06-14T10:47:57","modified_gmt":"2023-06-14T08:47:57","slug":"borse-di-studio-io-studio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/","title":{"rendered":"BORSE DI STUDIO"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h1 style=\"text-align: center\"><strong>\u00a0 \u00a0C\u00a0 O\u00a0 M\u00a0 U\u00a0 N\u00a0 E\u00a0\u00a0\u00a0\u00a0 DI\u00a0 \u00a0 \u00a0 F\u00a0 E\u00a0 R\u00a0 E\u00a0 N\u00a0 T\u00a0 I\u00a0 N\u00a0 O<\/strong><\/h1>\n<p style=\"text-align: center\"><strong>Provincia di Frosinone<\/strong><\/p>\n<h2 style=\"text-align: center\"><strong><em>\u00a0<\/em><\/strong><\/h2>\n<h2 style=\"text-align: center\"><strong><em>ASSESSORATO ALLA\u00a0 PUBBLICA\u00a0 ISTRUZIONE <\/em><\/strong><\/h2>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<h2 style=\"text-align: center\"><strong>BORSE DI STUDIO \u201cIO STUDIO\u201d<\/strong><\/h2>\n<p style=\"text-align: center\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong>A.S. 2022\/2023 <\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>IL RESPONSABILE DEL SETTORE N. 2<\/strong><\/p>\n<p style=\"text-align: center\"><strong>Visto<\/strong> il D.Lgs. 13 aprile 2017, n. 63 che ha istituito, presso il Ministero dell\u2019Istruzione, dell\u2019Universit\u00e0 e della Ricerca (MIUR), il \u201cFondo unico per il welfare dello studente e per il diritto allo\u00a0 studio\u201d per l&#8217;erogazione <strong>di BORSE DI STUDIO<\/strong> a favore degli studenti iscritti negli istituti di istruzione\u00a0 scolastiche\u00a0 di secondo grado, al fine di contrastare il fenomeno della dispersione scolastica;<\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>Vista <\/strong>la deliberazione della Giunta Regionale per il Lazio n.252 del01.06.20233, avente oggetto \u201cAttuazione Decreto del Ministero dell\u2019Istruzione, dell\u2019Universit\u00e0 e della Ricerca 7 marzo 2023, n 44. Disciplina delle modalit\u00e0 di individuazione dei beneficiari e criteri\u00a0 per l\u2019erogazione delle borse di studio in favore degli studenti residenti nella Regione Lazio e frequentanti le scuole secondarie di 2\u00b0 grado\u00a0 statali e paritarie o i percorsi <u>triennali<\/u> di I e Fp \u2013anno scolastico <strong>2022-2023<\/strong>\u201d.<\/p>\n<p style=\"text-align: center\"><strong>RENDE NOTO <\/strong><\/p>\n<p style=\"text-align: center\">La pubblicazione del presente Bando \u2013 Borse di Studio \u2013 \u201cIo Studio\u201d.<\/p>\n<p style=\"text-align: center\">L&#8217;importo unitario delle borse di studio nella Regione Lazio viene determinato in \u20ac 150,00 rideterminabile in rapporto al numero\u00a0 totale dei richiedenti e alle risorse finanziarie disponibile,\u00a0 nel limite massimo di \u20ac 500,00, come previsto dalle disposizioni ministeriali.<\/p>\n<p style=\"text-align: center\"><strong>REQUISITI DI ACCESSO<\/strong><\/p>\n<p style=\"text-align: center\">Al fine di individuare i beneficiari, si riportano i seguenti\u00a0 requisiti\u00a0 per l\u2019erogazione delle borse di studio in favore degli studenti residenti nella Regione Lazio:<\/p>\n<ul style=\"text-align: center\">\n<li>Residenza nel Comune di Ferentino.<\/li>\n<li>Iscrizione presso le scuole secondarie di 2\u00b0 grado, statali e\/o paritarie, appartenenti al sistema nazionale di istruzione o ai percorsi triennali di I e Fp.<\/li>\n<li>Attestazione I.S.E.E. non superiore a 15.748,78 in corso di validit\u00e0<\/li>\n<li>Fotocopia del documento di riconoscimento, in corso di validit\u00e0 del genitore.<\/li>\n<li>Fotocopia del documento di riconoscimento, in corso di validit\u00e0 dello studente e tessera sanitaria.<\/li>\n<\/ul>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><strong>TERMINE E MODALITA\u2019 DI PRESENTAZIONE DELLE DOMANDE<\/strong><\/p>\n<p style=\"text-align: center\">Per poter presentare la domanda, il relativo schema, dovr\u00e0 essere acquisito on-line, sul sito del Comune di Ferentino <strong>(<\/strong><a href=\"http:\/\/www.comune.ferentino.fr.it\"><strong>www.comune.ferentino.fr.it<\/strong><\/a>)<\/p>\n<p style=\"text-align: center\">Non appena compilate\u00a0 e corredate dalla documentazione allegata,dovr\u00e0 essere presentata al Comune con le seguenti modalit\u00e0:<\/p>\n<ul style=\"text-align: center\">\n<li>Consegnate a mano presso l\u2019ufficio protocollo dell\u2019Ente dal luned\u00ec al venerd\u00ec, dalle ore 9,00 alle ore 12,00.<\/li>\n<\/ul>\n<p style=\"text-align: center\"><strong><u>\u00a0entro e non oltre le ore 12,00 del \u00a030 GIUGNO 2023<\/u><\/strong><\/p>\n<p style=\"text-align: center\"><u>Accertamenti e trattamento dei dati personali<\/u><\/p>\n<p style=\"text-align: center\"><u>\u00a0<\/u><\/p>\n<p style=\"text-align: center\">Ai sensi\u00a0 dell\u2019art.71 comma 1, del D.P.R. 445\/00 l\u2019ente erogatore effettuer\u00e0 accurati controlli, sia a campione, che in tutti i casi in cui\u00a0 vi siano fondati dubbi sulla veridicit\u00e0 delle dichiarazioni rese dal richiedente in sede autocertificazione, anche dopo aver erogato il beneficio.<\/p>\n<p style=\"text-align: center\">A tal fine il richiedente dovr\u00e0 produrre tutta la documentazione richiesta.<\/p>\n<p style=\"text-align: center\">Nel caso di dichiarazioni non veritiere saranno applicate le sanzioni di legge vigenti.<\/p>\n<p style=\"text-align: center\">Si informa che i dati personali volontariamente forniti, necessari per l\u2019istruttoria della pratica, saranno trattati, anche facendo uso di strumenti informatici, al solo fine di consentire l\u2019attivit\u00e0 di valutazione e di erogazione dell\u2019intervento, nel rispetto della vigente normativa (GDPR 679\/2016).<\/p>\n<p style=\"text-align: center\">Ferentino, l\u00ec \u00a013.06.2023<\/p>\n<h5 style=\"text-align: left\">\u00a0L\u2019ASSESSORE ALLA P.I.<\/h5>\n<h5>F.to \u00a0Proff.ssa\u00a0 Pierina Dominici<\/h5>\n<h5 style=\"text-align: left\">IL RESPONSABILE DEL SETTORE\u00a0 N\u00b02<\/h5>\n<h5>F.to\u00a0\u00a0\u00a0 Dott.\u00a0 Domenico Spilabotte<\/h5>\n<p style=\"text-align: center\">\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_4872\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/06\/borse-studio.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/06\/borse-studio.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>borse di studio \"Io Studio\"<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00a0 \u00a0C\u00a0 O\u00a0 M\u00a0 U\u00a0 N\u00a0 E\u00a0\u00a0\u00a0\u00a0 DI\u00a0 \u00a0 \u00a0 F\u00a0 E\u00a0 R\u00a0 E\u00a0 N\u00a0 T\u00a0 I\u00a0 N\u00a0 O Provincia di Frosinone \u00a0 ASSESSORATO ALLA\u00a0 PUBBLICA\u00a0 ISTRUZIONE \u00a0 BORSE [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-4871","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BORSE DI STUDIO - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BORSE DI STUDIO - Ferentino\" \/>\n<meta property=\"og:description\" content=\"&nbsp; \u00a0 \u00a0C\u00a0 O\u00a0 M\u00a0 U\u00a0 N\u00a0 E\u00a0\u00a0\u00a0\u00a0 DI\u00a0 \u00a0 \u00a0 F\u00a0 E\u00a0 R\u00a0 E\u00a0 N\u00a0 T\u00a0 I\u00a0 N\u00a0 O Provincia di Frosinone \u00a0 ASSESSORATO ALLA\u00a0 PUBBLICA\u00a0 ISTRUZIONE \u00a0 BORSE [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-14T08:42:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T08:47:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/06\\\/14\\\/borse-di-studio-io-studio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/06\\\/14\\\/borse-di-studio-io-studio\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"BORSE DI STUDIO\",\"datePublished\":\"2023-06-14T08:42:33+00:00\",\"dateModified\":\"2023-06-14T08:47:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/06\\\/14\\\/borse-di-studio-io-studio\\\/\"},\"wordCount\":526,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/06\\\/14\\\/borse-di-studio-io-studio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/06\\\/14\\\/borse-di-studio-io-studio\\\/\",\"name\":\"BORSE DI STUDIO - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"datePublished\":\"2023-06-14T08:42:33+00:00\",\"dateModified\":\"2023-06-14T08:47:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/06\\\/14\\\/borse-di-studio-io-studio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/06\\\/14\\\/borse-di-studio-io-studio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/06\\\/14\\\/borse-di-studio-io-studio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BORSE DI STUDIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BORSE DI STUDIO - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/","og_locale":"it_IT","og_type":"article","og_title":"BORSE DI STUDIO - Ferentino","og_description":"&nbsp; \u00a0 \u00a0C\u00a0 O\u00a0 M\u00a0 U\u00a0 N\u00a0 E\u00a0\u00a0\u00a0\u00a0 DI\u00a0 \u00a0 \u00a0 F\u00a0 E\u00a0 R\u00a0 E\u00a0 N\u00a0 T\u00a0 I\u00a0 N\u00a0 O Provincia di Frosinone \u00a0 ASSESSORATO ALLA\u00a0 PUBBLICA\u00a0 ISTRUZIONE \u00a0 BORSE [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-06-14T08:42:33+00:00","article_modified_time":"2023-06-14T08:47:57+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"BORSE DI STUDIO","datePublished":"2023-06-14T08:42:33+00:00","dateModified":"2023-06-14T08:47:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/"},"wordCount":526,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/","url":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/","name":"BORSE DI STUDIO - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"datePublished":"2023-06-14T08:42:33+00:00","dateModified":"2023-06-14T08:47:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/06\/14\/borse-di-studio-io-studio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"BORSE DI STUDIO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=4871"}],"version-history":[{"count":7,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4871\/revisions"}],"predecessor-version":[{"id":4879,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4871\/revisions\/4879"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=4871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=4871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=4871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}