{"id":4895,"date":"2023-07-12T18:05:13","date_gmt":"2023-07-12T16:05:13","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=4895"},"modified":"2023-07-12T18:05:13","modified_gmt":"2023-07-12T16:05:13","slug":"convocazione-commissione-consulta-delle-associazioni","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/","title":{"rendered":"Convocazione Commissione Consulta delle Associazioni"},"content":{"rendered":"<p>Consulta delle Associazioni, che si terr\u00e0 mercoled\u00ec 19 luglio prossimo, alle ore 17:30, presso la sala consiglio comunale. Un organo fondamentale per discutere importanti questioni riguardanti le attivit\u00e0 associative del nostro territorio. Si dar\u00e0 il via alla prima fase per la costituzione della consulta delle associazioni, daremo inizio istituendo l\u2019albo delle associazioni presenti sul territorio, ogni associazione avr\u00e0 una categoria di appartenenza e di lavoro in base allo scopo sociale. Nella convocazione successiva dopo l\u2019adesione di tutte le associazioni che vorranno partecipare alla consulta si proceder\u00e0 all\u2019elezione degli organismi dirigenti.<\/p>\n<p>\u201cL&#8217;importanza delle nostre Associazioni nel tessuto sociale di Ferentino \u00e8 indiscutibile, e siamo certi che la partecipazione attiva alla Consulta delle associazioni contribuir\u00e0 alla promozione di un dialogo costruttivo e alla definizione di strategie condivise per lo sviluppo delle attivit\u00e0 associative nella nostra citt\u00e0\u201d dichiara il Vice Sindaco con delega all&#8217;associazionismo Andrea Pro.<br \/>\n\u201cPertanto, invitiamo tutte le associazioni della nostra citt\u00e0 a prendere parte a questo incontro al fine di\u00a0 e contribuire al processo decisionale.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consulta delle Associazioni, che si terr\u00e0 mercoled\u00ec 19 luglio prossimo, alle ore 17:30, presso la sala consiglio comunale. Un organo fondamentale per discutere importanti questioni riguardanti le attivit\u00e0 associative del [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-4895","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione Commissione Consulta delle Associazioni - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione Commissione Consulta delle Associazioni - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Consulta delle Associazioni, che si terr\u00e0 mercoled\u00ec 19 luglio prossimo, alle ore 17:30, presso la sala consiglio comunale. Un organo fondamentale per discutere importanti questioni riguardanti le attivit\u00e0 associative del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-12T16:05:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/07\\\/12\\\/convocazione-commissione-consulta-delle-associazioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/07\\\/12\\\/convocazione-commissione-consulta-delle-associazioni\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Convocazione Commissione Consulta delle Associazioni\",\"datePublished\":\"2023-07-12T16:05:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/07\\\/12\\\/convocazione-commissione-consulta-delle-associazioni\\\/\"},\"wordCount\":170,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/07\\\/12\\\/convocazione-commissione-consulta-delle-associazioni\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/07\\\/12\\\/convocazione-commissione-consulta-delle-associazioni\\\/\",\"name\":\"Convocazione Commissione Consulta delle Associazioni - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"datePublished\":\"2023-07-12T16:05:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/07\\\/12\\\/convocazione-commissione-consulta-delle-associazioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/07\\\/12\\\/convocazione-commissione-consulta-delle-associazioni\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/07\\\/12\\\/convocazione-commissione-consulta-delle-associazioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione Commissione Consulta delle Associazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione Commissione Consulta delle Associazioni - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione Commissione Consulta delle Associazioni - Ferentino","og_description":"Consulta delle Associazioni, che si terr\u00e0 mercoled\u00ec 19 luglio prossimo, alle ore 17:30, presso la sala consiglio comunale. Un organo fondamentale per discutere importanti questioni riguardanti le attivit\u00e0 associative del [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-07-12T16:05:13+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Convocazione Commissione Consulta delle Associazioni","datePublished":"2023-07-12T16:05:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/"},"wordCount":170,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/","url":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/","name":"Convocazione Commissione Consulta delle Associazioni - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"datePublished":"2023-07-12T16:05:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/07\/12\/convocazione-commissione-consulta-delle-associazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Convocazione Commissione Consulta delle Associazioni"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=4895"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4895\/revisions"}],"predecessor-version":[{"id":4896,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/4895\/revisions\/4896"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=4895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=4895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=4895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}