{"id":5106,"date":"2023-12-04T15:30:50","date_gmt":"2023-12-04T14:30:50","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=5106"},"modified":"2023-12-04T15:30:50","modified_gmt":"2023-12-04T14:30:50","slug":"la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/","title":{"rendered":"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il  convegno al &#8220;Filetico&#8221;"},"content":{"rendered":"<h6>\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, si \u00e8 svolto venerd\u00ec scorso, 1 dicembre 2023 presso il Salone di Rappresentanza del Liceo Martino &#8220;Filetico&#8221; di Ferentino il convegno voluto dall\u2019associazione Idee dal Futuro, sostenuta dal Comune di Ferentino, che nasce per raccontare l\u2019avventura di 12 ragazze e ragazzi con disabilita\u2019 intellettive che per 5 mesi con un progetto d\u2019inclusione sociale hanno lavorato, attraverso stage gratuiti, in altrettante aziende ed enti del territorio.<\/h6>\n<hr \/>\n<p>Oltre ad affrontare le tematiche d\u2019inclusione sociale nel lavoro, con le autorit\u00e0 presenti, si \u00e8 svolta la cerimonia di premiazione per i 12 giovani \u201clavoratori speciali&#8221; e per le aziende, associazioni, enti \u201cospitanti\u201d e sostenitori che hanno creduto in questo bel percorso intrapreso.<br \/>\nOltre al sindaco di Ferentino, Piergianni Fiorletta, e al promotore, il consigliere comunale Maurizio Berretta, presenti tra gli altri i consiglieri comunali Galazzi, Zaccari e Vittori e l&#8217;assessore alle Pari Opportunit\u00e0, Dominici. Altre autorit\u00e0 intervenute, il presidente del Consiglio Provinciale, Gianluca Quadrini, il presidente del consiglio comunale di Veroli, Cristina Verro, il vice sindaco di Sgurgola, Mario Cellitti, l&#8217;assessore Bompiani di Supino, l&#8217;assessore Silvestri di Morolo e l&#8217;assessore De Lellis di Anagni. A loro si aggiungano rappresentanti del 2\u00b0 Comprensivo di Ferentino, le professoresse Incelli e Masseti dell&#8217;Itis Morosini di Ferentino, Samuel Batttaglini, membro cda &#8220;Frosinone F<a href=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-5107 size-medium\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n-300x225.jpeg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n-768x576.jpeg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n.jpeg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>ormazione&#8221; e Walter Bocanelli, direttore Cfp Frosinone.<br \/>\nTra gli interventi di rilevante importanza quelli della professoressa Sara Colatosti dirigente scolastico del &#8220;Martino Filetico&#8221; e della dottoressa Angela Marone dirigente scolastico 1\u00b0 Istituto Comprensivo di Ferentino.<br \/>\nGrazie a tutti i presenti per l&#8217;ottima riuscita della manifestazione.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, si \u00e8 svolto venerd\u00ec scorso, 1 dicembre 2023 presso il Salone di Rappresentanza del Liceo Martino &#8220;Filetico&#8221; di Ferentino il convegno voluto dall\u2019associazione [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":5107,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-5106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al &quot;Filetico&quot; - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al &quot;Filetico&quot; - Ferentino\" \/>\n<meta property=\"og:description\" content=\"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, si \u00e8 svolto venerd\u00ec scorso, 1 dicembre 2023 presso il Salone di Rappresentanza del Liceo Martino &#8220;Filetico&#8221; di Ferentino il convegno voluto dall\u2019associazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T14:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al &#8220;Filetico&#8221;\",\"datePublished\":\"2023-12-04T14:30:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/\"},\"wordCount\":263,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2023\\\/12\\\/408213534_256276707455132_5184093392870844949_n.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/\",\"name\":\"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al \\\"Filetico\\\" - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2023\\\/12\\\/408213534_256276707455132_5184093392870844949_n.jpeg\",\"datePublished\":\"2023-12-04T14:30:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2023\\\/12\\\/408213534_256276707455132_5184093392870844949_n.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2023\\\/12\\\/408213534_256276707455132_5184093392870844949_n.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2023\\\/12\\\/04\\\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al &#8220;Filetico&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al \"Filetico\" - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al \"Filetico\" - Ferentino","og_description":"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, si \u00e8 svolto venerd\u00ec scorso, 1 dicembre 2023 presso il Salone di Rappresentanza del Liceo Martino &#8220;Filetico&#8221; di Ferentino il convegno voluto dall\u2019associazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-12-04T14:30:50+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n.jpeg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al &#8220;Filetico&#8221;","datePublished":"2023-12-04T14:30:50+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/"},"wordCount":263,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/","url":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/","name":"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al \"Filetico\" - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n.jpeg","datePublished":"2023-12-04T14:30:50+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n.jpeg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2023\/12\/408213534_256276707455132_5184093392870844949_n.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2023\/12\/04\/la-nostra-abilita-nel-mondo-del-lavoro-il-convegno-al-filetico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"\u201cLa nostra abilita\u2019 nel mondo del lavoro\u201d, il convegno al &#8220;Filetico&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/5106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=5106"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/5106\/revisions"}],"predecessor-version":[{"id":5108,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/5106\/revisions\/5108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/5107"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=5106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=5106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=5106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}