{"id":5231,"date":"2024-02-01T07:45:24","date_gmt":"2024-02-01T06:45:24","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=5231"},"modified":"2024-02-01T07:45:24","modified_gmt":"2024-02-01T06:45:24","slug":"giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/","title":{"rendered":"Giornata della Memoria &#8211; Evento alla scuola media Giorgi &#8211; Fracco"},"content":{"rendered":"<p>Si \u00e8 svolto luned\u00ec presso l&#8217;aula magna della Scuola Secondaria di Primo Grado &#8220;Giorgi-Fracco&#8221;.<br \/>\n&#8221; Complimenti a tutti i ragazzi delle classi terze, ai loro Docenti e al Dirigente Luigi Brandi della Scuola Secondaria di Primo Grado Giorgi-Fracco che hanno partecipato attivamente all\u2019incontro per la commemorazione della Giornata della Memoria 2024 &#8211; ha commentato l&#8217;assessore Piera Dominici -. I ragazzi hanno mostrato grande attenzione, compostezza, interesse, sensibilit\u00e0 e preparazione in merito al significativo e importante tema trattato. All\u2019evento, organizzato dall\u2019Amministrazione Comunale e concordato con il Dirigente Luigi Brandi, erano presenti, il Sindaco Piergianni Fiorletta, l\u2019Assessore alla Pubblica Istruzione Piera Dominici, l\u2019Assessore Franco Martini, Il consigliere Comunale Ugo Galassi, Il Dirigente Luigi Brandi e i Docenti. Tutti, nei loro interventi, hanno ribadito l\u2019importanza e il significato di questa giornata che, alla fine della seconda guerra mondiale, con l\u2019abbattimento dei cancelli di Auschwitz da parte dell\u2019esercito sovietico, segna la fine della persecuzione del popolo ebraico, delle leggi razziali e dei crimini commessi in quel periodo buio della nostra storia. La necessit\u00e0 e il dovere di tutti i cittadini e di avere Memoria, di conoscere e studiare quanto di orribile \u00e8 accaduto, affinch\u00e9, \u201csimili eventi non possano mai pi\u00f9 accadere\u201d come dice la stessa Legge istituita in Italia il 20 luglio 2000 e in tutto il mondo dall\u2019ONU nel 2005.<br \/>\nPrendendo spunto dalla lettura e visione del testo \u201cL\u2019Albero di Anne\u201d, che racconta la storia, attraverso le parole dell\u2019Ippocastano che Anne Frank guardava attraverso la finestra del suo rifugio fino al giorno in cui venne portata nel campo di concentramento, i ragazzi realizzeranno il loro Albero della Memoria simbolo di Speranza, colmo di riflessioni sulla Memoria, sul Rispetto, sulla Tolleranza, sull\u2019Altruismo e sulla Pace. L\u2019albero sar\u00e0 collocato presso la Biblioteca Comunale di Ferentino, luogo di studio e di conoscenza, affinch\u00e9 i loro messaggi passano essere visibili a tutti e costituiscano un impegno, per le nuove generazioni, per combattere ogni forma di violenza, di razzismo e di odio.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolto luned\u00ec presso l&#8217;aula magna della Scuola Secondaria di Primo Grado &#8220;Giorgi-Fracco&#8221;. &#8221; Complimenti a tutti i ragazzi delle classi terze, ai loro Docenti e al Dirigente Luigi [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":5232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-5231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giornata della Memoria - Evento alla scuola media Giorgi - Fracco - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata della Memoria - Evento alla scuola media Giorgi - Fracco - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 svolto luned\u00ec presso l&#8217;aula magna della Scuola Secondaria di Primo Grado &#8220;Giorgi-Fracco&#8221;. &#8221; Complimenti a tutti i ragazzi delle classi terze, ai loro Docenti e al Dirigente Luigi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-01T06:45:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2024\/02\/giornatamemoria_scuolamedia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Giornata della Memoria &#8211; Evento alla scuola media Giorgi &#8211; Fracco\",\"datePublished\":\"2024-02-01T06:45:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/\"},\"wordCount\":341,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2024\\\/02\\\/giornatamemoria_scuolamedia.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/\",\"name\":\"Giornata della Memoria - Evento alla scuola media Giorgi - Fracco - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2024\\\/02\\\/giornatamemoria_scuolamedia.jpg\",\"datePublished\":\"2024-02-01T06:45:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2024\\\/02\\\/giornatamemoria_scuolamedia.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2024\\\/02\\\/giornatamemoria_scuolamedia.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2024\\\/02\\\/01\\\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornata della Memoria &#8211; Evento alla scuola media Giorgi &#8211; Fracco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornata della Memoria - Evento alla scuola media Giorgi - Fracco - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/","og_locale":"it_IT","og_type":"article","og_title":"Giornata della Memoria - Evento alla scuola media Giorgi - Fracco - Ferentino","og_description":"Si \u00e8 svolto luned\u00ec presso l&#8217;aula magna della Scuola Secondaria di Primo Grado &#8220;Giorgi-Fracco&#8221;. &#8221; Complimenti a tutti i ragazzi delle classi terze, ai loro Docenti e al Dirigente Luigi [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-02-01T06:45:24+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2024\/02\/giornatamemoria_scuolamedia.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Giornata della Memoria &#8211; Evento alla scuola media Giorgi &#8211; Fracco","datePublished":"2024-02-01T06:45:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/"},"wordCount":341,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2024\/02\/giornatamemoria_scuolamedia.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/","url":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/","name":"Giornata della Memoria - Evento alla scuola media Giorgi - Fracco - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2024\/02\/giornatamemoria_scuolamedia.jpg","datePublished":"2024-02-01T06:45:24+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2024\/02\/giornatamemoria_scuolamedia.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2024\/02\/giornatamemoria_scuolamedia.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2024\/02\/01\/giornata-della-memoria-evento-alla-scuola-media-giorgi-fracco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Giornata della Memoria &#8211; Evento alla scuola media Giorgi &#8211; Fracco"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/5231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=5231"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/5231\/revisions"}],"predecessor-version":[{"id":5233,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/5231\/revisions\/5233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/5232"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=5231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=5231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=5231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}