{"id":821,"date":"2017-08-10T12:35:35","date_gmt":"2017-08-10T10:35:35","guid":{"rendered":"https:\/\/comunicacity.net\/ferentino\/?p=821"},"modified":"2017-08-10T12:35:35","modified_gmt":"2017-08-10T10:35:35","slug":"ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/","title":{"rendered":"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017"},"content":{"rendered":"<p><strong>Il sindaco, Antonio Pompeo<\/strong>: Con affetto auguro a tutte le famiglie buon Ferragosto, periodo che possa riservare a tutti la possibilit\u00e0 di dedicare e trascorrere giorni sereni con i propri cari e avere un meritato riposo. Il mio pensiero e ringraziamento \u00e8 rivolto a coloro che in questi giorni restano a garantire i servizi alla citt\u00e0, per mantenerla pulita, funzionale e soprattutto sicura\u00a0 Il programma degli eventi, predisposto con la Pro Loco, dopo le partecipate serate del Cinema a Piazza Mazzini, prevede eventi ne<strong>l Parco di Villa Gasbarra<\/strong>, in collaborazione e con la disponibilit\u00e0 del<strong>l\u2019Associazione Amici dell\u2019Agricoltura,<\/strong> serate con artisti locali, la bravissima Sabrina Ciocchetti, Oreste Datti e Jason, la comicit\u00e0 della Compagnia delle StreNghe, la serata dedicata a Luigi Tenco, recital del professor Amedeo Di Sora, brillanti protagonisti in uno spazio verde nel centro cittadino.<\/p>\n<p>Cerimonie religiose, come da tradizione, presso la <strong>Basilica Cattedrale, per onorare il patrono Ambrogio<\/strong>, martire sotto Diocleziano nell\u2019agosto del 304 d. C.<\/p>\n<p>Dal <strong>16 al 19 agosto<\/strong> ore 21.30 in Piazza Matteotti, <strong>musiche popolari e tradizionali<\/strong> con i concerti dei gruppi: <strong>DISSONANTI, BRIGALLE\u2019 e del maestro GIULIANO GABRIELE. <\/strong><\/p>\n<p>In Piazza Mazzini,<strong> dal 22 al 26 agosto<\/strong> ore 21.15, <strong>Teatro per Ragazzi<\/strong>, <strong>Ferentino in Fiaba<\/strong>, protagoniste le pi\u00f9 importanti compagnie nazionali di teatro dedicato ai ragazzi, rassegna che si fa considerare per la specificit\u00e0 delle scelte. La rassegna avr\u00e0 una <strong>grande festa, sabato 26 agosto<\/strong> dalle ore 18.00 presso<strong> l\u2019Orto del Vescovo<\/strong>, attori, figuranti, artisti di strada, giocolieri, e in Piazza Mazzini alle ore 21.15 il grande spettacolo <strong>con trampolieri e fuochi \u201cLUPERCOLA\u201d<\/strong> della <strong>Compagnia dell\u2019llex, <\/strong>un vero e proprio festival delle sorprese.<\/p>\n<p>Nello stesso periodo, in Piazza Matteotti, <strong>Bambini in Citt\u00e0<\/strong>, animazione, laboratori, spettacoli, una festa organizzata dalle Associazioni, con il coordinamento dell&#8217;assessorato alla Pubblica Istruzione,\u00a0 per assicurare divertimento per tutte le famiglie. Una programmazione che si prolungher\u00e0 nel mese prossimo, alla rassegna <strong>Ferentino \u00e8 prevista dal 14 al 17 settembre<\/strong>, che per noi rappresenta una vetrina d\u2019eccellenza.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-822\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Locandina-Notti-di-nnote-2017-1-300x157.jpg\" alt=\"\" width=\"805\" height=\"421\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Locandina-Notti-di-nnote-2017-1-300x157.jpg 300w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Locandina-Notti-di-nnote-2017-1-768x401.jpg 768w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Locandina-Notti-di-nnote-2017-1-1024x535.jpg 1024w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Locandina-Notti-di-nnote-2017-1-680x355.jpg 680w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Locandina-Notti-di-nnote-2017-1-800x418.jpg 800w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Locandina-Notti-di-nnote-2017-1.jpg 1169w\" sizes=\"auto, (max-width: 805px) 100vw, 805px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-823\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Villa-Gasbarra-Ferragosto-2017-1-210x300.jpg\" alt=\"\" width=\"295\" height=\"422\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Villa-Gasbarra-Ferragosto-2017-1-210x300.jpg 210w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Villa-Gasbarra-Ferragosto-2017-1.jpg 561w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-818\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Ferentino-in-Fiaba-programma-2017-212x300.jpg\" alt=\"\" width=\"290\" height=\"410\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Ferentino-in-Fiaba-programma-2017-212x300.jpg 212w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Ferentino-in-Fiaba-programma-2017.jpg 564w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-819\" src=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Schermata-2017-08-07-alle-10.25.41-212x300.jpg\" alt=\"\" width=\"292\" height=\"413\" srcset=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Schermata-2017-08-07-alle-10.25.41-212x300.jpg 212w, https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/08\/Schermata-2017-08-07-alle-10.25.41.jpg 565w\" sizes=\"auto, (max-width: 292px) 100vw, 292px\" \/><\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco, Antonio Pompeo: Con affetto auguro a tutte le famiglie buon Ferragosto, periodo che possa riservare a tutti la possibilit\u00e0 di dedicare e trascorrere giorni sereni con i propri [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017 - Ferentino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017 - Ferentino\" \/>\n<meta property=\"og:description\" content=\"Il sindaco, Antonio Pompeo: Con affetto auguro a tutte le famiglie buon Ferragosto, periodo che possa riservare a tutti la possibilit\u00e0 di dedicare e trascorrere giorni sereni con i propri [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferentino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-10T10:35:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"827\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoferentino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoferentino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/\"},\"author\":{\"name\":\"sindacoferentino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"headline\":\"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017\",\"datePublished\":\"2017-08-10T10:35:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/\"},\"wordCount\":326,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/r_mazzini_7.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/\",\"name\":\"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017 - Ferentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/r_mazzini_7.jpg\",\"datePublished\":\"2017-08-10T10:35:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/r_mazzini_7.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/wp-content\\\/uploads\\\/sites\\\/92\\\/2017\\\/04\\\/r_mazzini_7.jpg\",\"width\":620,\"height\":827},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/2017\\\/08\\\/10\\\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/\",\"name\":\"Ferentino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/#\\\/schema\\\/person\\\/cfca4edd45e4a69c4715514c218bef40\",\"name\":\"sindacoferentino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g\",\"caption\":\"sindacoferentino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ferentino\\\/author\\\/sindacoferentino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017 - Ferentino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017 - Ferentino","og_description":"Il sindaco, Antonio Pompeo: Con affetto auguro a tutte le famiglie buon Ferragosto, periodo che possa riservare a tutti la possibilit\u00e0 di dedicare e trascorrere giorni sereni con i propri [&hellip;]","og_url":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/","og_site_name":"Ferentino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-08-10T10:35:35+00:00","og_image":[{"width":620,"height":827,"url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","type":"image\/jpeg"}],"author":"sindacoferentino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoferentino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/"},"author":{"name":"sindacoferentino","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"headline":"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017","datePublished":"2017-08-10T10:35:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/"},"wordCount":326,"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/","url":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/","name":"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017 - Ferentino","isPartOf":{"@id":"https:\/\/comunicacity.net\/ferentino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","datePublished":"2017-08-10T10:35:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/#primaryimage","url":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","contentUrl":"https:\/\/comunicacity.net\/ferentino\/wp-content\/uploads\/sites\/92\/2017\/04\/r_mazzini_7.jpg","width":620,"height":827},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ferentino\/2017\/08\/10\/ferentino-gli-auguri-dellamministrazione-per-il-ferragosto-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ferentino\/"},{"@type":"ListItem","position":2,"name":"Ferentino gli Auguri dell\u2019Amministrazione per il Ferragosto 2017"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ferentino\/#website","url":"https:\/\/comunicacity.net\/ferentino\/","name":"Ferentino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ferentino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ferentino\/#\/schema\/person\/cfca4edd45e4a69c4715514c218bef40","name":"sindacoferentino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21046abd5c50b18c4bcba2cd16e05ad5d44fa44fabe1a51afadf3183c680b5cf?s=96&d=mm&r=g","caption":"sindacoferentino"},"url":"https:\/\/comunicacity.net\/ferentino\/author\/sindacoferentino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/comments?post=821"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/821\/revisions"}],"predecessor-version":[{"id":827,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/posts\/821\/revisions\/827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media\/395"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/media?parent=821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/categories?post=821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ferentino\/wp-json\/wp\/v2\/tags?post=821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}