{"id":43,"date":"2019-12-09T10:19:16","date_gmt":"2019-12-09T09:19:16","guid":{"rendered":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg"},"modified":"2019-12-09T10:19:56","modified_gmt":"2019-12-09T09:19:56","slug":"riserva-del-lago-di-cornino-3","status":"inherit","type":"attachment","link":"https:\/\/comunicacity.net\/forgarianelfriuli\/turismo\/riserva-del-lago-di-cornino\/riserva-del-lago-di-cornino-3\/","title":{"rendered":"Riserva del Lago di Cornino"},"author":282,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-43","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riserva del Lago di Cornino - Forgaria nel Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riserva del Lago di Cornino - Forgaria nel Friuli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Forgaria nel Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-09T09:19:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2019\\\/12\\\/Riserva-del-Lago-di-Cornino-3.jpg\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2019\\\/12\\\/Riserva-del-Lago-di-Cornino-3.jpg\",\"name\":\"Riserva del Lago di Cornino - Forgaria nel Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#website\"},\"datePublished\":\"2019-12-09T09:19:16+00:00\",\"dateModified\":\"2019-12-09T09:19:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2019\\\/12\\\/Riserva-del-Lago-di-Cornino-3.jpg#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2019\\\/12\\\/Riserva-del-Lago-di-Cornino-3.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2019\\\/12\\\/Riserva-del-Lago-di-Cornino-3.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riserva del Lago di Cornino\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/turismo\\\/riserva-del-lago-di-cornino\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Riserva del Lago di Cornino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/\",\"name\":\"Forgaria nel Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riserva del Lago di Cornino - Forgaria nel Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg","og_locale":"it_IT","og_type":"article","og_title":"Riserva del Lago di Cornino - Forgaria nel Friuli","og_url":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg","og_site_name":"Forgaria nel Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2019-12-09T09:19:56+00:00","og_image":[{"width":150,"height":200,"url":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg","url":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg","name":"Riserva del Lago di Cornino - Forgaria nel Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#website"},"datePublished":"2019-12-09T09:19:16+00:00","dateModified":"2019-12-09T09:19:56+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/forgarianelfriuli\/"},{"@type":"ListItem","position":2,"name":"Riserva del Lago di Cornino","item":"https:\/\/comunicacity.net\/forgarianelfriuli\/turismo\/riserva-del-lago-di-cornino\/"},{"@type":"ListItem","position":3,"name":"Riserva del Lago di Cornino"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#website","url":"https:\/\/comunicacity.net\/forgarianelfriuli\/","name":"Forgaria nel Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/forgarianelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/forgarianelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"200\" src=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":150,"height":200,"file":"2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg","sizes":{"thumbnail":{"file":"Riserva-del-Lago-di-Cornino-3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3-150x150.jpg"},"full":{"file":"Riserva-del-Lago-di-Cornino-3.jpg","width":150,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":39,"source_url":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2019\/12\/Riserva-del-Lago-di-Cornino-3.jpg","_links":{"self":[{"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/media\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/users\/282"}],"wp:attached-to":[{"embeddable":true,"post_type":"turismo","id":39,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/turismo\/39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}