{"id":170,"date":"2020-07-08T15:19:00","date_gmt":"2020-07-08T13:19:00","guid":{"rendered":"https:\/\/comunicacity.net\/forgarianelfriuli\/?p=170"},"modified":"2020-07-08T15:20:59","modified_gmt":"2020-07-08T13:20:59","slug":"forgaria-arena","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/","title":{"rendered":"Forgaria Arena"},"content":{"rendered":"<p>Forgaria Arena presenta un programma di serata con musica, teatro, cinema realizzata presso area sportiva Forgaria con inizio ore 21:00. <strong>Prenotazione obbligatoria<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-173\" src=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0001.jpg\" alt=\"\" width=\"875\" height=\"1241\" srcset=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0001.jpg 875w, https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0001-212x300.jpg 212w, https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0001-722x1024.jpg 722w, https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0001-768x1089.jpg 768w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-174\" src=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0002.jpg\" alt=\"\" width=\"875\" height=\"1241\" srcset=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0002.jpg 875w, https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0002-212x300.jpg 212w, https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0002-722x1024.jpg 722w, https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA_page-0002-768x1089.jpg 768w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_171\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/VOLANTINO_FORGARIA_ARENA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>VOLANTINO_FORGARIA_ARENA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Forgaria Arena presenta un programma di serata con musica, teatro, cinema realizzata presso area sportiva Forgaria con inizio ore 21:00. Prenotazione obbligatoria \ud83d\udcce AllegatiVOLANTINO_FORGARIA_ARENA<\/p>\n","protected":false},"author":1,"featured_media":172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Forgaria Arena - Forgaria nel Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Forgaria Arena - Forgaria nel Friuli\" \/>\n<meta property=\"og:description\" content=\"Forgaria Arena presenta un programma di serata con musica, teatro, cinema realizzata presso area sportiva Forgaria con inizio ore 21:00. Prenotazione obbligatoria \ud83d\udcce AllegatiVOLANTINO_FORGARIA_ARENA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/\" \/>\n<meta property=\"og:site_name\" content=\"Forgaria nel Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-08T13:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-08T13:20:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/FORGARIA-ARENA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Forgaria Arena\",\"datePublished\":\"2020-07-08T13:19:00+00:00\",\"dateModified\":\"2020-07-08T13:20:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/\"},\"wordCount\":23,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2020\\\/07\\\/FORGARIA-ARENA.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/\",\"name\":\"Forgaria Arena - Forgaria nel Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2020\\\/07\\\/FORGARIA-ARENA.png\",\"datePublished\":\"2020-07-08T13:19:00+00:00\",\"dateModified\":\"2020-07-08T13:20:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2020\\\/07\\\/FORGARIA-ARENA.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/169\\\/2020\\\/07\\\/FORGARIA-ARENA.png\",\"width\":553,\"height\":437},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/2020\\\/07\\\/08\\\/forgaria-arena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forgaria Arena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/\",\"name\":\"Forgaria nel Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/forgarianelfriuli\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Forgaria Arena - Forgaria nel Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/","og_locale":"it_IT","og_type":"article","og_title":"Forgaria Arena - Forgaria nel Friuli","og_description":"Forgaria Arena presenta un programma di serata con musica, teatro, cinema realizzata presso area sportiva Forgaria con inizio ore 21:00. Prenotazione obbligatoria \ud83d\udcce AllegatiVOLANTINO_FORGARIA_ARENA","og_url":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/","og_site_name":"Forgaria nel Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-07-08T13:19:00+00:00","article_modified_time":"2020-07-08T13:20:59+00:00","og_image":[{"width":553,"height":437,"url":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/FORGARIA-ARENA.png","type":"image\/png"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Forgaria Arena","datePublished":"2020-07-08T13:19:00+00:00","dateModified":"2020-07-08T13:20:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/"},"wordCount":23,"publisher":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/FORGARIA-ARENA.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/","url":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/","name":"Forgaria Arena - Forgaria nel Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/FORGARIA-ARENA.png","datePublished":"2020-07-08T13:19:00+00:00","dateModified":"2020-07-08T13:20:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/#primaryimage","url":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/FORGARIA-ARENA.png","contentUrl":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-content\/uploads\/sites\/169\/2020\/07\/FORGARIA-ARENA.png","width":553,"height":437},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/2020\/07\/08\/forgaria-arena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/forgarianelfriuli\/"},{"@type":"ListItem","position":2,"name":"Forgaria Arena"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#website","url":"https:\/\/comunicacity.net\/forgarianelfriuli\/","name":"Forgaria nel Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/forgarianelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/forgarianelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/forgarianelfriuli\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/forgarianelfriuli\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/posts\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/comments?post=170"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/posts\/170\/revisions"}],"predecessor-version":[{"id":177,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/posts\/170\/revisions\/177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/media\/172"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/media?parent=170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/categories?post=170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/forgarianelfriuli\/wp-json\/wp\/v2\/tags?post=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}