{"id":146,"date":"2018-10-31T12:55:59","date_gmt":"2018-10-31T11:55:59","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?post_type=info&#038;p=146"},"modified":"2018-10-31T13:04:33","modified_gmt":"2018-10-31T12:04:33","slug":"centro-sociale-anziani","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/","title":{"rendered":"Centro Sociale Anziani"},"content":{"rendered":"<p><strong>Presidente<\/strong> Sergio Ronconi<\/p>\n<p><strong>Sede Centro Urbano<\/strong><br \/>\n<i class=\"map marker icon\"><\/i> Piazza della Repubblica<br \/>\n<i class=\"fa fa-phone\"><\/i><a href=\"tel:06 9089535\"> 06 9089535<\/a><br \/>\n<i class=\"fa fa-envelope\"><\/i><a href=\"mailto:csa.formello@libero.it\"> csa.formello@libero.it<\/a><\/p>\n<p><strong>Sede Le Rughe<\/strong><br \/>\n<i class=\"map marker icon\"><\/i> Centro Civico Le Rughe &#8211; Viale America<\/p>\n<p>Il Centro Sociale Anziani, che dal 2006 ha una nuova ampia sede in Piazza della Repubblica, \u00e8 oggi una realt\u00e0 importante e preziosa del nostro Comune. Conta circa 700 iscritti e promuove numerossime attivit\u00e0: soggiorni estivi, visite culturali, corsi di ginnastica dolce, tornei, campagne di prevenzione alle malattie, attivit\u00e0 artistico-manuali e manifestazioni di beneficenza. Inoltre, ogni sabato sera si svolgono serate danzanti con musica dal vivo.<\/p>\n<p><strong>MODALITA&#8217; ISCRIZIONE<\/strong><br \/>\nPossono iscriversi direttamente presso il Centro, versando una simbolica quota associativa, le donne dal 55\u00b0 anno di et\u00e0 &#8211; gli uomini dal 60\u00b0 anno di et\u00e0.<\/p>\n<p><strong>PROGRAMMA ATTIVITA&#8217;<\/strong><br \/>\n<strong>Coro dei Nonni:<\/strong> coro amatoriale, diretto dall&#8221;insegnante Gabriella Costanza, che attualmente conta circa 30 coristi. Partecipa attivamente alle manifestazioni culturali, sociali e sportive del territorio. Le prove si svolgono mercoled\u00ec dalle ore 18.30 alle 20.00.<\/p>\n<p><strong>Laboratorio artistico-manuale<\/strong>: attivit\u00e0 prettamente seguita dalle donne del centro con laboratori di cucito, ricamo e manufatti artigianali. Gli incontri si svolgono tutti i marted\u00ec dalle ore 15.30 alle 18.30.<\/p>\n<p><strong>Attivit\u00e0 motorie<\/strong>: si svolgono presso la palestra comunale e sono articolate in Corso di balli di gruppo (mercoled\u00ec 17.00\/18.30) &#8211; Corso di ginnastica posturale (luned\u00ec-venerd\u00ec ore 17.00\/18.00) &#8211; Ginnastica dolce (luned\u00ec-venerd\u00ec 18.00\/19.00).<\/p>\n<p><strong>Laboratorio teatrale per la terza et\u00e0<\/strong>: attivo da 3 anni, sotto la guida dell&#8217;operatore teatrale Luciano Cuguru &#8211; Associazione Teatro dell&#8217;Irrisolto, prepara i partecipanti alla messa in scena di uno spettacolo da realizzarsi nell&#8221;ambito delle manifestazioni comunali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presidente Sergio Ronconi Sede Centro Urbano Piazza della Repubblica 06 9089535 csa.formello@libero.it Sede Le Rughe Centro Civico Le Rughe &#8211; Viale America Il Centro Sociale Anziani, che dal 2006 ha [&hellip;]<\/p>\n","protected":false},"featured_media":147,"parent":145,"menu_order":1,"template":"","meta":[],"plugin_info":[],"class_list":["post-146","info","type-info","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro Sociale Anziani - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro Sociale Anziani - Formello\" \/>\n<meta property=\"og:description\" content=\"Presidente Sergio Ronconi Sede Centro Urbano Piazza della Repubblica 06 9089535 csa.formello@libero.it Sede Le Rughe Centro Civico Le Rughe &#8211; Viale America Il Centro Sociale Anziani, che dal 2006 ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-31T12:04:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/centro-anziani-Formello.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"135\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/centro-sociale-anziani\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/centro-sociale-anziani\\\/\",\"name\":\"Centro Sociale Anziani - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/centro-sociale-anziani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/centro-sociale-anziani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/centro-anziani-Formello.jpg\",\"datePublished\":\"2018-10-31T11:55:59+00:00\",\"dateModified\":\"2018-10-31T12:04:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/centro-sociale-anziani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/centro-sociale-anziani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/centro-sociale-anziani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/centro-anziani-Formello.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/centro-anziani-Formello.jpg\",\"width\":200,\"height\":135},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/centro-sociale-anziani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spazi Sociali\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/spazi-sociali\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Centro Sociale Anziani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro Sociale Anziani - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/","og_locale":"it_IT","og_type":"article","og_title":"Centro Sociale Anziani - Formello","og_description":"Presidente Sergio Ronconi Sede Centro Urbano Piazza della Repubblica 06 9089535 csa.formello@libero.it Sede Le Rughe Centro Civico Le Rughe &#8211; Viale America Il Centro Sociale Anziani, che dal 2006 ha [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2018-10-31T12:04:33+00:00","og_image":[{"width":200,"height":135,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/centro-anziani-Formello.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/","url":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/","name":"Centro Sociale Anziani - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/centro-anziani-Formello.jpg","datePublished":"2018-10-31T11:55:59+00:00","dateModified":"2018-10-31T12:04:33+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/centro-anziani-Formello.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/centro-anziani-Formello.jpg","width":200,"height":135},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/centro-sociale-anziani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"Spazi Sociali","item":"https:\/\/comunicacity.net\/formello\/info\/spazi-sociali\/"},{"@type":"ListItem","position":3,"name":"Centro Sociale Anziani"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/info\/146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/info"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/info\/145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/147"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=146"}],"wp:term":[{"taxonomy":"plugin_info","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/plugin_info?post=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}