{"id":172,"date":"2018-11-06T12:19:02","date_gmt":"2018-11-06T11:19:02","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?post_type=info&#038;p=172"},"modified":"2021-10-27T09:46:37","modified_gmt":"2021-10-27T07:46:37","slug":"info-trasporto-pubblico","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/","title":{"rendered":"Info trasporto pubblico"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18679 size-large aligncenter\" src=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove-456x1024.png\" alt=\"\" width=\"456\" height=\"1024\" srcset=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove-456x1024.png 456w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove-134x300.png 134w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove.png 652w\" sizes=\"auto, (max-width: 456px) 100vw, 456px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":169,"menu_order":0,"template":"","meta":[],"plugin_info":[],"class_list":["post-172","info","type-info","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Info trasporto pubblico - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Info trasporto pubblico - Formello\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-27T07:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove-456x1024.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/info-trasporto-pubblico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/info-trasporto-pubblico\\\/\",\"name\":\"Info trasporto pubblico - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/info-trasporto-pubblico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/info-trasporto-pubblico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/11\\\/Formello-si-muove-456x1024.png\",\"datePublished\":\"2018-11-06T11:19:02+00:00\",\"dateModified\":\"2021-10-27T07:46:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/info-trasporto-pubblico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/info-trasporto-pubblico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/info-trasporto-pubblico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/11\\\/Formello-si-muove.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/11\\\/Formello-si-muove.png\",\"width\":652,\"height\":1464},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/info-trasporto-pubblico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trasporto pubblico\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/info\\\/trasporto-pubblico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Info trasporto pubblico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Info trasporto pubblico - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/","og_locale":"it_IT","og_type":"article","og_title":"Info trasporto pubblico - Formello","og_url":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2021-10-27T07:46:37+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove-456x1024.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/","url":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/","name":"Info trasporto pubblico - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove-456x1024.png","datePublished":"2018-11-06T11:19:02+00:00","dateModified":"2021-10-27T07:46:37+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove.png","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/11\/Formello-si-muove.png","width":652,"height":1464},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/info-trasporto-pubblico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"Trasporto pubblico","item":"https:\/\/comunicacity.net\/formello\/info\/trasporto-pubblico\/"},{"@type":"ListItem","position":3,"name":"Info trasporto pubblico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/info\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/info"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/info\/169"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"plugin_info","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/plugin_info?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}