{"id":1008,"date":"2019-08-06T17:51:34","date_gmt":"2019-08-06T15:51:34","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1008"},"modified":"2019-08-06T17:51:34","modified_gmt":"2019-08-06T15:51:34","slug":"rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/","title":{"rendered":"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS"},"content":{"rendered":"<p>Finalmente il primo risultato del tavolo di concertazione tra Comune di Formello, Regione LAZIO e ANAS &#8211; comunica il Sindaco <a class=\"profileLink\" title=\"Gian Filippo Santi\" href=\"https:\/\/www.facebook.com\/profile.php?id=100012306004436&amp;__tn__=K-R&amp;eid=ARAlBaBlcyWyLKogz9pVlcZW9tvRgjBmXAI5ixh0TPIdXEXjccoUzdqPV0DZppgZSJdoifh7HKPwDoYh&amp;fref=mentions&amp;__xts__%5B0%5D=68.ARBDbRPEYyAT0OYWzN18VqY_0TxGHl7sw4Dpp2dpq1jM1VfgkWZSM8fqLBlMASYn7CY0zx8QU4r31pRNr1waZ2ulX77hf7719aCm9NEFLq-OWqGqrnOWjWzYWyJYtGhNu3uRJcU24NyUrkGr8cik-RfyUp8wlIkFusOYRwJeTLlVfOsJWvMG2M5RMqcvHILanSxOUCb4-m-2nNBPznLmNt8sZqil4hVqHjWN_ub-lKZkxQM1bNj-EZPElcdsUR9g3go78L7mnDgletRlWSL9WGtYsuVX7wtYkjb2hM-51Bs_5NKAkYokgqxLrObFpk9dX1N2wZ46lxUVyD9SCvy4Ox4yVD82\">Gian Filippo Santi<\/a> &#8211; e presto il protocollo d&#8217;intesa per il controllo e la rimozione dei fenomeni di abbandono dei rifiuti lungo la Cassia Bis, con installazione di videocamere e pene severe per i trasgressori. Un grazie particolare &#8211; conclude il Sindaco &#8211; al Vice Presidente della Regione LAZIO On. <a class=\"profileLink\" title=\"Giuseppe Emanuele Cangemi\" href=\"https:\/\/www.facebook.com\/giuseppeemanuele.cangemi.1?__tn__=K-R&amp;eid=ARBDLeTT2IAiMpwPZY_ez8Hg_qcA-J2hBZvKnxGZx3dJj_87nwLo2q8smFkEeWAaNiznSOwe39LzgGdY&amp;fref=mentions&amp;__xts__%5B0%5D=68.ARBDbRPEYyAT0OYWzN18VqY_0TxGHl7sw4Dpp2dpq1jM1VfgkWZSM8fqLBlMASYn7CY0zx8QU4r31pRNr1waZ2ulX77hf7719aCm9NEFLq-OWqGqrnOWjWzYWyJYtGhNu3uRJcU24NyUrkGr8cik-RfyUp8wlIkFusOYRwJeTLlVfOsJWvMG2M5RMqcvHILanSxOUCb4-m-2nNBPznLmNt8sZqil4hVqHjWN_ub-lKZkxQM1bNj-EZPElcdsUR9g3go78L7mnDgletRlWSL9WGtYsuVX7wtYkjb2hM-51Bs_5NKAkYokgqxLrObFpk9dX1N2wZ46lxUVyD9SCvy4Ox4yVD82\">Giuseppe E<span class=\"text_exposed_show\">manuele Cangemi<\/span><\/a><span class=\"text_exposed_show\"> che si \u00e8 prodigato per la positiva risoluzione dell&#8217;annosa questione.<br \/>\nDi seguito il comunicato stampa del Vicepresidente:<br \/>\n(DIRE) Roma, 6 ago. &#8211; &#8220;Anas ha avviato la rimozione dei cumuli di rifiuti sulla Cassia bis, intervento che avevo sollecitato all`indomani del passaggio dell`arteria dalle competenze regionali a quelle dell`azienda. Il prossimo passo sia l`installazione, quanto prima, di telecamere di sorveglianza per scoraggiare l`abbandono incivile di spazzatura e individuare chi si macchia di un vero e proprio scempio ambientale contro cui ci auguriamo siano applicate pene severe. Basta con le pattumiere a cielo aperto&#8221;. Cosi` in un comunicato il vicepresidente del Consiglio regionale del Lazio, Giuseppe Cangemi. (Comunicati\/Dire<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalmente il primo risultato del tavolo di concertazione tra Comune di Formello, Regione LAZIO e ANAS &#8211; comunica il Sindaco Gian Filippo Santi &#8211; e presto il protocollo d&#8217;intesa per [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":1009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS - Formello\" \/>\n<meta property=\"og:description\" content=\"Finalmente il primo risultato del tavolo di concertazione tra Comune di Formello, Regione LAZIO e ANAS &#8211; comunica il Sindaco Gian Filippo Santi &#8211; e presto il protocollo d&#8217;intesa per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-06T15:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/08\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS\",\"datePublished\":\"2019-08-06T15:51:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/\"},\"wordCount\":191,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/08\\\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/\",\"name\":\"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/08\\\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg\",\"datePublished\":\"2019-08-06T15:51:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/08\\\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/08\\\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/06\\\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/","og_locale":"it_IT","og_type":"article","og_title":"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS - Formello","og_description":"Finalmente il primo risultato del tavolo di concertazione tra Comune di Formello, Regione LAZIO e ANAS &#8211; comunica il Sindaco Gian Filippo Santi &#8211; e presto il protocollo d&#8217;intesa per [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-06T15:51:34+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/08\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS","datePublished":"2019-08-06T15:51:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/"},"wordCount":191,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/08\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/","url":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/","name":"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/08\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg","datePublished":"2019-08-06T15:51:34+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/08\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/08\/5b320485-012a-4fb3-bf99-f60968fd16d7.jpg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/06\/rimossi-i-cumuli-di-rifiuti-sulla-cassia-bis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"RIMOSSI I CUMULI DI RIFIUTI SULLA CASSIA BIS"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1008"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1008\/revisions"}],"predecessor-version":[{"id":1010,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1008\/revisions\/1010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/1009"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}