{"id":1042,"date":"2019-08-23T11:25:01","date_gmt":"2019-08-23T09:25:01","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1042"},"modified":"2019-08-23T11:25:01","modified_gmt":"2019-08-23T09:25:01","slug":"bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/","title":{"rendered":"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA&#8217; 2018"},"content":{"rendered":"<p>Prosegue la realizzazione dei progetti del <strong>Bilancio Partecipato 2018<\/strong>. Dopo il successo di quello sul &#8220;Bullismo e Cyberbullismo&#8221;, al via anche quello sul <strong>&#8220;Premio Natalit\u00e0 2018&#8221;<\/strong>.\u00a0Il 16 agosto sono stati inviati alle 88 famiglie dei bimbi nati nel 2018 gli inviti a riscuotere i 100,00 euro del <strong>Premio Natalit\u00e0<\/strong>.\u00a0&#8220;Vuole essere un segno tangibile di augurio e vicinanza alla\u00a0collettivit\u00e0 per un evento cos\u00ec importante &#8211; commenta <strong>Roberta Mazzoneschi<\/strong>, promotrice del Bilancio Partecipato &#8211; A breve realizzeremo gli altri progetti del 2018 ed avvieremo il Bilancio Partecipato 2019&#8243;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue la realizzazione dei progetti del Bilancio Partecipato 2018. Dopo il successo di quello sul &#8220;Bullismo e Cyberbullismo&#8221;, al via anche quello sul &#8220;Premio Natalit\u00e0 2018&#8221;.\u00a0Il 16 agosto sono stati [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1042","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA&#039; 2018 - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA&#039; 2018 - Formello\" \/>\n<meta property=\"og:description\" content=\"Prosegue la realizzazione dei progetti del Bilancio Partecipato 2018. Dopo il successo di quello sul &#8220;Bullismo e Cyberbullismo&#8221;, al via anche quello sul &#8220;Premio Natalit\u00e0 2018&#8221;.\u00a0Il 16 agosto sono stati [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-23T09:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/23\\\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/23\\\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA&#8217; 2018\",\"datePublished\":\"2019-08-23T09:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/23\\\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\\\/\"},\"wordCount\":93,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/23\\\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/23\\\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\\\/\",\"name\":\"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA' 2018 - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"datePublished\":\"2019-08-23T09:25:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/23\\\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/23\\\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/08\\\/23\\\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA&#8217; 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA' 2018 - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/","og_locale":"it_IT","og_type":"article","og_title":"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA' 2018 - Formello","og_description":"Prosegue la realizzazione dei progetti del Bilancio Partecipato 2018. Dopo il successo di quello sul &#8220;Bullismo e Cyberbullismo&#8221;, al via anche quello sul &#8220;Premio Natalit\u00e0 2018&#8221;.\u00a0Il 16 agosto sono stati [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-23T09:25:01+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/formello\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA&#8217; 2018","datePublished":"2019-08-23T09:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/"},"wordCount":93,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/","url":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/","name":"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA' 2018 - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"datePublished":"2019-08-23T09:25:01+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/08\/23\/bilancio-partecipato-100-euro-alle-famiglie-dei-nati-del-2018-grazie-al-premio-natalita-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"BILANCIO PARTECIPATO: 100 EURO ALLE FAMIGLIE DEI NATI DEL 2018 GRAZIE AL PREMIO NATALITA&#8217; 2018"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1042"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1042\/revisions"}],"predecessor-version":[{"id":1043,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1042\/revisions\/1043"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}