{"id":1080,"date":"2019-09-13T09:00:56","date_gmt":"2019-09-13T07:00:56","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1080"},"modified":"2019-09-13T09:46:50","modified_gmt":"2019-09-13T07:46:50","slug":"a-formello-la-notte-bianca-dello-sport","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/","title":{"rendered":"A FORMELLO LA NOTTE BIANCA DELLO SPORT"},"content":{"rendered":"<p><strong>Sabato 14 settembre <\/strong>Formello ospita la <strong>Notte Bianca dello Sport.<\/strong> E&#8217; questa la terza edizione promossa dall&#8217;assessore allo Sport <strong>Roberta Bellotti<\/strong> in collaborazione con la Pro Loco e il Coni. Durante l&#8217;evento, che ha inizio alle 18 (dalle 19 gli stand gastronomici) nei giardini comunali e nel centro storico, \u00e8 possibile effettuare prove gratuite presso gli stand (gli sport della mente a Palazzo Chigi), nonch\u00e9 visitare la Mostra del Museo del Calcio nella Sala Orsini di Palazzo Chigi. Per informazioni rivolgersi al numero 3381789241 oppure a proloco@prolocoformello.org.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-16399\" src=\"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2019\/09\/IMG-20190904-WA0007-576x1024.jpg\" alt=\"\" width=\"576\" height=\"1024\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 14 settembre Formello ospita la Notte Bianca dello Sport. E&#8217; questa la terza edizione promossa dall&#8217;assessore allo Sport Roberta Bellotti in collaborazione con la Pro Loco e il Coni. [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-1080","post","type-post","status-publish","format-standard","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A FORMELLO LA NOTTE BIANCA DELLO SPORT - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A FORMELLO LA NOTTE BIANCA DELLO SPORT - Formello\" \/>\n<meta property=\"og:description\" content=\"Sabato 14 settembre Formello ospita la Notte Bianca dello Sport. E&#8217; questa la terza edizione promossa dall&#8217;assessore allo Sport Roberta Bellotti in collaborazione con la Pro Loco e il Coni. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-13T07:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-13T07:46:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2019\/09\/IMG-20190904-WA0007-576x1024.jpg\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"A FORMELLO LA NOTTE BIANCA DELLO SPORT\",\"datePublished\":\"2019-09-13T07:00:56+00:00\",\"dateModified\":\"2019-09-13T07:46:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/\"},\"wordCount\":91,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comune.formello.rm.it\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/IMG-20190904-WA0007-576x1024.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/\",\"name\":\"A FORMELLO LA NOTTE BIANCA DELLO SPORT - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comune.formello.rm.it\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/IMG-20190904-WA0007-576x1024.jpg\",\"datePublished\":\"2019-09-13T07:00:56+00:00\",\"dateModified\":\"2019-09-13T07:46:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.comune.formello.rm.it\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/IMG-20190904-WA0007-576x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.comune.formello.rm.it\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/IMG-20190904-WA0007-576x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/09\\\/13\\\/a-formello-la-notte-bianca-dello-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A FORMELLO LA NOTTE BIANCA DELLO SPORT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A FORMELLO LA NOTTE BIANCA DELLO SPORT - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/","og_locale":"it_IT","og_type":"article","og_title":"A FORMELLO LA NOTTE BIANCA DELLO SPORT - Formello","og_description":"Sabato 14 settembre Formello ospita la Notte Bianca dello Sport. E&#8217; questa la terza edizione promossa dall&#8217;assessore allo Sport Roberta Bellotti in collaborazione con la Pro Loco e il Coni. [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-09-13T07:00:56+00:00","article_modified_time":"2019-09-13T07:46:50+00:00","og_image":[{"url":"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2019\/09\/IMG-20190904-WA0007-576x1024.jpg","type":"","width":"","height":""}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"A FORMELLO LA NOTTE BIANCA DELLO SPORT","datePublished":"2019-09-13T07:00:56+00:00","dateModified":"2019-09-13T07:46:50+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/"},"wordCount":91,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2019\/09\/IMG-20190904-WA0007-576x1024.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/","url":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/","name":"A FORMELLO LA NOTTE BIANCA DELLO SPORT - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2019\/09\/IMG-20190904-WA0007-576x1024.jpg","datePublished":"2019-09-13T07:00:56+00:00","dateModified":"2019-09-13T07:46:50+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/#primaryimage","url":"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2019\/09\/IMG-20190904-WA0007-576x1024.jpg","contentUrl":"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2019\/09\/IMG-20190904-WA0007-576x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/09\/13\/a-formello-la-notte-bianca-dello-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"A FORMELLO LA NOTTE BIANCA DELLO SPORT"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1080"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1080\/revisions"}],"predecessor-version":[{"id":1082,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1080\/revisions\/1082"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}