{"id":1267,"date":"2019-11-07T10:50:28","date_gmt":"2019-11-07T09:50:28","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1267"},"modified":"2019-11-07T16:04:31","modified_gmt":"2019-11-07T15:04:31","slug":"santi-eletto-nel-direttivo-dellanci","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/","title":{"rendered":"SANTI ELETTO NEL DIRETTIVO DELL&#8217;ANCI"},"content":{"rendered":"<p>Il sindaco di Formello, <strong>Gian Filippo Santi<\/strong>, \u00e8 stato eletto nel Consiglio direttivo dell&#8217;<strong>Anci (Associazione Nazionale Comuni Italiani)<\/strong> del <strong>Lazio.<\/strong> L&#8217;elezione \u00e8 avvenuta all&#8217;unanimit\u00e0 nell&#8217;assemblea del 6 novembre. Insieme a Santi sono stati eletti: Domenico Alfieri, sindaco di Paliano; Daniela Ballico, sindaco di Ciampino; Michel Barbet, sindaco di Guidonia; Stefano Biagiotti, sindaco di Valentano; Alfredo Campagna, presidente del XIV Municipio di Roma Capitale; Luca D&#8217;Arpino, presidente del Consiglio comunale di Ripi (vicepresidente); Federico Del Baglivo, consigliere di Fonte Nuova; Martina Domenici, sindaco di Castel Sant&#8217;Angelo Romano; Piergianni Fiorletta, consigliere di Ferentino; Ilaria Gatti, sindaco di Pescorocchiano; Alessandro Giulivi, sindaco di Tarquinia (vicepresidente); Alessandro Grando, sindaco di Ladispoli; Monica Lozzi, presidente del VII Municipio di Roma Capitale; Manuel Magliocchetti, consigliere di Palestrina; Giampaolo Nardi, sindaco di Castel San Pietro Romano (vicepresidente); Lina Novelli, sindaco di Canino; Luisa Piacentini, consigliere di Marano Equo; Daniele Sinibaldi, vicesindaco di Rieti (vicepresidente vicario); Antonio Terra, sindaco di Aprilia. All&#8217;Anci aderiscono circa 7.300 Comuni italiani che, nella loro globalit\u00e0, rappresentano circa il 90% della popolazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco di Formello, Gian Filippo Santi, \u00e8 stato eletto nel Consiglio direttivo dell&#8217;Anci (Associazione Nazionale Comuni Italiani) del Lazio. L&#8217;elezione \u00e8 avvenuta all&#8217;unanimit\u00e0 nell&#8217;assemblea del 6 novembre. Insieme a [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":1268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SANTI ELETTO NEL DIRETTIVO DELL&#039;ANCI - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SANTI ELETTO NEL DIRETTIVO DELL&#039;ANCI - Formello\" \/>\n<meta property=\"og:description\" content=\"Il sindaco di Formello, Gian Filippo Santi, \u00e8 stato eletto nel Consiglio direttivo dell&#8217;Anci (Associazione Nazionale Comuni Italiani) del Lazio. L&#8217;elezione \u00e8 avvenuta all&#8217;unanimit\u00e0 nell&#8217;assemblea del 6 novembre. Insieme a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-07T09:50:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-07T15:04:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/11\/output_immagine.php_-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"SANTI ELETTO NEL DIRETTIVO DELL&#8217;ANCI\",\"datePublished\":\"2019-11-07T09:50:28+00:00\",\"dateModified\":\"2019-11-07T15:04:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/\"},\"wordCount\":169,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/11\\\/output_immagine.php_-4.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/\",\"name\":\"SANTI ELETTO NEL DIRETTIVO DELL'ANCI - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/11\\\/output_immagine.php_-4.jpg\",\"datePublished\":\"2019-11-07T09:50:28+00:00\",\"dateModified\":\"2019-11-07T15:04:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/11\\\/output_immagine.php_-4.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/11\\\/output_immagine.php_-4.jpg\",\"width\":240,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/11\\\/07\\\/santi-eletto-nel-direttivo-dellanci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SANTI ELETTO NEL DIRETTIVO DELL&#8217;ANCI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SANTI ELETTO NEL DIRETTIVO DELL'ANCI - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/","og_locale":"it_IT","og_type":"article","og_title":"SANTI ELETTO NEL DIRETTIVO DELL'ANCI - Formello","og_description":"Il sindaco di Formello, Gian Filippo Santi, \u00e8 stato eletto nel Consiglio direttivo dell&#8217;Anci (Associazione Nazionale Comuni Italiani) del Lazio. L&#8217;elezione \u00e8 avvenuta all&#8217;unanimit\u00e0 nell&#8217;assemblea del 6 novembre. Insieme a [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-11-07T09:50:28+00:00","article_modified_time":"2019-11-07T15:04:31+00:00","og_image":[{"width":240,"height":320,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/11\/output_immagine.php_-4.jpg","type":"image\/jpeg"}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"SANTI ELETTO NEL DIRETTIVO DELL&#8217;ANCI","datePublished":"2019-11-07T09:50:28+00:00","dateModified":"2019-11-07T15:04:31+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/"},"wordCount":169,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/11\/output_immagine.php_-4.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/","url":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/","name":"SANTI ELETTO NEL DIRETTIVO DELL'ANCI - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/11\/output_immagine.php_-4.jpg","datePublished":"2019-11-07T09:50:28+00:00","dateModified":"2019-11-07T15:04:31+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/11\/output_immagine.php_-4.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/11\/output_immagine.php_-4.jpg","width":240,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/11\/07\/santi-eletto-nel-direttivo-dellanci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"SANTI ELETTO NEL DIRETTIVO DELL&#8217;ANCI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1267"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1267\/revisions"}],"predecessor-version":[{"id":1269,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1267\/revisions\/1269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/1268"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}