{"id":1359,"date":"2019-12-16T10:54:19","date_gmt":"2019-12-16T09:54:19","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1359"},"modified":"2019-12-16T10:54:19","modified_gmt":"2019-12-16T09:54:19","slug":"consiglio-comunale-convocato-per-giovedi-19-dicembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/","title":{"rendered":"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI&#8217; 19 DICEMBRE"},"content":{"rendered":"<p>La presidente del Consiglio comunale <strong>Roberta Mazzoneschi<\/strong> convoca in seduta ordinaria il Consiglio comunale per <strong>gioved\u00ec 19\u00a0dicembre<\/strong> alle ore 9 nella Sala Grande di Palazzo Chigi.\u00a0 Di seguito l&#8217;ordine del giorno.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-16841\" src=\"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2019\/12\/IMG-20191216-WA0001-724x1024.jpg\" alt=\"\" width=\"640\" height=\"905\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidente del Consiglio comunale Roberta Mazzoneschi convoca in seduta ordinaria il Consiglio comunale per gioved\u00ec 19\u00a0dicembre alle ore 9 nella Sala Grande di Palazzo Chigi.\u00a0 Di seguito l&#8217;ordine del [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":4,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI&#039; 19 DICEMBRE - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI&#039; 19 DICEMBRE - Formello\" \/>\n<meta property=\"og:description\" content=\"La presidente del Consiglio comunale Roberta Mazzoneschi convoca in seduta ordinaria il Consiglio comunale per gioved\u00ec 19\u00a0dicembre alle ore 9 nella Sala Grande di Palazzo Chigi.\u00a0 Di seguito l&#8217;ordine del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-16T09:54:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/formello.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI&#8217; 19 DICEMBRE\",\"datePublished\":\"2019-12-16T09:54:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/\"},\"wordCount\":36,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/formello.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/\",\"name\":\"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI' 19 DICEMBRE - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/formello.jpg\",\"datePublished\":\"2019-12-16T09:54:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/formello.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/formello.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/12\\\/16\\\/consiglio-comunale-convocato-per-giovedi-19-dicembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI&#8217; 19 DICEMBRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI' 19 DICEMBRE - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/","og_locale":"it_IT","og_type":"article","og_title":"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI' 19 DICEMBRE - Formello","og_description":"La presidente del Consiglio comunale Roberta Mazzoneschi convoca in seduta ordinaria il Consiglio comunale per gioved\u00ec 19\u00a0dicembre alle ore 9 nella Sala Grande di Palazzo Chigi.\u00a0 Di seguito l&#8217;ordine del [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-12-16T09:54:19+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/formello.jpg","type":"image\/jpeg"}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI&#8217; 19 DICEMBRE","datePublished":"2019-12-16T09:54:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/"},"wordCount":36,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/formello.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/","url":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/","name":"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI' 19 DICEMBRE - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/formello.jpg","datePublished":"2019-12-16T09:54:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/formello.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/formello.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/12\/16\/consiglio-comunale-convocato-per-giovedi-19-dicembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"CONSIGLIO COMUNALE CONVOCATO PER GIOVEDI&#8217; 19 DICEMBRE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1359"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1359\/revisions"}],"predecessor-version":[{"id":1360,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1359\/revisions\/1360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/4"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}