{"id":1547,"date":"2020-03-12T16:19:55","date_gmt":"2020-03-12T15:19:55","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1547"},"modified":"2020-03-12T16:19:55","modified_gmt":"2020-03-12T15:19:55","slug":"coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/","title":{"rendered":"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA&#8217;"},"content":{"rendered":"<p>Il sindaco <strong>Gian Filippo Santi<\/strong> e il consigliere incaricato alle Politiche sociali <strong>Domenico Cagnucci,<\/strong> nell&#8217;ambito delle misure di contenimento del Coronavirus, comunicano l&#8217;attivazione di un servizio per la spesa a domicilio per anziani e persone in difficolt\u00e0, in collaborazione con la cooperativa Alicenova del consorzio Parsifal. Il servizio parte <strong>venerd\u00ec 13 marzo 2020<\/strong> e viene svolto dal<strong> luned\u00ec al venerd\u00ec<\/strong>, chiamando il numero di telefono <strong>06 90140021<\/strong>. La consegna avviene in giornata da parte degli operatori della cooperativa Alicenova. L&#8217;interazione tra il beneficiario del servizio e l&#8217;operatore deve limitarsi al tempo necessario per la consegna; l&#8217;operatore non pu\u00f2 entrare nell&#8217;abitazione. Il costo della spesa \u00e8 a carico del beneficiario. Il servizio \u00e8 <strong>gratuito<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-17250\" src=\"https:\/\/www.comune.formello.rm.it\/wp-content\/uploads\/2020\/03\/spesa-724x1024.jpg\" alt=\"\" width=\"640\" height=\"905\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco Gian Filippo Santi e il consigliere incaricato alle Politiche sociali Domenico Cagnucci, nell&#8217;ambito delle misure di contenimento del Coronavirus, comunicano l&#8217;attivazione di un servizio per la spesa a [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":1530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA&#039; - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA&#039; - Formello\" \/>\n<meta property=\"og:description\" content=\"Il sindaco Gian Filippo Santi e il consigliere incaricato alle Politiche sociali Domenico Cagnucci, nell&#8217;ambito delle misure di contenimento del Coronavirus, comunicano l&#8217;attivazione di un servizio per la spesa a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-12T15:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/03\/IMG-20200311-WA0007-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"706\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA&#8217;\",\"datePublished\":\"2020-03-12T15:19:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/\"},\"wordCount\":117,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/03\\\/IMG-20200311-WA0007-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/\",\"name\":\"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA' - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/03\\\/IMG-20200311-WA0007-1.jpg\",\"datePublished\":\"2020-03-12T15:19:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/03\\\/IMG-20200311-WA0007-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/03\\\/IMG-20200311-WA0007-1.jpg\",\"width\":706,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/03\\\/12\\\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA' - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/","og_locale":"it_IT","og_type":"article","og_title":"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA' - Formello","og_description":"Il sindaco Gian Filippo Santi e il consigliere incaricato alle Politiche sociali Domenico Cagnucci, nell&#8217;ambito delle misure di contenimento del Coronavirus, comunicano l&#8217;attivazione di un servizio per la spesa a [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-12T15:19:55+00:00","og_image":[{"width":706,"height":960,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/03\/IMG-20200311-WA0007-1.jpg","type":"image\/jpeg"}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA&#8217;","datePublished":"2020-03-12T15:19:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/"},"wordCount":117,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/03\/IMG-20200311-WA0007-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/","url":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/","name":"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA' - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/03\/IMG-20200311-WA0007-1.jpg","datePublished":"2020-03-12T15:19:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/03\/IMG-20200311-WA0007-1.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/03\/IMG-20200311-WA0007-1.jpg","width":706,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/03\/12\/coronavirus-spesa-a-domicilio-per-anziani-e-persone-in-difficolta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"CORONAVIRUS: SPESA A DOMICILIO PER ANZIANI E PERSONE IN DIFFICOLTA&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1547"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1547\/revisions"}],"predecessor-version":[{"id":1548,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1547\/revisions\/1548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/1530"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}